{"id":8487,"date":"2006-04-03T14:44:19","date_gmt":"2006-04-03T14:44:19","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/04\/03\/a-conversa-com-teresa-salgueiro\/"},"modified":"2006-04-03T14:44:19","modified_gmt":"2006-04-03T14:44:19","slug":"a-conversa-com-teresa-salgueiro","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/a-conversa-com-teresa-salgueiro\/","title":{"rendered":"\u00c0 conversa com&#8230; Teresa Salgueiro"},"content":{"rendered":"<p>O amor, quando \u00e9 amor, \u00e9 infinito <!--more--> Perfil  Maria Teresa Salgueiro nasceu na Amadora, a 8 de Janeiro de 1969. Aos 17 anos era a vocalista do grupo \u201cAmenti\u201d. \u00abTeresa molda os versos que canta com a sua voz delicada e pura, plena de emo\u00e7\u00e3o. As palavras tornam-se leves apesar de carregadas de sentimento, ondulam no ar libertas pelo seu cantar suave e apaziguador. A voz sublime flui com naturalidade da sua figura pequena e fr\u00e1gil de mulher, dela emana um encanto natural que n\u00e3o passa despercebido, irradia uma paz que poucos conseguem transmitir, somente os seres iluminados que indicam caminhos. A uma figura como a de Teresa s\u00f3 poderia corresponder uma voz cristalina e l\u00edmpida, pacificadora.\u00bb (do site www.madredeus-osonho.net). Teresa Salgueiro torna-se o \u00edcone, a personagem principal dos MADREDEUS, sendo a primeira e \u00fanica vocalista deste grupo.    VP \u2013 Faz no pr\u00f3ximo ano duas d\u00e9cadas de projecto inicial dos Madredeus. Surgiu com Pedro Ayres Magalh\u00e3es e Rodrigo Le\u00e3o, baixistas dos Her\u00f3is do Mar e dos S\u00e9tima Legi\u00e3o, respectivamente. Poderemos dizer que destas duas bandas foram, de certa forma, deixando de existir lentamente para dar lugar aos Madredeus? Teresa Salgueiro (TS) \u2013 N\u00e3o diria exactamente isso, de maneira nenhuma. Acho que eram projectos que tinham os seus objectivos e que foram cumpridos e, ali\u00e1s, os S\u00e9tima Legi\u00e3o ainda hoje existem. Agora, tamb\u00e9m sem d\u00favida que a dedica\u00e7\u00e3o dos m\u00fasicos a esta ideia dos Madredeus, que foi bem recebida pela cr\u00edtica, pelo p\u00fablico nacional e de outros pa\u00edses, permitiu-nos fazer esta longa viagem que dura at\u00e9 hoje, por muitas culturas diferentes. A dedica\u00e7\u00e3o tem sido grande. Em rela\u00e7\u00e3o \u00e0 presen\u00e7a deles nos outros grupos com certeza que limitou-os na disponibilidade. Mas n\u00e3o deixaram de ser o que eram para passarem a ser Madredeus.  VP \u2013 Os elementos fundadores dos Madredeus, j\u00e1 com Gabriel Gomes, encontram a jovem Teresa, em 1986, a cantar fado num velho bar do Bairro Alto. Descobrem assim a voz que lhes faltava, a voz que o grupo viu projectada e que Portugal ganhou. Como foi esse momento de ent\u00e3o? TS \u2013 Cantava fado \u00e0 capela, mas nunca cantei em casas de fado nem com guitarras. Cantava com os meus amigos. Foi numa dessas noites em que sa\u00ed, que fui cantar ao Bairro Alto e onde estavam esses m\u00fasicos de que falou. Nessa altura uma amiga minha com quem andava sempre pediu-me para cantar e eu cantei. Depois vieram ter comigo e convidaram-me para uma audi\u00e7\u00e3o, como j\u00e1 tinham feito com outras pessoas 2 anos antes, pois esse projecto j\u00e1 vem desde 1984. J\u00e1 havia algumas can\u00e7\u00f5es compostas que serviam de teste nas audi\u00e7\u00f5es, como \u201cCantiga do Campo\u201d, \u201cDeus\u201d e \u201cA Sombra\u201d, que foram depois gravadas no disco \u201cDias da Madredeus\u201d. Fiz ent\u00e3o a audi\u00e7\u00e3o e ficaram contentes com a minha voz. Convidaram-me portanto a ficar com eles e assim foi. Foi um momento especial para mim, porque nunca tinha tido nenhuma experi\u00eancia do g\u00e9nero.  VP \u2013 N\u00e3o resisto a perguntar se ainda continua, a t\u00edtulo pessoal e n\u00e3o oficial, a cantar fado\u2026 N\u00e3o sente saudade nem vontade de o voltar a fazer? TS \u2013 Eu nunca o cantei duma maneira muito s\u00e9ria, mas espont\u00e2nea. Tive depois uma altura em que surgiu o mestre Ant\u00f3nio Cha\u00ednho, gravei com ele 2 temas para um disco e participei em alguns dos seus concertos. Depois n\u00e3o voltou a acontecer. Tenho uma grande paix\u00e3o e admira\u00e7\u00e3o pelo fado, pois acho que \u00e9 uma m\u00fasica extraordin\u00e1ria, da minha cidade, pois tenho um grande amor por Lisboa. Ela tem uma m\u00fasica pr\u00f3pria, que lhe \u00e9 dedicada. Admiro muito os fadistas. \u00c9 uma escola muito interessante, que \u00e9 preciso viv\u00ea-la. Viver aquele mundo, aquele ambiente. Nunca mais cantei. Nunca perco de vista essa tradi\u00e7\u00e3o. Continuo sim a ouvir e a aprender com os grandes fadistas. N\u00e3o tenho, neste momento, ideia de o cantar em p\u00fablico.  VP \u2013 Teve alguma forma\u00e7\u00e3o musical espec\u00edfica para possuir uma bela voz? Qual \u00e9 a educa\u00e7\u00e3o e o tratamento que lhe d\u00e1 para a manter sempre com esse encanto? TS \u2013 Nunca tive nenhuma forma\u00e7\u00e3o espec\u00edfica a n\u00edvel do canto, apenas tive umas aulas de m\u00fasica no Col\u00e9gio e algumas aulas de piano. Sempre foi muito pouco e sem grande consequ\u00eancia. Na altura nunca tinha pensado que a minha vida viria a ser esta, de cantora. E cantava duma forma muito espont\u00e2nea, cantava aquilo de que gostava e gosto de ouvir, desde m\u00fasica popular, ao Zeca Afonso e at\u00e9 mesmo ao fado.  VP \u2013 E j\u00e1 com os Madredeus n\u00e3o sentiu uma maior exig\u00eancia e necessidade de aperfei\u00e7oar a t\u00e9cnica vocal, por exemplo? TS \u2013 O primeiro disco foi gravado duma forma muito simples, apenas com vontade de registar aqueles momentos t\u00e3o especiais e inspiradores. Entretanto, na altura, atrav\u00e9s do Francisco Ribeiro, que era o violoncelista e que tamb\u00e9m cantava, tive um professor de canto, familiar dele. A partir da\u00ed tanto eu como o Francisco come\u00e7amos a ter aulas de canto, com esse Maestro, que era tamb\u00e9m professor do Coro do Teatro de S. Carlos. Nos primeiros anos n\u00e3o t\u00ednhamos muitos concertos, faz\u00edamos cerca de uns 10 ou 12 por ano. T\u00ednhamos que ter muito cuidado com cada local onde \u00edamos, para apresentar a nossa proposta musical, que era cuidada e diferente. N\u00e3o cantava fado, mas sobre o fado. Era como quando cantava s\u00f3 fado, antes dos Madredeus, que, na altura, falar e cantar o fado era um pouco tabu. Felizmente que hoje em dia j\u00e1 n\u00e3o \u00e9 assim. Vivemos uma cultura portuguesa diferente. Fomos bem recebidos, mas notamos que n\u00e3o havia uma grande tradi\u00e7\u00e3o de ir aos concertos, pois havia o grande movimento do rock portugu\u00eas, onde foi preciso criar toda uma estrutura, a n\u00edvel de espa\u00e7o, de vesti\u00e1rio e de filosofia. A ideia dos Madredeus tamb\u00e9m vem da\u00ed, de criar um grupo o mais vers\u00e1til poss\u00edvel, em que exista o m\u00ednimo de coisas conc\u00eantricas, para que seja poss\u00edvel. Cada concerto que faz\u00edamos era uma festa, porque era uma novidade para o p\u00fablico e esses primeiros anos foram, de facto, vividos em clima de festa, era uma celebra\u00e7\u00e3o. Depois dos concertos, quando voltava a Lisboa, tinha mais aulas, duas ou tr\u00eas vezes por semana. Come\u00e7amos a ter, entretanto, as primeiras tourn\u00e9es. Depois disso mudei, durante um ano, para uma professora Cristina de Castro, que leccionava no Conservat\u00f3rio de Lisboa. Interrompi mais tarde as aulas, com a grande tourn\u00e9e do \u201cEsp\u00edrito da Paz\u201d, pois percebi que come\u00e7ava a ser complicado, tanto pelo tempo, como por aquela t\u00e9cnica vocal que aprendia e que, de certa forma, n\u00e3o podia aplicar e praticar. S\u00f3 voltei a ter aulas h\u00e1 2 anos atr\u00e1s, com a professora Nat\u00e1lia Viana, que entretanto faleceu. Por isso a minha forma\u00e7\u00e3o n\u00e3o \u00e9 muita, ou seja, acaba por ser um pouco espor\u00e1dica e todas as bases que tive e aprendi foram claramente muito importantes. Ainda hoje gostava de voltar a ter um professor, para continuar a trabalhar. Para concluir: no fundo, a minha grande escola de canto s\u00e3o e t\u00eam sido as can\u00e7\u00f5es dos Madredeus. O que acho que \u00e9 importante \u00e9 o grande cuidado que tenho com a voz e que procuro cantar o mais natural poss\u00edvel, o canto n\u00e3o \u00e9 nenhum esfor\u00e7o.  VP \u2013 Vieram recentemente ao Porto para apresentar o vosso \u00faltimo trabalho, intitulado de \u201cUm Amor Infinito\u201d. Em que consiste este 13\u00ba \u00e1lbum dos Madredeus? Qual a mensagem de fundo e o condimento necess\u00e1rio para que seja infinito todo o amor? TS \u2013 Quanto ao \u00e1lbum, no que consiste n\u00e3o h\u00e1 como falar de m\u00fasica, aquilo que \u00e9 ideal \u00e9 ouvi-la. Depois disso \u00e9 que se pode, cada um, tirar ila\u00e7\u00f5es, porque cada pessoa ouve e sente \u00e0 sua maneira. E essa \u00e9 a ideia. O \u00e1lbum baseia-se na nova escrita dum novo concerto dos Madredeus, que se chama precisamente \u201cUm Amor Infinito\u201d. Cont\u00e9m tamb\u00e9m outras m\u00fasicas, inclu\u00eddas noutro disco (gravado ao mesmo tempo) e que s\u00e3o dedicadas a Lisboa. Foram compiladas a um outro disco. Este disco \u00e9 uma forma de agradecimento a todo o p\u00fablico que nos t\u00eam esperado e t\u00eam ido ao nosso encontro. Este \u00e9 o 5\u00ba grande concerto, a n\u00edvel da cria\u00e7\u00e3o do grupo no seu repert\u00f3rio. Isto torna-se o promotor do nosso quotidiano, da nossa pr\u00f3pria vontade de continuar. Vivemos do p\u00fablico um grande amor para com o nosso trabalho e vivemos tamb\u00e9m o amor pelo nosso dia-a-dia, isto \u00e9 uma grandeza enorme. Agrade\u00e7o ao p\u00fablico, porque onde quer que vamos encontramos uma sala sempre cheia. Acho que o amor, quando \u00e9 amor, \u00e9 infinito. As condi\u00e7\u00f5es para que o amor possa acontecer s\u00e3o, a meu ver, o respeito e a aten\u00e7\u00e3o pelo outro, com todas as suas refer\u00eancias e particularidades. Mais importante do que julgar os outros, aquele que est\u00e1 ao nosso lado, \u00e9 olhar para n\u00f3s mesmos e questionarmos de cada passo que damos e termos a vontade de nos aproximarmos do outro. \u00c9 uma quest\u00e3o de considera\u00e7\u00e3o e respeito. \t\t VP \u2013 A Teresa, j\u00e1 por algumas vezes, actuou no Porto e sei que tem por ele um carinho especial\u2026 TS \u2013 O Porto, como se sabe, \u00e9 a cidade onde nos estreamos. O 1\u00ba concerto foi no Teatro Carlos Alberto. Tenho do Porto as melhores recorda\u00e7\u00f5es, de todos os concertos que nele tenho feito. Gosto muito, sinceramente, do cora\u00e7\u00e3o da gente do Porto, \u00e9 um p\u00fablico muito caloroso. \u00c9 sempre com grande alegria quando vou cantar ao Porto, porque h\u00e1 uma comunh\u00e3o muito grande. As pessoas s\u00e3o muito generosas e gostam muito de n\u00f3s, como n\u00f3s deles. E \u00e9 uma cidade bel\u00edssima e cheia de tradi\u00e7\u00f5es. Temos sempre saudades de voltar. H\u00e1-de ser sempre assim!  VP \u2013 Desde cedo iniciaram a vossa carreira art\u00edstica, dado que foram logo solicitados para v\u00e1rios concertos por todo o Pa\u00eds. Presumo que, na altura, n\u00e3o tenha sido f\u00e1cil conciliar tantos espect\u00e1culos com as grava\u00e7\u00f5es e restante agenda. Como gerem o vosso tempo? TS \u2013 N\u00e3o \u00e9 f\u00e1cil. Tamb\u00e9m o calend\u00e1rio do grupo, mesmo em termo de viagens, j\u00e1 foi muito mais intenso do que \u00e9 hoje. Mas n\u00e3o levamos uma vida de \u201cmadre-fada\u201d. \u00c9 uma quest\u00e3o de se ter sempre em vista aquilo que de bom esta vida tem, que acho que \u00e9 uma forma de vida privilegiada, por fazer aquilo que tanto gosto \u2013 cantar \u2013 e por dar grande valor ao que conseguimos fazer at\u00e9 hoje, de levar a m\u00fasica portuguesa longe. O ganho est\u00e1 na satisfa\u00e7\u00e3o e na realiza\u00e7\u00e3o pessoal. No tempo que sobra faz-se o melhor poss\u00edvel: estar com a fam\u00edlia, porque o calend\u00e1rio tamb\u00e9m prev\u00ea isso.  VP \u2013 Li numa confer\u00eancia do Pedro que os Madredeus, no conceito original, se apresentam vocacionados para concertos em teatros, jardins, castelos e outros monumentos, ou at\u00e9 mesmo em pra\u00e7as p\u00fablicas. Mant\u00eam sempre este ideal?  TS \u2013 Mantemos, basta observar. Mesmo no estrangeiro. S\u00e3o quase todas e sempre que poss\u00edvel ao ar livre. Lembro-me de 2 grandes espect\u00e1culos l\u00e1 fora: um numa pra\u00e7a do M\u00e9xico, com 80.000 pessoas \u2013 at\u00e9 hoje o mais numeroso \u2013 e outro num castelo na ex-Jugosl\u00e1via. Em geral, h\u00e1 muito bons teatros para este tipo de espect\u00e1culo. Mesmo em Portugal o grupo era vocacionado a isto, e continua a ser, numa altura em que havia pouco audit\u00f3rios. O lugar para o qual nos convidam a actuar interessa ou n\u00e3o interessa, ou seja, respondemos favoravelmente dependendo das condi\u00e7\u00f5es reunidas.  VP \u2013 Olhando para v\u00f3s mesmos, como sentem fazer a diferen\u00e7a perante os outros grupos portugueses? Ou seja, o que \u00e9 que mais vos distingue na m\u00fasica portuguesa? TS \u2013 Eu n\u00e3o componho e n\u00e3o posso comparar o meu trabalho com o dos outros. Mas acho que o nosso \u00e9 razo\u00e1vel. O nosso trabalho \u00e9 este, tudo o que as pessoas conhecem. A nossa proposta \u00e9 muito bem sucedida porque nos dedicamos absolutamente e com grande assiduidade e seriedade. Quanto ao estilo da m\u00fasica penso que o nosso \u00e9 um estilo muito pr\u00f3prio, original e particular, que facilmente n\u00e3o se encontra. Mas n\u00e3o me cabe a mim dizer se a minha m\u00fasica \u00e9 melhor ou pior do que outras m\u00fasicas. Cada grupo tem o seu estilo pr\u00f3prio.   TR\u00cdMERO TEM\u00c1TICO:  VP \u2013 162 praias portuguesas protegidas com Bandeira Azul&#8230; (in)suficientes? TS \u2013 S\u00e3o sempre insuficientes, apesar de serem muitas e \u00e9 uma maravilha que assim seja. Se j\u00e1 houve mais e agora h\u00e1 menos n\u00e3o \u00e9 bom. O ideal seria que todas as nossas praias tivessem Bandeira Azul. Mas acho que a sufici\u00eancia n\u00e3o \u00e9 aquilo que se procura, procura-se sim o ideal.   VP \u2013 Bush ou Kerry: qual preferia e seria melhor vencer? TS \u2013 Para mim faz-me tanta impress\u00e3o que tenha tanta import\u00e2ncia para o mundo inteiro a presid\u00eancia americana. Tenho pena que seja assim. Espero que se ultrapasse isto, que se relativize o interesse que ela suscita. N\u00e3o se pode passar \u00e0 frente de outras quest\u00f5es muito importantes, como s\u00e3o o desrespeito pelos Direitos Humanos em v\u00e1rios pa\u00edses africanos. Mas francamente n\u00e3o sei quem seria, de facto, o melhor para ganhar. O Sr. Kerry n\u00e3o conhe\u00e7o e quanto ao Sr. Bush n\u00e3o estou, de maneira nenhuma, de acordo com a pol\u00edtica que ele faz.  VP \u2013 Princesa Diana: morte acidental ou morte provocada&#8230; TS \u2013 N\u00e3o sei de nada disso, \u00e9 pura especula\u00e7\u00e3o. O que me faz muita confus\u00e3o \u00e9 que ela continue a vender tantas revistas, isto \u00e9, continua a ser muitas vezes capa de revistas. \u00c9 uma personagem admir\u00e1vel, mas acho que, como fizeram ao longo da vida dela, continuam a abusar da sua figura, mesmo que por boas raz\u00f5es. Torna-se muito pol\u00e9mica e ela tentou virar a aten\u00e7\u00e3o que tinha sobre os media para chamar a aten\u00e7\u00e3o sobre certos problemas. Achei isso extraordin\u00e1rio.    ASPECTOS DE ELEI\u00c7\u00c3O  VP \u2013 Um tema&#8230; TS \u2013 A comunica\u00e7\u00e3o, que acho que \u00e9 a coisa mais dif\u00edcil entre as pessoas. \u00c9 feita de palavras e, por vezes, \u00e9 uma coisa rara conseguirmos dizer exactamente aquilo que queremos e termos a certeza de que aquilo que estamos a dizer \u00e9 aquilo que os outros est\u00e3o a ouvir. \u00c9 muito importante que se procure isto.  VP \u2013 Uma cultura&#8230; TS \u2013 N\u00e3o escolho, porque tenho respeito e admira\u00e7\u00e3o por todas. Conhe\u00e7o tantas que seria injusto escolher uma. Para mim \u00e9 muito dif\u00edcil destacar prefer\u00eancias, porque sou o oposto disso. Mas j\u00e1 que insiste, refiro que uma cultura que me impressiona muito pela sua expressividade, pela sua riqueza, pela sua antiguidade \u00e9 a cultura mexicana. E pela sua for\u00e7a e capacidade de sobreviv\u00eancia. Cativa-me tamb\u00e9m pela sua diferen\u00e7a.  VP \u2013 Uma paisagem&#8230; TS \u2013 A paisagem que me diz mais \u00e9 o mar, o horizonte do mar. Escolho o Atl\u00e2ntico: um mar muito forte e com muita energia, com muitas ondas.  VP \u2013 Um homem ilustre&#8230; TS \u2013 H\u00e1 tantas pessoas de que vale a pena falar. Mas uma que me lembro assim \u00e0 primeira \u00e9 Mahatma Gandhi. Tinha uma capacidade e rectid\u00e3o extraordin\u00e1rias, com a sua cultura da n\u00e3o-viol\u00eancia, que lhe permitiu a liberta\u00e7\u00e3o da \u00cdndia. Foi um feito not\u00e1vel.   Entrevista de ANDR\u00c9 RUBIM RANGEL in Voz Portucalense de 10 de Novembro de 2004 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O amor, quando \u00e9 amor, \u00e9 infinito<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6],"tags":[182,187,189,193,206],"class_list":["post-8487","post","type-post","status-publish","format-standard","hentry","category-entrevistas","tag-diocese-de-viana-do-castelo","tag-diocese-do-porto","tag-direitos-humanos","tag-educacao","tag-familia"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/8487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=8487"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/8487\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=8487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=8487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=8487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}