{"id":8007,"date":"2006-04-03T14:44:19","date_gmt":"2006-04-03T14:44:19","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/04\/03\/canonizacao-dos-pastorinhos-da-passos-decisivos-em-fatima\/"},"modified":"2006-04-03T14:44:19","modified_gmt":"2006-04-03T14:44:19","slug":"canonizacao-dos-pastorinhos-da-passos-decisivos-em-fatima","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/canonizacao-dos-pastorinhos-da-passos-decisivos-em-fatima\/","title":{"rendered":"Canoniza\u00e7\u00e3o dos Pastorinhos d\u00e1 passos decisivos em F\u00e1tima"},"content":{"rendered":"<p>O Bispo de Leiria-F\u00e1tima anunciou que amanh\u00e3, \u00e0s 15h00, vai dar-se in\u00edcio ao processo inquiri\u00e7\u00e3o sobre o milagre em ordem \u00e0 canoniza\u00e7\u00e3o dos beatos Jacinta e Francisco Marto, vincando que tudo ser\u00e1 feito para que ele seja entregue no Vaticano \u201cno pr\u00f3ximo dia 15 de Novembro\u201d. A canoniza\u00e7\u00e3o dos dois Pastorinhos pode estar pr\u00f3xima, tendo em conta a decis\u00e3o do Vaticano que permitiu que o processo de inquiri\u00e7\u00e3o sobre o milagre necess\u00e1rio para a canoniza\u00e7\u00e3o, em vez de ser feito na Su\u00ed\u00e7a, onde aconteceram os factos, decorra na diocese de Leiria-F\u00e1tima, como foi anunciado em primeira m\u00e3o pela Ag\u00eancia ECCLESIA. A alegada cura de uma crian\u00e7a de um ano, que sofria de diabetes de tipo 1, filha de emigrantes portugueses na Su\u00ed\u00e7a, em Maio de 2000, quando o Papa veio a F\u00e1tima beatificar Jacinta e Francisco Marto, \u00e9 o milagre cuja autenticidade estar\u00e1 em averigua\u00e7\u00e3o. Na ocasi\u00e3o, a m\u00e3e segurou o Filipe, nascido a 16 de Maio de 1999, enquanto assistia, pela televis\u00e3o, \u00e0s cerim\u00f3nias de beatifica\u00e7\u00e3o, presididas pelo Papa. Na confer\u00eancia de imprensa, al\u00e9m do prelado, esteve presente o Pe. Lu\u00eds Kondor, vice-postulador da Causa de Canoniza\u00e7\u00e3o de Francisco e Jacinta Marto. A Congrega\u00e7\u00e3o para a Causa dos Santos enviou no passado dia 23 de Setembro ao Pe. Lu\u00eds Kondor, a autoriza\u00e7\u00e3o de transfer\u00eancia do processo para Leiria. A transfer\u00eancia justifica-se porque todos os intervenientes s\u00e3o portugueses e isso dar\u00e1 mais rapidez ao processo. O Bispo da Diocese de Leiria\/F\u00e1tima, D. Serafim Ferreira e Silva, j\u00e1 nomeou os elementos do j\u00fari que v\u00e3o reunir no Santu\u00e1rio de F\u00e1tima para analisar o alegado milagre que poder\u00e1 elevar os beatos Francisco e Jacinta \u00e0 categoria de santos. Neste tribunal eclesi\u00e1stico ser\u00e3o ouvidas as testemunhas e apresentada toda a documenta\u00e7\u00e3o relativa \u00e0 doen\u00e7a e alegada cura por intercess\u00e3o dos Pastorinhos.  O tribunal diocesano, presidido pelo juiz Alfredo Melo, dever\u00e1 concluir esta primeira fase em 15 de Novembro, seguindo a documenta\u00e7\u00e3o para a Santa S\u00e9, onde Jo\u00e3o Paulo II est\u00e1 a par de todos os procedimentos.  Depois, o processo ser\u00e1 remetido para a Congrega\u00e7\u00e3o para a Causa dos Santos, presidida pelo Cardeal portugu\u00eas D. Jos\u00e9 Saraiva Martins, cabendo aos m\u00e9dicos uma segunda avalia\u00e7\u00e3o, aquela que confirmar\u00e1 ou n\u00e3o a exist\u00eancia de um milagre. O Pe. Luis Kondor referiu que \u201cJo\u00e3o Paulo II \u00e9 a pessoa mais importante neste processo\u201d, assegurando que o Papa tem colocado o m\u00e1ximo empenho no mesmo. O Bispo de Leiria-F\u00e1tima afirmou que h\u00e1 neste processo \u201cuma clara preocupa\u00e7\u00e3o pedag\u00f3gica\u201d por parte de Jo\u00e3o Paulo II. Enquanto que a beatifica\u00e7\u00e3o permite o culto na diocese onde as crian\u00e7as viveram, a canoniza\u00e7\u00e3o universaliza as personalidades, podendo prestar-se-lhe o culto em todo o mundo. Nenhuma data foi avan\u00e7ada para a poss\u00edvel cerim\u00f3nia de Canoniza\u00e7\u00e3o, nem se confirmou se o Papa tem a inten\u00e7\u00e3o de se deslocar pessoalmente a F\u00e1tima. <B>Not\u00edcias relacionadas<\/B> <a href=\"http:\/\/www.agencia.ecclesia.pt\/noticia.asp?noticiaid=12004\">\u2022 Processo do milagre dos pastorinhos ser\u00e1 em Portugal<\/a>  <b>O carisma dos Pastorinhos<\/b> Na mesma confer\u00eancia de imprensa foi apresentado o livro \u201cO carisma dos Pastorinhos de F\u00e1tima\u201d, escrito pelo padre Jorge Guarda, Vig\u00e1rio-Geral da diocese de Leiria-F\u00e1tima. Este \u00e9 um trabalho de Mestrado na Universidade Gregoriana em Roma. \u201cProcurei ir \u00e0 raiz do acontecimento de F\u00e1tima, o que pode explicar que tr\u00eas crian\u00e7as tenham sido acreditadas e deram origem ao movimento que \u00e9 hoje F\u00e1tima\u201d, disse o sacerdote em confer\u00eancia de imprensa. \u201cA chave que eu encontrei \u00e9 o conceito de carisma, no sentido teol\u00f3gico de dom especial de Deus que torna uma pessoa apto para determinada miss\u00e3o na Igreja\u201d, explicou. Este encontro com os jornalistas realizou-se no primeiro dia da peregrina\u00e7\u00e3o internacional de Outubro ao Santu\u00e1rio de F\u00e1tima, presidida pelo Arcebispo de Bombaim (\u00cdndia), D. Ivan Dias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Bispo de Leiria-F\u00e1tima anunciou que amanh\u00e3, \u00e0s 15h00, vai dar-se in\u00edcio ao processo inquiri\u00e7\u00e3o sobre o milagre em ordem \u00e0 canoniza\u00e7\u00e3o dos beatos Jacinta e Francisco Marto, vincando que tudo ser\u00e1 feito para que ele seja entregue no Vaticano \u201cno pr\u00f3ximo dia 15 de Novembro\u201d. A canoniza\u00e7\u00e3o dos dois Pastorinhos pode estar pr\u00f3xima, tendo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[154,168,177,207,237,284,297],"class_list":["post-8007","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-crianca","tag-diocese-da-guarda","tag-diocese-de-leiria-fatima","tag-fatima","tag-joao-paulo-ii","tag-pastorinhos-de-fatima","tag-santa-se"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/8007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=8007"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/8007\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=8007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=8007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=8007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}