{"id":7256,"date":"2006-04-03T14:44:19","date_gmt":"2006-04-03T14:44:19","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/04\/03\/vaticano-confirma-disponibilidade-para-mediar-conflito-no-iraque\/"},"modified":"2006-04-03T14:44:19","modified_gmt":"2006-04-03T14:44:19","slug":"vaticano-confirma-disponibilidade-para-mediar-conflito-no-iraque","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/vaticano-confirma-disponibilidade-para-mediar-conflito-no-iraque\/","title":{"rendered":"Vaticano confirma disponibilidade para mediar conflito no Iraque"},"content":{"rendered":"<p>O Vaticano confirmou ao in\u00edcio da tarde a sua disponibilidade para uma media\u00e7\u00e3o no Iraque, com a condi\u00e7\u00e3o de que as parte implicadas a desejem verdadeiramente. \u201cA Santa S\u00e9, obviamente, est\u00e1 sempre dispon\u00edvel para ajudar as partes a falar e dialogar, com a condi\u00e7\u00e3o de que exista verdadeiramente a vontade de caminhar para vias pac\u00edficas de solu\u00e7\u00e3o dos conflitos\u201d, referiu o Pe. Ciro Benedettini, director adjunto da Sala de Imprensa da Santa S\u00e9. Este respons\u00e1vel adiantou ainda que o N\u00fancio Apost\u00f3lico em Bagdad \u201csegue directamente os desenvolvimentos da situa\u00e7\u00e3o, mesmo as relativas aos acontecimentos em quest\u00e3o (na cidade de Najaf, ndr) e a Secretaria de Estado permanece em estreito contacto seja com o N\u00fancio, seja com o Patriarca caldeu e o Episcopado do pa\u00eds\u201d. O porta-voz adjunto do Vaticano vincou que \u201cmuitas partes interrogaram a Santa S\u00e9 sobre se seria poss\u00edvel a sua interven\u00e7\u00e3o na suspens\u00e3o dos combates em Najaf, cidade santa dos xiitas no Iraque\u201d. O l\u00edder radical xiita Moqtada Sadr convidou hoje o Papa Jo\u00e3o Paulo II a resolver o conflito que op\u00f5e desde o dia 5 de Agosto os seus milicianos \u00e0s for\u00e7as norte-americanas e iraquianas na cidade de Najaf. O Convite surge na sequ\u00eancia de uma declara\u00e7\u00e3o de inten\u00e7\u00f5es do Cardeal Secretario de Estado do Vaticano, D. Angelo Sodano, onde mostrou a disponibilidade do Papa para uma media\u00e7\u00e3o deste conflito. Esta manh\u00e3 o presidente iraquiano interino comprometeu empenhar-se no fim da rebeli\u00e3o xiita e alcan\u00e7ar a paz na cidade santa. Oito membros da delega\u00e7\u00e3o da Confer\u00eancia Nacional viajam de avi\u00e3o para Najaf.  <B>Not\u00edcias relacionadas<\/B> <a href=\"http:\/\/www.agencia.ecclesia.pt\/noticia.asp?noticiaid=11067\">\u2022 Vaticano dispon\u00edvel para mediar situa\u00e7\u00e3o em Najaf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Vaticano confirmou ao in\u00edcio da tarde a sua disponibilidade para uma media\u00e7\u00e3o no Iraque, com a condi\u00e7\u00e3o de que as parte implicadas a desejem verdadeiramente. \u201cA Santa S\u00e9, obviamente, est\u00e1 sempre dispon\u00edvel para ajudar as partes a falar e dialogar, com a condi\u00e7\u00e3o de que exista verdadeiramente a vontade de caminhar para vias pac\u00edficas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[237,297],"class_list":["post-7256","post","type-post","status-publish","format-standard","hentry","category-vaticano","tag-joao-paulo-ii","tag-santa-se"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/7256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=7256"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/7256\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=7256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=7256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=7256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}