{"id":64963,"date":"2014-03-11T18:37:58","date_gmt":"2014-03-11T18:37:58","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2014\/03\/11\/francisco-atencao-mediatica-explica-se-pela-forma-simples-e-proxima-de-comunicar\/"},"modified":"2014-03-11T18:37:58","modified_gmt":"2014-03-11T18:37:58","slug":"francisco-atencao-mediatica-explica-se-pela-forma-simples-e-proxima-de-comunicar","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/francisco-atencao-mediatica-explica-se-pela-forma-simples-e-proxima-de-comunicar\/","title":{"rendered":"Francisco: Aten\u00e7\u00e3o medi\u00e1tica explica-se pela forma simples e pr\u00f3xima de comunicar"},"content":{"rendered":"<p>Henrique Monteiro e Pedro Mexia analisaram relev\u00e2ncia que o Papa adquiriu <!--more--> <\/p>\n<p>Lisboa, 11 mar 2014 (Ecclesia) &ndash; O jornalista Henrique Monteiro e o cr&iacute;tico liter&aacute;rio Pedro Mexia consideram que a aten&ccedil;&atilde;o da imprensa mundial &agrave; volta do Papa se explica pelos seus &ldquo;gestos simples&rdquo;.<\/p>\n<p>&ldquo;O facto da imprensa achar que o Papa Francisco &eacute; cool n&atilde;o mostra nada, apenas revela que atrav&eacute;s dos seus gestos simples agradou a muita gente fora da Igreja&rdquo;, disse Henrique Monteiro durante a confer&ecirc;ncia &lsquo;Francisco: Um Papa do fim do Mundo&rsquo;, promovida pela Ag&ecirc;ncia Ecclesia, R&aacute;dio Renascen&ccedil;a e Universidade Cat&oacute;lica Portuguesa (UCP) para assinalar o primeiro anivers&aacute;rio do pontificado.<\/p>\n<p>&ldquo;Este &uacute;ltimo ano serviu para reorientar o foco da Igreja na quest&atilde;o da justi&ccedil;a social o que &eacute; muito importante nomeadamente neste momento que se vive, em tempos de crise, e isso toca as pessoas que vivem o desemprego, esta mensagem toca muito as pessoas&rdquo;, acrescentou o cronista Pedro Mexia que lembrou o facto de que o &ldquo;mensageiro conta tanto como a mensagem e este ano medi&aacute;tico tem servido para muita gente conhecer e redescobrir algo que a Igreja sempre defendeu mas que n&atilde;o tinha tanta aten&ccedil;&atilde;o.&rdquo;<\/p>\n<p>Para o jornalista e comentador Henrique Monteiro o segredo do Papa Francisco &eacute; &ldquo;a sua linguagem afetiva e pr&oacute;xima, &eacute; um homem que fala a cada um e chega a toda a gente, &eacute; muito intimista, muito pessoal que fala por par&aacute;bolas&rdquo;.<\/p>\n<p>&ldquo;O papa &eacute; aquele tio que toda a gente gostava de ter, que fosse l&aacute; a casa dar uns bons conselhos, que manda umas piadas e conta hist&oacute;rias&rdquo; e isso cria &ldquo;expectativas n&atilde;o s&oacute; na imprensa mas tamb&eacute;m em pessoas simples e at&eacute; nos n&atilde;o crist&atilde;os&rdquo;.<\/p>\n<p>&ldquo;Ele centrou toda a sua atividade de um ano por aquilo que &eacute; o mandamento universal que &eacute; o amor, algo t&atilde;o simples e esse &eacute; o verdadeiro segredo&rdquo;, concluiu Henrique Monteiro.<\/p>\n<p>J&aacute; Pedro Mexia, cronista e cr&iacute;tico liter&aacute;rio disse que &ldquo;o momento-chave e de longe o mais importante deste ano de papado foi o momento em que Francisco foi &agrave; ilha de Lampedusa, em It&aacute;lia&rdquo;.<\/p>\n<p>&nbsp;&ldquo;Tem sido um ano bastante paradoxal porque raramente algum dos meus amigos gostava do Papa, dantes quando ele aparecia na televis&atilde;o mudavam de canal, agora quando Francisco aparece aumentam o volume do som e isso &eacute; muito estranho&rdquo;, gracejou.<\/p>\n<p>&ldquo;A primeira grande ova&ccedil;&atilde;o que o Papa teve foi quando a seguir ao seu primeiro Angelus disse &lsquo;bom almo&ccedil;o e bom domingo&rsquo;, um tom de proximidade que desarmou as pessoas, &eacute; algo cativante mesmo para quem n&atilde;o tem uma liga&ccedil;&atilde;o crist&atilde;&rdquo;.<\/p>\n<p>&ldquo;O facto de o Papa querer ficar na Casa de Santa Marta e de renovar o seu bilhete de identidade argentino, mostra que n&atilde;o quer ficar ref&eacute;m do Vaticano, do cargo&rdquo;, sublinhou o cronista.<\/p>\n<p>&ldquo;Nunca vi tantas pessoas fora do &acirc;mbito crente a querer ouvir o que o Papa diz e isso &eacute; importante&rdquo; algo que talvez se justifique com o facto de Jorge Bergoglio ser &ldquo;uma pessoa que tem um passado como padre no terreno que &eacute; determinante na sua experi&ecirc;ncia atual, tem gestos importantes como por exemplo quando telefona a uma m&atilde;e que est&aacute; na d&uacute;vida se aborta e recebendo o telefonema do Papa n&atilde;o aborta&rdquo;, concluiu Pedro Mexia.<\/p>\n<p>&ldquo;Como o Vaticano se tornou pr&oacute;ximo&rdquo; foi o segundo tema em debate que foi moderado pela professora da Faculdade de Ci&ecirc;ncias Humanas da UCP, Rita Figueira que referiu dados de um estudo norte-americano em que no &uacute;ltimo ano o nome do Papa &eacute; dos &ldquo;mais referidos ao longo de todo o ano a par de Barack Obama e Nelson Mandela&rdquo;, al&eacute;m de marcar presen&ccedil;a nos media sociais, sendo que no Twitter &ldquo;84 por cento dos coment&aacute;rios sobre o Papa s&atilde;o muito positivos.&rdquo;<\/p>\n<p>As capas da revista Time e Rolling Stones s&atilde;o tamb&eacute;m, na opini&atilde;o da professora universit&aacute;ria &ldquo;indicadores culturais e comerciais incontorn&aacute;vel do valor do Papa nos media atuais&rdquo;.<\/p>\n<p>O programa da iniciativa incluiu ainda an&aacute;lises ao pontificado pela voz de <a href=\"http:\/\/www.agencia.ecclesia.pt\/cgi-bin\/noticia.pl?tpl=&amp;id=99423\" target=\"_blank\">Adriano Moreira<\/a> e por uma <a href=\"http:\/\/www.agencia.ecclesia.pt\/cgi-bin\/noticia.pl?tpl=&amp;id=99424\" target=\"_blank\">mesa redonda<\/a> onde intervieram Alfredo Bruto da Costa, Manuel F&uacute;ria e Margarida Neto.<\/p>\n<p><em>MD<\/em><\/p>\n<p><em><span style=\"font-style: italic;\">[[v,d,,]]<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-style: italic;\">  <object width=\"425\" height=\"350\" data=\"http:\/\/www.youtube.com\/v\/I-VnDKtGr5s<param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/I-VnDKtGr5s\" \/><\/object> <\/span><\/em><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-style: italic;\"> <object width=\"425\" height=\"350\" data=\"http:\/\/www.youtube.com\/v\/Np8IaWgYDt8<param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/Np8IaWgYDt8\" \/><\/object> <\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Henrique Monteiro e Pedro Mexia analisaram relev\u00e2ncia que o Papa adquiriu<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[274,321],"class_list":["post-64963","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-papa-francisco","tag-ucp"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/64963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=64963"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/64963\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=64963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=64963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=64963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}