{"id":56589,"date":"2012-05-16T13:48:43","date_gmt":"2012-05-16T13:48:43","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2012\/05\/16\/guimaraes-rota-religiosa-na-capital-da-cultura\/"},"modified":"2012-05-16T13:48:43","modified_gmt":"2012-05-16T13:48:43","slug":"guimaraes-rota-religiosa-na-capital-da-cultura","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/guimaraes-rota-religiosa-na-capital-da-cultura\/","title":{"rendered":"Guimar\u00e3es: Rota Religiosa na Capital da Cultura"},"content":{"rendered":"<p>\u00abPessoas j\u00e1 perguntam e mostram curiosidade\u00bb, revela diretor t\u00e9cnico da Turel <!--more--> <\/p>\n<p>Guimar&atilde;es, Braga, 16 mai 2012 (Ecclesia) &ndash; O diretor t&eacute;cnico da Cooperativa TUREL &ndash; Turismo Cultural e Religioso, mostrou-se hoje confiante de que os novos roteiros desenvolvidos para as igrejas e santu&aacute;rios de Guimar&atilde;es v&atilde;o chamar mais visitantes &agrave; Capital Europeia da Cultura 2012.<\/p>\n<p>&ldquo;O objetivo principal &eacute; contribuir para o aumento do n&uacute;mero de turistas, dar &agrave;s pessoas mais um motivo para visitarem Guimar&atilde;es, e de certeza que estes recursos v&atilde;o funcionar como um atrativo extra&rdquo;, sustentou Varico Pereira, coordenador dos projetos, em declara&ccedil;&otilde;es &agrave; Ag&ecirc;ncia ECCLESIA.<\/p>\n<p>As novas ferramentas de divulga&ccedil;&atilde;o dos monumentos, que v&atilde;o estar &agrave; disposi&ccedil;&atilde;o do p&uacute;blico de forma totalmente gratuita, nasceram de uma parceria alargada envolvendo os promotores da iniciativa <a href=\"http:\/\/www.guimaraes2012.pt\/\" target=\"_blank\">Guimar&atilde;es 2012 &ndash; Capital Europeia da Cultura<\/a>, a Turel e a Arquidiocese de Braga.<\/p>\n<p>&ldquo;A Arquidiocese de Braga est&aacute; a realizar um trabalho muito detalhado de inventaria&ccedil;&atilde;o e, no caso de Guimar&atilde;es, o processo permitiu identificar os recursos mais relevantes e apresent&aacute;-los em forma de roteiro&rdquo;, explicou Varico Pereira.<\/p>\n<p>Na g&eacute;nese de todo o processo est&aacute; o programa &lsquo;Religioso em Guimar&atilde;es: Mem&oacute;ria e Identidade&rsquo;, que visa a afirma&ccedil;&atilde;o da regi&atilde;o como destino tur&iacute;stico cultural e religioso.<\/p>\n<p>A ideia &eacute; envolver n&atilde;o s&oacute; os turistas e peregrinos mas tamb&eacute;m &ldquo;a popula&ccedil;&atilde;o local&rdquo;, para que esta funcione tamb&eacute;m como um polo de dinamiza&ccedil;&atilde;o do patrim&oacute;nio.<\/p>\n<p>No que diz respeito ao roteiro religioso do centro urbano vimaranense, que d&aacute; a conhecer as nove igrejas mais representativas da cidade, as expectativas da Turel j&aacute; come&ccedil;aram a ser comprovadas no terreno.<\/p>\n<p>&ldquo;A obra foi apresentada apenas h&aacute; um dia [ter&ccedil;a-feira] mas, em conversa com operadores tur&iacute;sticos de Guimar&atilde;es, deu para perceber que as pessoas j&aacute; perguntam e mostram curiosidade&rdquo;, adianta o diretor t&eacute;cnico da cooperativa.<\/p>\n<p>Escrito em portugu&ecirc;s e ingl&ecirc;s &ndash; futuramente poder&aacute; tamb&eacute;m estar traduzido em espanhol &ndash; o roteiro est&aacute; &agrave; disposi&ccedil;&atilde;o das pessoas em cada um das igrejas envolvidas: S&atilde;o Pedro, S&atilde;o Francisco, Nossa Senhora da Consola&ccedil;&atilde;o e Santos Passos, Nossa Senhora da Oliveira, Nossa Senhora do Carmo, Santo Ant&oacute;nio dos Capuchos, Miseric&oacute;rdia, S. Domingos e S&atilde;o Sebasti&atilde;o.<\/p>\n<p>A publica&ccedil;&atilde;o est&aacute; ainda a ser distribu&iacute;da pelos postos de turismo, museus e hot&eacute;is da cidade e pode ser encontrada tamb&eacute;m em alguns restaurantes locais.<\/p>\n<p>Nalguns casos, como na igreja de Nossa Senhora do Carmo, a experi&ecirc;ncia dos visitantes pode ser enriquecida com recurso a um guia permanente, que acolhe e acompanha as pessoas.<\/p>\n<p>O pr&oacute;ximo passo ser&aacute; o lan&ccedil;amento, em julho, de um roteiro religioso dedicado aos cinco santu&aacute;rios do concelho: Santu&aacute;rio de S. Torcato, Santa Marinha, Nossa Senhora da Penha, Nossa Senhora da Lapinha e S&atilde;o Bento das Peras.<\/p>\n<p>Uma vez que esta proposta implica uma desloca&ccedil;&atilde;o mais extensa &#8211; completar o itiner&aacute;rio implica percorrer cerca de 50 quil&oacute;metros &#8211; a Turel est&aacute; a preparar &ldquo;um programa que permita aos turistas ter transporte e alimenta&ccedil;&atilde;o inclu&iacute;da&rdquo;.<\/p>\n<p>Varico Pereira concluiu a apresenta&ccedil;&atilde;o dos projetos destacando o baixo grau de investimento realizado.<\/p>\n<p>&ldquo;Felizmente todos os monumentos inclu&iacute;dos apresentam &oacute;timas condi&ccedil;&otilde;es de conserva&ccedil;&atilde;o e acessibilidade e n&atilde;o foi necess&aacute;rio efetuar qualquer interven&ccedil;&atilde;o na estrutura para facilitar a visita&rdquo;, salientou.<\/p>\n<p><em>JCP<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abPessoas j\u00e1 perguntam e mostram curiosidade\u00bb, revela diretor t\u00e9cnico da Turel<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[172,320],"class_list":["post-56589","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-diocese-de-braga","tag-turismo"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/56589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=56589"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/56589\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=56589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=56589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=56589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}