{"id":53659,"date":"2011-11-03T12:55:45","date_gmt":"2011-11-03T12:55:45","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2011\/11\/03\/braganca-miranda-crise-vocacional-so-acaba-com-nova-mentalidade-salienta-primeira-carta-pastoral-do-bispo\/"},"modified":"2011-11-03T12:55:45","modified_gmt":"2011-11-03T12:55:45","slug":"braganca-miranda-crise-vocacional-so-acaba-com-nova-mentalidade-salienta-primeira-carta-pastoral-do-bispo","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/braganca-miranda-crise-vocacional-so-acaba-com-nova-mentalidade-salienta-primeira-carta-pastoral-do-bispo\/","title":{"rendered":"Bragan\u00e7a-Miranda: \u00abCrise vocacional\u00bb s\u00f3 acaba com nova mentalidade, salienta primeira Carta Pastoral do bispo"},"content":{"rendered":"<p>D. Jos\u00e9 Cordeiro centra-se no percurso feito nos semin\u00e1rios e aponta forma\u00e7\u00e3o dos padres como prioridade <!--more--> <\/p>\n<p>Bragan&ccedil;a, 03 nov 2011 (Ecclesia) &ndash; A escassez de voca&ccedil;&otilde;es sacerdotais s&oacute; pode ser ultrapassada com a &ldquo;convers&atilde;o&rdquo; dos cat&oacute;licos, sublinha o novo bispo de Bragan&ccedil;a-Miranda na sua primeira <a href=\"noticia.pl?id=88015\">Carta Pastoral<\/a>, intitulada &ldquo;O Semin&aacute;rio como um laborat&oacute;rio de esperan&ccedil;a para o presente do futuro&rdquo;.<\/p>\n<p>&ldquo;Todos n&oacute;s devemos admitir que n&atilde;o respondemos plenamente a esse chamamento [de Deus e da sua Igreja] nas nossas fam&iacute;lias, nos ambientes de trabalho, nas par&oacute;quias, nos movimentos, nas congrega&ccedil;&otilde;es religiosas e institutos seculares, escreve D. Jos&eacute; Cordeiro no documento enviado &agrave; Ag&ecirc;ncia ECCLESIA.<\/p>\n<p>No texto lan&ccedil;ado alguns dias antes da Semana dos Semin&aacute;rios, de 6 a 13 de novembro, o mais jovem bispo portugu&ecirc;s real&ccedil;a que a sa&iacute;da da &ldquo;crise vocacional&rdquo; s&oacute; ocorrer&aacute; &ldquo;se esse processo de mudan&ccedil;a de olhar e de mentalidade for sincero e produzir frutos de novidade de vida&rdquo;.<\/p>\n<p>&ldquo;A qualidade dos futuros presb&iacute;teros depende da seriedade da sua forma&ccedil;&atilde;o&rdquo;, refere o bispo da diocese transmontana, que centra a Carta nas prioridades educativas dos candidatos ao sacerd&oacute;cio.<\/p>\n<p>No cap&iacute;tulo dedicado &agrave; &ldquo;forma&ccedil;&atilde;o humana&rdquo;, o prelado indica as virtudes humanas e capacidades relacionais dos padres, &ldquo;desde o equil&iacute;brio geral da personalidade&rdquo; at&eacute; &agrave; aptid&atilde;o para &ldquo;carregar o peso das responsabilidades pastorais&rdquo;, ter um &ldquo;conhecimento profundo da alma humana&rdquo; e cultivar o &ldquo;sentido da justi&ccedil;a e da lealdade&rdquo;.<\/p>\n<p>Referindo-se &agrave; dimens&atilde;o comunit&aacute;ria, D. Jos&eacute; Cordeiro considera que &eacute; preciso superar &ldquo;entraves graves&rdquo;, como &ldquo;atitudes individualistas e narcisistas&rdquo;, &ldquo;comportamentos de isolamento&rdquo;, &ldquo;busca de promo&ccedil;&atilde;o pessoal&rdquo;, &ldquo;competi&ccedil;&atilde;o&rdquo;, &ldquo;tend&ecirc;ncia pelo luxo, pela mordomia e aburguesamento&rdquo;, &ldquo;&lsquo;intriga eclesi&aacute;stica&rsquo;&rdquo; e &ldquo;submiss&atilde;o por conveni&ecirc;ncia&rdquo;.<\/p>\n<p>A forma&ccedil;&atilde;o espiritual deve incidir na &ldquo;leitura meditada e orante da Palavra de Deus&rdquo; e nos sacramentos, ao mesmo tempo que aprofunda &ldquo;o sentido profundo do humano&rdquo;, o &ldquo;valor religioso do sil&ecirc;ncio&rdquo;, a procura de &ldquo;Cristo nos homens&rdquo; e a oferta do &ldquo;dom generoso e gratuito de si mesmo (celibato)&rdquo;.<\/p>\n<p>&ldquo;Considerando a prioridade da forma&ccedil;&atilde;o presbiteral, em todas as suas dimens&otilde;es, a prepara&ccedil;&atilde;o acad&eacute;mica qualificada dos formadores&rdquo; exige da diocese &#8220;constante aten&ccedil;&atilde;o, sacrif&iacute;cios pastorais e investimento econ&oacute;mico&rdquo;, indica o bispo.<\/p>\n<p>A Carta Pastoral destaca igualmente a necessidade de os sacerdotes estarem permanentemente atualizados, j&aacute; que &ldquo;se a vida do padre n&atilde;o &eacute; forma&ccedil;&atilde;o permanente, toma-se frustra&ccedil;&atilde;o permanente&rdquo;.<\/p>\n<p>O acompanhamento dos novos sacerdotes tamb&eacute;m &eacute; focado: &ldquo;Logo a seguir &agrave; ordena&ccedil;&atilde;o presbiteral o padre &eacute; enviado, sozinho, para um vasto conjunto de experi&ecirc;ncias pastorais&rdquo;, assinala o prelado, que faz votos para &ldquo;a solid&atilde;o, que pode ser experimentada em qualquer idade, nunca seja produzida pelo desleixo da comunh&atilde;o sacerdotal&rdquo;.<\/p>\n<p>O antigo reitor do Pontif&iacute;cio Col&eacute;gio Portugu&ecirc;s em Roma real&ccedil;a que &ldquo;as testemunhas mais eficazes da voca&ccedil;&atilde;o ao presbiterado s&atilde;o os pr&oacute;prios presb&iacute;teros e os seminaristas.<\/p>\n<p>D. Jos&eacute; Cordeiro disp&otilde;e de 100 padres, &ldquo;dos quais 66 dedicados e sacrificados p&aacute;rocos&rdquo; respons&aacute;veis pelas 326 par&oacute;quias da <a href=\"http:\/\/www.bragancanet.pt\/diocese\/\" target=\"_blank\">diocese<\/a>, enquanto que a n&iacute;vel de candidatos ao sacerd&oacute;cio h&aacute; dois jovens com licenciatura em Teologia, quatro seminaristas maiores e 11 menores (do 7.&ordm; ao 12.&ordm; ano).<\/p>\n<p><em>RJM<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D. Jos\u00e9 Cordeiro centra-se no percurso feito nos semin\u00e1rios e aponta forma\u00e7\u00e3o dos padres como prioridade<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[173,294],"class_list":["post-53659","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-diocese-de-braganca-miranda","tag-sacramentos"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/53659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=53659"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/53659\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=53659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=53659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=53659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}