{"id":45760,"date":"2010-06-08T15:45:18","date_gmt":"2010-06-08T15:45:18","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2010\/06\/08\/para-la-do-ano-sacerdotal-do-misterio-ao-ministerio\/"},"modified":"2010-06-08T15:45:18","modified_gmt":"2010-06-08T15:45:18","slug":"para-la-do-ano-sacerdotal-do-misterio-ao-ministerio","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/para-la-do-ano-sacerdotal-do-misterio-ao-ministerio\/","title":{"rendered":"Para l\u00e1 do Ano Sacerdotal \u2013 do Mist\u00e9rio ao minist\u00e9rio"},"content":{"rendered":"<p>Pe. Jos\u00e9 Manuel Cordeiro <!--more--> <\/p>\n<p>Com enorme surpresa, antes da viagem apost&oacute;lica a &Aacute;frica (Camar&otilde;es e Angola) em Mar&ccedil;o de 2009, o Papa Bento XVI anunciou a convoca&ccedil;&atilde;o de um especial Ano sacerdotal, a prop&oacute;sito do 150.&ordm; anivers&aacute;rio da morte de S. Jo&atilde;o Maria Vianney, o P&aacute;roco de Ars, anunciando, ao mesmo tempo, que o proclamaria padroeiro de todos os sacerdotes do mundo.<\/p>\n<p>Efectivamente, este Ano abriu com uma celebra&ccedil;&atilde;o de V&eacute;speras na Bas&iacute;lica Vaticana, no dia 19 de Junho 2009, solenidade do Sagrado Cora&ccedil;&atilde;o de Jesus, e concluiu com um congresso mundial de sacerdotes em Roma, de 9 a 11 de Junho de 2010. Foi um Ano marcado por v&aacute;rios problemas e pol&eacute;micas em torno de alguns sacerdotes, mas sobretudo por muitas iniciativas, celebra&ccedil;&otilde;es e publica&ccedil;&otilde;es que contribu&iacute;ram para renovar o dom recebido pela imposi&ccedil;&atilde;o das m&atilde;os.<\/p>\n<p><em>Fidelidade de Cristo, Fidelidade do Sacerdote<\/em> &ndash; foi o tema escolhido pelo Santo Padre que nos impele a um amor maior que vence o tempo. Costumava dizer o Santo P&aacute;roco d&rsquo;Ars que &laquo;<em>o sacerd&oacute;cio &eacute; o amor do cora&ccedil;&atilde;o de Jesus&raquo;.<\/em> Ao falar do Cora&ccedil;&atilde;o de Jesus, queremos tamb&eacute;m dizer o amor humano de uma pessoa divina, porque Cristo &laquo;amou com um cora&ccedil;&atilde;o humano&raquo; (1) e o cora&ccedil;&atilde;o de Deus bate de amor por todas as pessoas. O primeiro fiel a tanto amor &eacute; o pr&oacute;prio Cristo e nesta fidelidade fundadora &eacute; que se radica a f&eacute; e a vida de cada sacerdote.<\/p>\n<p>O Papa recordou-o claramente na celebra&ccedil;&atilde;o de V&eacute;speras com os sacerdotes, Religiosos, Seminaristas e Di&aacute;conos em F&aacute;tima: &laquo;<em>permiti abrir-vos o cora&ccedil;&atilde;o para vos dizer que a principal preocupa&ccedil;&atilde;o de todo o crist&atilde;o, nomeadamente da pessoa consagrada e do ministro do Altar, h&aacute;-de ser a fidelidade, a lealdade &agrave; pr&oacute;pria voca&ccedil;&atilde;o, como disc&iacute;pulo que quer seguir o Senhor. A fidelidade no tempo &eacute; o nome do amor; de um amor coerente, verdadeiro e profundo a Cristo Sacerdote. (&#8230;) Isto sup&otilde;e, evidentemente, uma verdadeira intimidade com Cristo na ora&ccedil;&atilde;o, pois ser&aacute; a experi&ecirc;ncia forte e intensa do amor do Senhor que h&aacute;-de levar os sacerdotes e os consagrados a corresponderem ao seu amor de modo exclusivo e esponsal&raquo; (2)<\/em>.<\/p>\n<p>O Ano sacerdotal foi, com efeito, para toda a Igreja e n&atilde;o apenas para os seus Padres. Todavia a Igreja n&atilde;o existe sem a Eucaristia, dado que &eacute; a Eucaristia que faz a Igreja e o mundo sem a Eucaristia n&atilde;o recebe as energias da transfigura&ccedil;&atilde;o e de salva&ccedil;&atilde;o que emanam deste mist&eacute;rio. A Igreja une-se ao seu Senhor que a habita e a edifica, n&atilde;o s&oacute; durante a celebra&ccedil;&atilde;o lit&uacute;rgica, mas em todo o instante, conservando-O como o &ldquo;tesouro&rdquo; mais precioso. Deste modo, a Eucaristia apresenta-se como a fonte, o centro e o cume de toda a vida crist&atilde; e de toda a evangeliza&ccedil;&atilde;o, porque o seu fim &eacute; a comunh&atilde;o dos homens com Cristo e, n&rsquo;Ele, com o Pai e com o Esp&iacute;rito Santo (3).<\/p>\n<p>Considerando que a Eucaristia faz a Igreja e a Igreja faz a Eucaristia, podemos afirmar que existe entre elas uma &iacute;ntima rela&ccedil;&atilde;o. Portanto, n&atilde;o h&aacute; Igreja &iacute;ntegra sem a sucess&atilde;o apost&oacute;lica e n&atilde;o h&aacute; verdadeira Eucaristia sem o minist&eacute;rio dos sacerdotes, segundo uma hermen&ecirc;utica da continuidade eclesial e sacerdotal.<\/p>\n<p>Na verdade, afirma Bento XVI: &laquo;<em>revela-se cada vez mais urgente a hermen&ecirc;utica da continuidade para compreender de modo adequado os textos do Conc&iacute;lio Ecum&eacute;nico Vaticano II, analogamente &eacute; necess&aacute;ria uma hermen&ecirc;utica que poderemos definir &ldquo;da continuidade sacerdotal&rdquo;, a qual, partindo de Jesus de Nazar&eacute;, Senhor e Cristo, e passando pelos dois mil anos de hist&oacute;ria de grandeza e de santidade, de cultura e de piedade, que o Sacerd&oacute;cio escreveu no mundo, atinja at&eacute; aos nossos dias<\/em>&raquo; (4).<\/p>\n<p>Para mostrar os mist&eacute;rios de Cristo e viver sempre do mist&eacute;rio ao mi(ni)st&eacute;rio &ndash; h&aacute; que &laquo;<em>encontrar paci&ecirc;ncia bastante para aguentar &ndash; <\/em>aconselhava Rainer Rilke<em> &ndash; e inoc&ecirc;ncia bastante para acreditar, mais confian&ccedil;a no que &eacute; dif&iacute;cil e no estado de solid&atilde;o entre os outros. E no mais, deixe acontecer a vida. Acredite-me a vida tem raz&atilde;o em todos os casos<\/em>&raquo; (5).<\/p>\n<p>Tamb&eacute;m um psiquiatra italiano n&atilde;o crente escreveu no &acirc;mbito do Ano sacerdotal um interessante livro (6) acerca dos padres. Diz ele que &laquo;<em>parece-me poder dizer que se o Bispo quer que os seus padres sejam santos, eu como psiquiatra gostaria que fossem serenos e ao menos, algumas vezes, felizes<\/em>&raquo;.<\/p>\n<p>Em conclus&atilde;o, o mist&eacute;rio do minist&eacute;rio sacerdotal &eacute; sempre o mesmo e o &uacute;nico mist&eacute;rio de Deus: Cristo, nossa P&aacute;scoa. O desafio &eacute; o de sempre para l&aacute; do Ano sacerdotal, isto &eacute;, partir do Mist&eacute;rio para o minist&eacute;rio que fa&ccedil;a da vida um lugar de beleza e de verdade no sublime quotidiano da liturgia da pr&oacute;pria vida.<\/p>\n<p align=\"right\"><em>Pe. Jos&eacute; Manuel Cordeiro, Reitor do&nbsp; Pontif&iacute;cio Col&eacute;gio Portugu&ecirc;s (Roma)<\/em><\/p>\n<p>NOTAS:<\/p>\n<p>1 &#8211; GS 22.<\/p>\n<p>2- BENTO XVI, Discurso aos sacerdotes, Religiosos, Seminaristas e Di&aacute;conos em F&aacute;tima, 12 de Maio 2010.<\/p>\n<p>3 &#8211; Cf. LG 11; PO 5.<\/p>\n<p>4 &#8211; BENTO XVI, &laquo;Discurso aos participantes do conv&eacute;nio teol&oacute;gico organizado pela Congrega&ccedil;&atilde;o para o Clero, 12.03.2010&raquo;, in <em>OSSERVATORE ROMANO<\/em> (13.03.2010) 8.<\/p>\n<p>5 &#8211; R. M. RILKE, <em>Cartas a um jovem poeta<\/em>, Edi&ccedil;&otilde;es ASA, Porto 2002, 87.<\/p>\n<p>6 &#8211; V. ANDREOLI, <em>Preti. Viaggio fra gli uomini del sacro<\/em>, Piemme, Milano 2009.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pe. Jos\u00e9 Manuel Cordeiro<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[106,114,120,187,246],"class_list":["post-45760","post","type-post","status-publish","format-standard","hentry","category-dossier","tag-angola","tag-ano-sacerdotal","tag-bento-xvi","tag-diocese-do-porto","tag-liturgia"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/45760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=45760"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/45760\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=45760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=45760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=45760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}