{"id":45362,"date":"2010-05-14T06:39:28","date_gmt":"2010-05-14T06:39:28","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2010\/05\/14\/missa-na-avenida-dos-aliados-conclui-visita-de-bento-xvi-a-portugal\/"},"modified":"2010-05-14T06:39:28","modified_gmt":"2010-05-14T06:39:28","slug":"missa-na-avenida-dos-aliados-conclui-visita-de-bento-xvi-a-portugal","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/missa-na-avenida-dos-aliados-conclui-visita-de-bento-xvi-a-portugal\/","title":{"rendered":"Missa na Avenida dos Aliados conclui visita de Bento XVI a Portugal"},"content":{"rendered":"<p>Papa dirige-se ainda aos fi\u00e9is e aos jovens da varanda da C\u00e2mara Municipal do Porto <!--more--> <\/p>\n<p>O quarto e &uacute;ltimo dia da Viagem Apost&oacute;lica de Bento XVI a Portugal &eacute; tamb&eacute;m o mais curto em termos de agenda, envolvendo duas viagens: de F&aacute;tima para Gaia e do Porto para Roma, com a celebra&ccedil;&atilde;o de uma missa na Avenida dos Aliados como ponto mais alto do programa.<\/p>\n<p>No final da eucaristia, o Papa dirige-se &agrave; varanda da C&acirc;mara Municipal do Porto para se dirigir em especial aos jovens, no que vai ser a segunda vez que, nesta visita, lhes dedica uma mensagem especial.<\/p>\n<p>Bento XVI deixa a Casa de Nossa Senhora do Carmo, onde ficou por duas noites, &agrave;s 08h00 para se dirigir de papam&oacute;vel para o Est&aacute;dio Municipal de F&aacute;tima, em cujo parque de estacionamento foi instalado o heliporto.<\/p>\n<p>A&iacute; recebe os cumprimentos de despedida das mesmas autoridades que o receberam na tarde do dia 12: o bispo de Leiria-F&aacute;tima, D. Ant&oacute;nio Marto, a Governadora Civil de Santar&eacute;m, S&oacute;nia Sanfona, o presidente da C&acirc;mara Municipal de Our&eacute;m, Paulo Fonseca, o presidente da Junta de Freguesia de F&aacute;tima, Nat&aacute;lio Reis, e autoridades militares, civis e de seguran&ccedil;a locais.<\/p>\n<p>Mais uma vez, por raz&otilde;es de seguran&ccedil;a, o Merlin que transporta Bento XVI &eacute; o primeiro a levantar voo, sendo o &uacute;ltimo a aterrar no heliporto do Regimento de Artilharia da Serra do Pilar, em Gaia.<\/p>\n<p>No trajecto entre F&aacute;tima e Gaia o helic&oacute;ptero vai sobrevoar as vinhas do Alto-Douro, Patrim&oacute;nio Mundial da UNESCO.<\/p>\n<p>A chegada a Gaia est&aacute; prevista para as 09h30. Ao descer do helic&oacute;ptero o Papa &eacute; acolhido pelo Bispo do Porto, D. Manuel Clemente, pelo presidente da C&acirc;mara Municipal de Gaia, Lu&iacute;s Filipe Menezes, pela Governadora Civil do Porto, Isabel Santos, pelo chefe do Estado Maior do Ex&eacute;rcito, general Jos&eacute; Pinto Ramalho, e pelo Comandante do Regimento, coronel Pedro Calado.<\/p>\n<p>Um grupo de 83 crian&ccedil;as de par&oacute;quias de Gaia acolhe o Papa, cantando o hino de boas-vindas.<\/p>\n<p>Ainda no Regimento da Serra do Pilar, Bento XVI recebe uma prenda da C&acirc;mara de Gaia, entregue por Lu&iacute;s Filipe Menezes: um &#8220;vintage&#8221; de 1926 da Casa Ferreirinha.<\/p>\n<p>Depois da sauda&ccedil;&atilde;o, Bento XVI segue em Papam&oacute;vel para a Avenida dos Aliados, Porto, onde vai presidir &agrave; missa.<\/p>\n<p>Quando atravessar a Ponte do Infante, Bento XVI vai saudar as centenas de embarca&ccedil;&otilde;es engalanadas atracadas no rio Douro e que v&atilde;o tamb&eacute;m saudar o Papa, fazendo soar as suas sirenes.<\/p>\n<p>Ao chegar &agrave; Avenida, o Papam&oacute;vel d&aacute; uma volta completa &agrave; zona, antes de se dirigir para o edif&iacute;cio da C&acirc;mara Municipal do Porto, onde &eacute; recebido pelo presidente da C&acirc;mara, Rui Rio.<\/p>\n<p>O autarca portuense vai entregar ao Papa as chaves da cidade, uma pe&ccedil;a de porcelana com as armas da cidade e uma obra liter&aacute;ria constitu&iacute;da por uma antologia de verso e prosa sobre o Porto, intitulada &#8220;Daqui houve nome Portugal&#8221;, coordenada por Eug&eacute;nio de Andrade.<\/p>\n<p>Depois de se paramentar numa sala da C&acirc;mara Municipal, dirige-se para o altar, para dar in&iacute;cio &agrave; celebra&ccedil;&atilde;o, prevista para as 10h15.<\/p>\n<p>Terminado o c&acirc;ntico de entrada, o Bispo do Porto, D. Manuel Clemente, d&aacute; as boas-vindas ao Papa, recebendo das suas m&atilde;os um c&aacute;lice, como recorda&ccedil;&atilde;o pela visita apost&oacute;lica.<\/p>\n<p>Depois de se paramentar numa sala da C&acirc;mara Municipal, o Papa dirigir-se-&aacute; para o altar, para dar in&iacute;cio &agrave; Missa. &nbsp;<\/p>\n<p>Na b&ecirc;n&ccedil;&atilde;o final, Bento XVI vai aben&ccedil;oar tamb&eacute;m a primeira pedra do novo Semin&aacute;rio Diocesano Mission&aacute;rio Redemptoris Mater que ficar&aacute; instalado no Semin&aacute;rio do Bom Pastor, no Porto. &nbsp;<\/p>\n<p>Ap&oacute;s a Missa, Bento XVI subir&aacute; ao balc&atilde;o da C&acirc;mara Municipal do Porto e dirigir&aacute; uma mensagem aos jovens, tal como fez em Lisboa na Nunciatura Apost&oacute;lica<\/p>\n<p>Em papam&oacute;vel, Bento XVI segue depois para o Aeroporto S&aacute; Carneiro, onde &agrave;s 13h30 decorre a cerim&oacute;nia oficial de despedida, com a presen&ccedil;a do Presidente da Rep&uacute;blica e de v&aacute;rias entidades.<\/p>\n<p>&Eacute; nesta cerim&oacute;nia que o Papa pronuncia o s&eacute;timo e &uacute;ltimo discurso da sua viagem de quatro dias a Portugal.<\/p>\n<p>O&nbsp;Airbus A320 Columbano Bordalo Pinheiro,&nbsp;da TAP, voo&nbsp;9704&nbsp;para Roma que leva o Papa e a sua comitiva&nbsp; levanta voo &agrave;s 14h00, estando a chegada ao Aeroporto Leonardo da Vinci previsto para as 18h00 locais (17h00 em Lisboa).<\/p>\n<p>Tal como em Lisboa e em F&aacute;tima, anteriores etapas desta Viagem Apost&oacute;lica para assinalar o d&eacute;cimo anivers&aacute;rio da beatifica&ccedil;&atilde;o de Francisco e Jacinto Marto, a circula&ccedil;&atilde;o autom&oacute;vel e pedonal e os transportes p&uacute;blicos v&atilde;o sofrer altera&ccedil;&otilde;es.<\/p>\n<p>As informa&ccedil;&otilde;es mais actualizadas podem ser encontradas <strong><a href=\"http:\/\/www.bentoxviportugal.pt\/ficheiros\/file\/Porto_transito.pdf\" target=\"_blank\">aqui<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Papa dirige-se ainda aos fi\u00e9is e aos jovens da varanda da C\u00e2mara Municipal do Porto<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[120,187],"class_list":["post-45362","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-bento-xvi","tag-diocese-do-porto"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/45362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=45362"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/45362\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=45362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=45362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=45362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}