{"id":438234,"date":"2026-08-13T13:05:47","date_gmt":"2026-08-13T12:05:47","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=438234"},"modified":"2026-08-15T06:38:30","modified_gmt":"2026-08-15T05:38:30","slug":"fatima-d-jose-ornelas-exorta-todos-a-abrir-o-coracao-e-estender-a-mao-a-quem-chega-e-parte","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/fatima-d-jose-ornelas-exorta-todos-a-abrir-o-coracao-e-estender-a-mao-a-quem-chega-e-parte\/","title":{"rendered":"F\u00e1tima: D. Jos\u00e9 Ornelas exorta \u00abtodos a abrir o cora\u00e7\u00e3o e estender a m\u00e3o a quem chega e parte\u00bb"},"content":{"rendered":"<p><em>Bispo diocesano deixou uma mensagem final aos peregrinos, na Missa da Peregrina\u00e7\u00e3o do Migrante e Refugiado, na qual recordou Eug\u00e9nio Fonseca e v\u00edtimas do terramoto na Col\u00f4mbia e Venezuela\u00a0<\/em><\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_438258\" aria-describedby=\"caption-attachment-438258\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/D.-Jose-Ornelas-Missa-Fatima.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-438258 size-full\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/D.-Jose-Ornelas-Missa-Fatima.jpg\" alt=\"\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/D.-Jose-Ornelas-Missa-Fatima.jpg 1920w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/D.-Jose-Ornelas-Missa-Fatima-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/D.-Jose-Ornelas-Missa-Fatima-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/D.-Jose-Ornelas-Missa-Fatima-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/D.-Jose-Ornelas-Missa-Fatima-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/D.-Jose-Ornelas-Missa-Fatima-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a><figcaption id=\"caption-attachment-438258\" class=\"wp-caption-text\">Foto: Santu\u00e1rio de F\u00e1tima<\/figcaption><\/figure>\n<p>F\u00e1tima, 13 ago 2026 (Ecclesia) &#8211; O bispo de Leiria-F\u00e1tima, D. Jos\u00e9 Ornelas, exortou hoje a abrir o cora\u00e7\u00e3o e a ajudar os migrantes que chegam a Portugal e os que partem do pa\u00eds, na Missa da Peregrina\u00e7\u00e3o do Migrante e do Refugiado ao Santu\u00e1rio de F\u00e1tima.<\/p>\n<p>\u201cQue Maria, que foi migrante e refugiada no Egito, para salvar o seu Filho, que havia de tornar-se o salvador da humanidade, nos ajude a todos a abrir o cora\u00e7\u00e3o e estender a m\u00e3o a quem chega e parte para construirmos juntos uma humanidade e um mundo mais humano e mais fraterno\u201d, afirmou o respons\u00e1vel cat\u00f3lico, na mensagem final aos peregrinos, no recinto de ora\u00e7\u00e3o do Santu\u00e1rio.<\/p>\n<p>F\u00e1tima acolheu esta quarta e quinta-feira a Peregrina\u00e7\u00e3o do Migrante e do Refugiado, que foi presidida pelo n\u00fancio apost\u00f3lico em Portugal, D. Andr\u00e9s Carrascosa Coso, integrada na Semana Nacional de Migra\u00e7\u00f5es, com o tema \u201cDa fragilidade \u00e0 Esperan\u00e7a\u201d, que decorre at\u00e9 dia 16 de agosto.<\/p>\n<p>Na conclus\u00e3o da celebra\u00e7\u00e3o, D. Jos\u00e9 Ornelas saudou \u201ctodos os peregrinos, especialmente os migrantes\u201d: \u201cAqueles que partiram deste pa\u00eds para todo o mundo e os que, de todo o mundo, est\u00e3o chegando ao nosso pa\u00eds\u201d.<\/p>\n<p>&#8220;Esta \u00e9 \u2018Casa da M\u00e3e para todos, todos, todos\u2019, sem excluir ningu\u00e9m, como dizia o Papa Francisco. Sede bem-vindos a esta nossa casa comum, sob a prote\u00e7\u00e3o e o exemplo da M\u00e3e, para que, peregrinando para nossa casa ou \u00e0 procura dela, colaboremos para fazer desta terra a \u00abcasa comum da humanidade\u00bb, como diz o mesmo Papa, na enc\u00edclica \u2018Laudato si\u2019\u2019\u201d, expressou.<\/p>\n<p>O bispo de Leiria-F\u00e1tima agradeceu, de forma especial e amiga, ao n\u00fancio apost\u00f3lico, \u201cque torna bem presente\u201d, no pa\u00eds, \u201co minist\u00e9rio do Santo Padre Le\u00e3o XIV\u201d, naquele Santu\u00e1rio.<\/p>\n<blockquote><p>Obrigado, caro arcebispo Andr\u00e9s, pelas suas palavras amig\u00e1veis e estimulantes sobre o tema da nossa peregrina\u00e7\u00e3o que, no m\u00eas de agosto, tem sempre presente a grande parte da humanidade que \u00e9 peregrina e migrante na terra\u201d, referiu.<\/p><\/blockquote>\n<p>D. Jos\u00e9 Ornelas manifestou a inten\u00e7\u00e3o de que os peregrinos levem a mensagem do embaixador da Santa S\u00e9, que \u201creflete a grande aten\u00e7\u00e3o da Igreja, e em particular do Papa Le\u00e3o XIV\u201d, que chama a aten\u00e7\u00e3o \u201cpara as pessoas que, impulsionadas pela necessidade, enfrentam enormes desafios, manipula\u00e7\u00e3o, explora\u00e7\u00e3o e morte, em busca de um mundo melhor\u201d.<\/p>\n<figure id=\"attachment_438215\" aria-describedby=\"caption-attachment-438215\" style=\"width: 400px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/Santuario-de-Fatima-12-e-13-agosto-2026.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-438215\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/Santuario-de-Fatima-12-e-13-agosto-2026-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/Santuario-de-Fatima-12-e-13-agosto-2026-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/Santuario-de-Fatima-12-e-13-agosto-2026-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/Santuario-de-Fatima-12-e-13-agosto-2026-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/Santuario-de-Fatima-12-e-13-agosto-2026-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/Santuario-de-Fatima-12-e-13-agosto-2026-1536x1025.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/08\/Santuario-de-Fatima-12-e-13-agosto-2026.jpg 1920w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-438215\" class=\"wp-caption-text\">Foto: Santu\u00e1rio de F\u00e1tima<\/figcaption><\/figure>\n<p>\u201cQue esta peregrina\u00e7\u00e3o nos permita adotar a atitude da M\u00e3e do c\u00e9u que, aqui em F\u00e1tima, veio cuidar dos mais pequenos e insignificantes e os transformou em profetas da paz, da miseric\u00f3rdia e do acolhimento maternal do seu cora\u00e7\u00e3o\u201d, desejou.<\/p>\n<p>O respons\u00e1vel cat\u00f3lico recordou tamb\u00e9m as v\u00edtimas dos terramotos que atingiram a Venezuela e a Col\u00f4mbia, rezando por elas.<\/p>\n<p>Aos mais pequenos, D. Jos\u00e9 Ornelas deixou tamb\u00e9m uma mensagem, saudando-os com \u201calegria e carinho\u201d e referindo que Nossa Senhora de F\u00e1tima fica contente com a sua presen\u00e7a naquele lugar, que \u00e9 a \u201cCasa da M\u00e3e\u201d.<\/p>\n<p>\u201cNesta casa da M\u00e3e, ela convida a todos a sentirem-se na sua casa como irm\u00e3os e irm\u00e3s, seja qual for a sua nacionalidade, a sua l\u00edngua e a sua cultura, a cor da sua pele. Aqui somos todos filhos e filhas de Deus e nesta casa da M\u00e3e, ela pede que nos aceitemos como irm\u00e3os e amigos\u201d, indicou.<\/p>\n<p>O bispo diocesano fez tamb\u00e9m um apelo, o mesmo que Maria fez aos pastorinhos Francisco, Jacinta e L\u00facia: \u201cRezemos pela Paz e trabalhemos pela paz, acolhendo com alegria aqueles que encontramos nas nossas escolas, nas nossas cidades, nas nossas f\u00e9rias, seja qual for o pa\u00eds onde nasceram, a cor da pele ou a cultura que trazem\u201d.<\/p>\n<blockquote><p>Aqui, a M\u00e3e do C\u00e9u pede que nos tratemos todos como irm\u00e3os e amigos, para evitar \u00f3dios, conflitos e guerras e construir juntos a paz e a felicidade para todos. Boas F\u00e9rias!\u201d, desejou.<\/p><\/blockquote>\n<p>A Peregrina\u00e7\u00e3o do Migrante e Refugiado ao Santu\u00e1rio de F\u00e1tima insere-se na 54.\u00aa edi\u00e7\u00e3o da Semana Nacional de Migra\u00e7\u00f5es 2026, que decorre at\u00e9 domingo, com o tema \u2018Da fragilidade \u00e0 Esperan\u00e7a\u2019.<\/p>\n<table style=\"width: 100%; border-collapse: collapse; background-color: #c2e8f7; height: 309px;\">\n<tbody>\n<tr style=\"height: 309px;\">\n<td style=\"width: 100%; height: 309px;\">\n<figure id=\"attachment_349064\" aria-describedby=\"caption-attachment-349064\" style=\"width: 390px\" class=\"wp-caption alignright\"><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/eugenio-fonseca-ecclesia3.jpg\"><img decoding=\"async\" class=\"wp-image-349064 size-medium\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/eugenio-fonseca-ecclesia3-390x260.jpg\" alt=\"\" width=\"390\" height=\"260\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/eugenio-fonseca-ecclesia3-390x260.jpg 390w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/eugenio-fonseca-ecclesia3-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/eugenio-fonseca-ecclesia3-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/eugenio-fonseca-ecclesia3-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/eugenio-fonseca-ecclesia3-1536x1024.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/eugenio-fonseca-ecclesia3.jpg 1920w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/a><figcaption id=\"caption-attachment-349064\" class=\"wp-caption-text\">Foto: Ag\u00eancia ECCLESIA\/MC<\/figcaption><\/figure>\n<p>Numa nota final na celebra\u00e7\u00e3o, o bispo de Leiria-F\u00e1tima recordou Eug\u00e9nio Fonseca, presidente da Confedera\u00e7\u00e3o Portuguesa do Voluntariado, que <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/igreja-sociedade-morreu-eugenio-fonseca-antigo-presidente-da-caritas-portuguesa\/\">morreu<\/a> aos 69 anos na sequ\u00eancia de uma paragem cardiorrespirat\u00f3ria.<\/p>\n<p>Falando num \u201camigo e colega de caminho\u201d, D. Jos\u00e9 Ornelas destacou que, \u201cnos 21 anos\u201d em que o antigo presidente liderou a C\u00e1ritas Portuguesa, \u201cfoi o rosto apaixonado de incans\u00e1vel samaritano da Igreja para os sem-abrigo, os que ficam \u00e0 beira do caminho, os sedentos de justi\u00e7a, de acolhimento, de casa, p\u00e3o e esperan\u00e7a, de uma terra mais fraterna e em paz\u201d,<\/p>\n<p>\u201cNesta casa da M\u00e3e, fa\u00e7o mem\u00f3ria desta partida, juntando-me ao luto da fam\u00edlia e da Igreja de Set\u00fabal, mas dando igualmente gra\u00e7as a Deus pelo testemunho de vida deste irm\u00e3o, pedindo que as sementes de miseric\u00f3rdia que ele semeou cres\u00e7am no terreno da nossa sociedade e da nossa Igreja, para a constru\u00e7\u00e3o de um mundo de justi\u00e7a, de acolhimento e paz solid\u00e1ria para todos\u201d, apelou.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>LJ<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bispo diocesano deixou uma mensagem final aos peregrinos, na Missa da Peregrina\u00e7\u00e3o do Migrante e Refugiado, na qual recordou Eug\u00e9nio Fonseca e v\u00edtimas do terramoto na Col\u00f4mbia e Venezuela\u00a0<\/p>\n","protected":false},"author":17,"featured_media":438258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[89,3],"tags":[207,258,307],"class_list":["post-438234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque2","category-nacional","tag-fatima","tag-migracoes","tag-semana-nacional-de-migracoes"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/438234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=438234"}],"version-history":[{"count":12,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/438234\/revisions"}],"predecessor-version":[{"id":438350,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/438234\/revisions\/438350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/438258"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=438234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=438234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=438234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}