{"id":435431,"date":"2026-07-22T16:24:25","date_gmt":"2026-07-22T15:24:25","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=435431"},"modified":"2026-07-24T11:56:24","modified_gmt":"2026-07-24T10:56:24","slug":"igreja-brasil-patriarca-de-lisboa-desafia-fieis-a-missao-evangelizadora","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/igreja-brasil-patriarca-de-lisboa-desafia-fieis-a-missao-evangelizadora\/","title":{"rendered":"Igreja\/Brasil: Patriarca de Lisboa desafia fi\u00e9is \u00e0 miss\u00e3o evangelizadora"},"content":{"rendered":"<p><em>D. Rui Val\u00e9rio presidiu a Missa no VIII Encontro Latino-Americano de Espiritualidade Monfortina<\/em><!--more--><\/p>\n<figure id=\"attachment_435436\" aria-describedby=\"caption-attachment-435436\" style=\"width: 1599px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-435436 size-full\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida2.jpg\" alt=\"\" width=\"1599\" height=\"1066\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida2.jpg 1599w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida2-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida2-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida2-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida2-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1599px) 100vw, 1599px\" \/><figcaption id=\"caption-attachment-435436\" class=\"wp-caption-text\">FOTO: Santu\u00e1rio Nacional de Nossa Senhora Aparecida<\/figcaption><\/figure>\n<p>Aparecida, Brasil, 22 jul 2026 (Ecclesia) \u2013 O Patriarca de Lisboa desafiou hoje os cat\u00f3licos a assumirem um compromisso evangelizador capaz de reverter din\u00e2micas de morte espiritual, durante uma celebra\u00e7\u00e3o no Santu\u00e1rio de Nossa Senhora Aparecida, no Brasil.<\/p>\n<p>\u201cOs nossos pastores desafiam-nos todos ao quarto momento, a sermos mission\u00e1rios, a irmos para o mundo com este fogo, com esta for\u00e7a, para transformar as muitas sepulturas que existem nas almas, nas vidas, nos cora\u00e7\u00f5es de tantas, tantas pessoas, transformar estes sepulcros em jardins floridos pela nossa mensagem, pelo nosso testemunho, pela nossa miss\u00e3o evangelizadora\u201d, exortou D. Rui Val\u00e9rio, perante os participantes no VIII Encontro Latino-Americano de Espiritualidade Monfortina.<\/p>\n<p>O respons\u00e1vel portugu\u00eas apresentou o percurso b\u00edblico de Santa Maria Madalena como um itiner\u00e1rio pr\u00e1tico estruturado em quatro etapas distintas para consolidar a viv\u00eancia da f\u00e9.<\/p>\n<p>\u201cAlgu\u00e9m s\u00f3 vai \u00e0 procura se no seu cora\u00e7\u00e3o sentir um profundo desejo\u201d, indicou, numa interven\u00e7\u00e3o divulgada pelo Patriarcado de Lisboa.<\/p>\n<p>Segundo D. Rui Val\u00e9rio, a segunda fase desta caminhada depara-se frequentemente com uma &#8220;ambiguidade do olhar&#8221; face \u00e0s realidades quotidianas marcadas pelo luto e pela frustra\u00e7\u00e3o.<\/p>\n<p>\u201cQuando n\u00f3s olhamos para a vida e n\u00e3o compreendemos a vida, olhamos para o outro e n\u00e3o compreendemos o outro\u201d, diagnosticou o patriarca.<\/p>\n<div id='gallery-1' class='gallery galleryid-435431 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/igreja-brasil-patriarca-de-lisboa-desafia-fieis-a-missao-evangelizadora\/rui_valerio_aparecida\/'><img decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-435434\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida-1536x1024.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida.jpg 1599w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-435434'>\n\t\t\t\tFOTO: Santu\u00e1rio Nacional de Nossa Senhora Aparecida\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/igreja-brasil-patriarca-de-lisboa-desafia-fieis-a-missao-evangelizadora\/rui_valerio_aparecida3\/'><img decoding=\"async\" width=\"187\" height=\"280\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida3-187x280.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-435437\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida3-187x280.jpg 187w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida3-683x1024.jpg 683w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida3-768x1152.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida3.jpg 900w\" sizes=\"(max-width: 187px) 100vw, 187px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-435437'>\n\t\t\t\tFOTO: Santu\u00e1rio Nacional de Nossa Senhora Aparecida\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/igreja-brasil-patriarca-de-lisboa-desafia-fieis-a-missao-evangelizadora\/rui_valerio_aparecida1\/'><img loading=\"lazy\" decoding=\"async\" width=\"187\" height=\"280\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida1-187x280.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-435435\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida1-187x280.jpg 187w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida1-683x1024.jpg 683w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida1-768x1152.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida1-1024x1536.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/rui_valerio_aparecida1.jpg 1066w\" sizes=\"(max-width: 187px) 100vw, 187px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-435435'>\n\t\t\t\tFOTO: Santu\u00e1rio Nacional de Nossa Senhora Aparecida\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>A homilia destacou a mudan\u00e7a que acontece quando Maria Madalena ouve Jesus pronunciar o seu nome.<\/p>\n<p>\u201cEla foi chamada, n\u00e3o foi para ser criticada, n\u00e3o foi para ser condenada, foi para ser amada\u201d, precisou D. Rui Val\u00e9rio, destacando que a for\u00e7a do Evangelho n\u00e3o pode ficar &#8220;contida&#8221; na esfera individual.<\/p>\n<p>Na sauda\u00e7\u00e3o inicial da celebra\u00e7\u00e3o, o patriarca convidou os fi\u00e9is a colocarem-se diante de Jesus com a intercess\u00e3o de Nossa Senhora Aparecida, come\u00e7ando por reconhecer os motivos de gratid\u00e3o presentes na pr\u00f3pria vida.<\/p>\n<p>\u201cEstamos com Maria, Senhora da Aparecida, sua e nossa M\u00e3e. O primeiro olhar \u00e9 lan\u00e7ado \u00e0 nossa vida para nela encontrar raz\u00f5es, motivos, situa\u00e7\u00f5es e circunst\u00e2ncias de louvor e de gratid\u00e3o\u201d, afirmou.<\/p>\n<p>O VIII Encontro Latino-Americano de Espiritualidade Monfortina decorre at\u00e9 domingo na cidade de S\u00e3o Paulo.<\/p>\n<p><em>OC<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D. Rui Val\u00e9rio presidiu a Missa no VIII Encontro Latino-Americano de Espiritualidade Monfortina<\/p>\n","protected":false},"author":2,"featured_media":435436,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[89,3],"tags":[122,343,326],"class_list":["post-435431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque2","category-nacional","tag-brasil","tag-diocese-de-lisboa","tag-vida-consagrada"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/435431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=435431"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/435431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/435436"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=435431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=435431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=435431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}