{"id":435406,"date":"2026-07-22T13:42:43","date_gmt":"2026-07-22T12:42:43","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=435406"},"modified":"2026-07-24T10:10:08","modified_gmt":"2026-07-24T09:10:08","slug":"venezuela-bispo-auxiliar-de-caracas-lusodescendente-afirma-ha-muito-por-fazer-passado-um-mes-da-tragedia","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/venezuela-bispo-auxiliar-de-caracas-lusodescendente-afirma-ha-muito-por-fazer-passado-um-mes-da-tragedia\/","title":{"rendered":"Venezuela: Bispo auxiliar de Caracas, lusodescendente, afirma \u00abh\u00e1 muito por fazer\u00bb, passado um m\u00eas da \u00abtrag\u00e9dia\u00bb"},"content":{"rendered":"<p><em>A \u00abexperi\u00eancia pessoal\u00bb de D. Jos\u00e9 Dion\u00edsio Gouveia, com ra\u00edzes madeirenses, tem sido \u00abacompanhar, visitar os lugares afetados, falar com as pessoas\u00bb<\/em><!--more--><\/p>\n<figure id=\"attachment_432024\" aria-describedby=\"caption-attachment-432024\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-432024 size-full\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/06\/sismo_venezuela_EPA-2.jpg\" alt=\"\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/06\/sismo_venezuela_EPA-2.jpg 1920w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/06\/sismo_venezuela_EPA-2-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/06\/sismo_venezuela_EPA-2-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/06\/sismo_venezuela_EPA-2-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/06\/sismo_venezuela_EPA-2-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/06\/sismo_venezuela_EPA-2-1536x1024.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption id=\"caption-attachment-432024\" class=\"wp-caption-text\">Foto: Lusa\/EPA<\/figcaption><\/figure>\n<p>Caracas, 22 jul 2026 (Ecclesia) \u2013 O bispo auxiliar eleito de Caracas assinalou que \u201cpassado um m\u00eas desta trag\u00e9dia\u201d dos sismos na Venezuela \u201ch\u00e1 muito por fazer, h\u00e1 ainda muito movimento da terra para buscar v\u00edtimas\u201d, e destaca a proximidade da Igreja Cat\u00f3lica para apoiar a popula\u00e7\u00e3o.<\/p>\n<p>\u201cPassado um m\u00eas desta trag\u00e9dia, h\u00e1 agora muito por fazer, h\u00e1 ainda muito movimento da terra para buscar v\u00edtimas,\u00a0 alguma pessoa viva, para retirar muitos cad\u00e1veres que ainda faltam. E, agora, o desafio ue se apresenta \u00e9 procurar) habita\u00e7\u00e3o para as pessoas que ficaram sem casa, e seguir dando comida, roupa, de medicina, de aten\u00e7\u00e3o m\u00e9dica\u201d, disse D. Jos\u00e9 Dion\u00edsio Gouveia, em declara\u00e7\u00f5es \u00e0 Ag\u00eancia ECCLESIA.<\/p>\n<p>O bispo lusodescendente explicou que as pessoas est\u00e3o a se organizar \u201cem ref\u00fagios, acampamentos\u201d, e est\u00e3o o governo, muitas entidades a trabalhar, a acompanhar estas pessoas, por isso, o \u201cgrande desafio agora\u201d, \u00e9 irem tirando os escombros \u201ce limpando, mas tamb\u00e9m pensando nestas pessoas\u201d.<\/p>\n<p>\u201cEst\u00e1-se a fazer um grande trabalho tamb\u00e9m de engenharia, de olhar para muitos edif\u00edcios,\u00a0para certificar-se que pode habitar ou tem que ser demolido, arranjado,\u00a0antes de as pessoas continuarem morando a\u00ed\u201d, acrescentou.<\/p>\n<p>O territ\u00f3rio venezuelano foi atingido no passado dia 24 de junho por dois sismos consecutivos com magnitudes de 7,2 e 7,5 na escala de Richter; o n\u00famero de mortos aumentou para 5.346, segundo o \u00faltimo balan\u00e7o oficial, divulgado esta ter\u00e7a-feira.<\/p>\n<p>Sobre o aux\u00edlio \u00e0 popula\u00e7\u00e3o, o bispo auxiliar eleito de Caracas destaca que a arquidiocese cat\u00f3lica da capital venezuelana organizou \u201cum comit\u00e9 de emerg\u00eancia\u00a0para atender todas as pessoas\u201d\u00a0que foram afetadas pelo duplo sismo, \u201cn\u00e3o s\u00f3 na arquidiocese, mas tamb\u00e9m\u00a0em apoio \u00e0 Diocese de La Guaira,\u00a0tamb\u00e9m muito afetada\u201d.<\/p>\n<p>\u201cAtrav\u00e9s deste comit\u00e9 de emerg\u00eancia\u00a0est\u00e1-se visitando as pessoas no acampamento,\u00a0a ver que necessidades t\u00eam as pessoas\u00a0de comida, de roupas, de medicina,\u00a0de aten\u00e7\u00e3o m\u00e9dica,\u00a0e tamb\u00e9m fazer acompanhamento espiritual, psicol\u00f3gico, celebra\u00e7\u00f5es lit\u00fargicas para animar as pessoas,\u00a0olhar tamb\u00e9m os sacramentos, para as pessoas que ainda n\u00e3o t\u00eam\u201d, desenvolveu D. Jos\u00e9 Dion\u00edsio Gouveia, que \u00e9 natural de La Guaira, onde nasceu a 4 de junho de 1966.<\/p>\n<figure id=\"attachment_435408\" aria-describedby=\"caption-attachment-435408\" style=\"width: 373px\" class=\"wp-caption alignright\"><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/D.-Jose-Dionisio-Gouveia_Caracas_Venezuela_Facebook.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-435408\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/D.-Jose-Dionisio-Gouveia_Caracas_Venezuela_Facebook-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/D.-Jose-Dionisio-Gouveia_Caracas_Venezuela_Facebook-373x280.jpg 373w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/D.-Jose-Dionisio-Gouveia_Caracas_Venezuela_Facebook-1024x768.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/D.-Jose-Dionisio-Gouveia_Caracas_Venezuela_Facebook-768x576.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/D.-Jose-Dionisio-Gouveia_Caracas_Venezuela_Facebook-1536x1152.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/07\/D.-Jose-Dionisio-Gouveia_Caracas_Venezuela_Facebook.jpg 2048w\" sizes=\"(max-width: 373px) 100vw, 373px\" \/><\/a><figcaption id=\"caption-attachment-435408\" class=\"wp-caption-text\">Foto: D. Jos\u00e9 Dion\u00edsio Gouveia (Facebook)<\/figcaption><\/figure>\n<p>O respons\u00e1vel destaca que a Arquidiocese de Caracas est\u00e1 a fazer \u201cum trabalho muito grande\u201d, sobretudo com este Comit\u00e9 de Emerg\u00eancia, que faz parcerias com a C\u00e1ritas de Venezuela, com as C\u00e1ritas paroquiais e tamb\u00e9m com muitas institui\u00e7\u00f5es religiosas que \u201cest\u00e3o a atender meninos, anci\u00e3os, doentes, e a visitar os hospitais, as pessoas nas casas, \u201ca acompanhar o enterro dos seres queridos que v\u00e3o aparecendo\u201d,\u00a0 a b\u00ean\u00e7\u00e3o das cinzas, para \u201cdar tranquilidade, uma fortaleza a todas estas pessoas\u201d.<\/p>\n<p>D. Jos\u00e9 Dion\u00edsio Gouveia adiantou que v\u00e3o assinalar o primeiro \u201cm\u00eas da trag\u00e9dia dos terremotos na Venezuela\u201d, e esta sexta-feira, dia 24 de julho, v\u00e3o celebrar \u201cuma Santa Missa na Arquidiocese de Caracas, na igreja S\u00e3o Judas Tadeu, para elevar uma ora\u00e7\u00e3o pelas v\u00edtimas, para tamb\u00e9m animar as pessoas\u201d.<\/p>\n<blockquote><p>\u201cA minha experi\u00eancia pessoal neste tempo tem sido acompanhar, visitar os lugares afetados,\u00a0falar com as pessoas, dar \u00e2nimo, escutar os testemunhos do que viveram, rezar pelo seres queridos perdidos,\u00a0olhar para os doentes\u201d, partilhou.<\/p><\/blockquote>\n<p>Segundo o bispo auxiliar eleito, \u201ctem-se feito muito\u201d, muita companhia na pastoral arquidiocesana,\u00a0nas par\u00f3quias, nas visitas e a \u201cter contato com essas pessoas, que est\u00e3o agora a passar essas grandes necessidades, para fazer presen\u00e7a do Nosso Senhor e da Igreja\u201d.<\/p>\n<p>Ordenado sacerdote 24 novembro de 2001, D. Jos\u00e9 Dion\u00edsio Gouveia foi nomeado bispo auxiliar de Caracas \u2013 Santiago de Venezuela, titular da S\u00e9 de Fuerteventura, pelo Papa Le\u00e3o XIV, no dia 18 de mar\u00e7o deste ano.<\/p>\n<p>A ordena\u00e7\u00e3o episcopal do atual reitor do Semin\u00e1rio arquidiocesano de Santa Rosa de Lima vai realizar-se a 15 de agosto, solenidade da Assun\u00e7\u00e3o de Nossa Senhora e festa de Nossa Senhora do Monte, padroeira da Madeira, na igreja de S\u00e3o Jo\u00e3o Bosco, em Altamira; onde participar\u00e1 o bispo do Funchal, D. Nuno Br\u00e1s, que vai <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/events\/igreja-solidariedade-bispo-do-funchal-vai-visitar-zonas-afetadas-pelos-sismos-na-venezuela\/\">visitar<\/a> a Venezuela, de 12 a 16 de agosto, a convite do arcebispo de Caracas, D. Ra\u00fal Biord.<\/p>\n<p><em>CB\/OC<\/em><\/p>\n<table style=\"width: 100%; border-collapse: collapse; background-color: #f3ddca;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\">A\u00a0Funda\u00e7\u00e3o Ajuda \u00e0 Igreja que Sofre (AIS) est\u00e1 a apoiar sacerdotes, religiosas e leigos que trabalham diretamente com as v\u00edtimas dos sismos na Venezuela, a sua presidente executiva\u00a0visitou o pa\u00eds da Am\u00e9rica latina, no dia 7 de julho, para manifestar solidariedade com a Igreja local e as comunidades.<\/p>\n<p>\u201cEu n\u00e3o esperava encontrar um n\u00edvel de destrui\u00e7\u00e3o t\u00e3o grande. Quando se chega l\u00e1 e v\u00ea montanhas de escombros por toda a cidade, equipas de homens e escavadoras a remexer os destro\u00e7os (eles j\u00e1 n\u00e3o procuram sobreviventes, passou demasiado tempo) ou se v\u00eaem enormes pr\u00e9dios inclinados onde obviamente ningu\u00e9m pode estar vivo, \u00e9 algo de apocal\u00edptico\u201d, relatou Regina Lynch, na informa\u00e7\u00e3o enviada hoje \u00e0 Ag\u00eancia ECCLESIA, pelo secretariado portugu\u00eas da funda\u00e7\u00e3o pontif\u00edcia.<\/p>\n<p>A AIS para al\u00e9m da assist\u00eancia imediata, tamb\u00e9m destinou uma\u00a0ajuda inicial de 100 mil euros, est\u00e1 a preparar novos projetos para reconstruir estruturas da Igreja e oferecer apoio \u00e0s pessoas que enfrentam traumas, para a presidente executiva a situa\u00e7\u00e3o da Venezuela e a destrui\u00e7\u00e3o causada pelos terramotos, supera qualquer expectativa, e descreve a realidade em La Guaira como \u201capocal\u00edptica\u201d.<\/p>\n<p>\u201cFoi poss\u00edvel ver como a Igreja est\u00e1 bem organizada na Venezuela. Eles t\u00eam uma grande opera\u00e7\u00e3o em andamento. Havia muitos volunt\u00e1rios, de todas as idades, ajudando a separar as doa\u00e7\u00f5es enviadas por outras pessoas do pr\u00f3prio pa\u00eds. Parecia uma colmeia\u201d, acrescentou Regina Lynch.<\/p>\n<p>A <a href=\"https:\/\/fundacao-ais.pt\/venezuela-situacao-e-apocaliptica-mas-a-igreja-esta-organizada-e-a-dar-resposta-as-vitimas-dos-terramotos\/\">Funda\u00e7\u00e3o Ajuda \u00e0 Igreja que Sofre<\/a> est\u00e1 presente nas Dioceses venezuelanas de Caracas e La Guaira desde 2011, \u201cquando come\u00e7ou a grave crise econ\u00f3mica e social no pa\u00eds\u201d, e construiu uma \u201crela\u00e7\u00e3o de confian\u00e7a\u201d com a Igreja local ao longo destes quase 15 anos, segundo a presidente executiva\u00a0as infraestruturas constru\u00eddas com recursos da AIS resistiu aos terramotos, enquanto muitos conjuntos habitacionais desabaram completamente.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_27370\"  width=\"480\" height=\"270\"  data-origwidth=\"480\" data-origheight=\"270\" src=\"https:\/\/www.youtube.com\/embed\/7UYYG7V8rnE?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=pt&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A \u00abexperi\u00eancia pessoal\u00bb de D. Jos\u00e9 Dion\u00edsio Gouveia, com ra\u00edzes madeirenses, tem sido \u00abacompanhar, visitar os lugares afetados, falar com as pessoas\u00bb<\/p>\n","protected":false},"author":3,"featured_media":432024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[89,4],"tags":[104,215,314,398],"class_list":["post-435406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque2","category-internacional","tag-america","tag-fundacao-ais","tag-solidariedade","tag-venezuela"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/435406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=435406"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/435406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/432024"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=435406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=435406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=435406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}