{"id":434503,"date":"2026-07-15T12:01:56","date_gmt":"2026-07-15T11:01:56","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=434503"},"modified":"2026-07-14T16:12:09","modified_gmt":"2026-07-14T15:12:09","slug":"guarda-bispo-aprova-mapa-provisorio-de-reorganizacao-das-361-paroquias-em-27-unidades-pastorais","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/guarda-bispo-aprova-mapa-provisorio-de-reorganizacao-das-361-paroquias-em-27-unidades-pastorais\/","title":{"rendered":"Guarda: Bispo aprova mapa provis\u00f3rio de reorganiza\u00e7\u00e3o das 361 par\u00f3quias em 27 unidades pastorais"},"content":{"rendered":"<p><em>D. Jos\u00e9 Pereira explica que implementa\u00e7\u00e3o ser\u00e1 feita de forma gradual at\u00e9 ao Jubileu dos Dois Mil Anos da Reden\u00e7\u00e3o, em 2033<\/em><\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-272408 size-full\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda.jpg\" alt=\"\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda.jpg 1920w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda-390x260.jpg 390w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda-1536x1024.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda-1080x720.jpg 1080w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda-1280x853.jpg 1280w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda-980x653.jpg 980w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2023\/02\/Guarda-480x320.jpg 480w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/a>Guarda, 14 jul 2026 (Ecclesia) &#8211; O bispo da Guarda, D. Jos\u00e9 Pereira, aprovou um mapa provis\u00f3rio da constitui\u00e7\u00e3o de 27 Unidades Pastorais (UP), que ser\u00e1 revisto em 2032, concretizando a reconfigura\u00e7\u00e3o pastoral das 361 par\u00f3quias da diocese.<\/p>\n<p>\u201cO mapa agora considerado \u00e9 provis\u00f3rio: ir\u00e1 sendo implementado durante os pr\u00f3ximos anos at\u00e9 \u00e0 celebra\u00e7\u00e3o do Jubileu Extraordin\u00e1rio de 2033. At\u00e9 l\u00e1, as configura\u00e7\u00f5es das Unidades Pastorais poder\u00e3o sofrer alguma revis\u00e3o, de acordo com as indica\u00e7\u00f5es que surgirem do funcionamento pastoral das mesmas\u201d, l\u00ea-se no decreto enviado hoje \u00e0 Ag\u00eancia Ecclesia, com a data do \u00faltimo s\u00e1bado, mem\u00f3ria lit\u00fargica de S\u00e3o Bento, padroeiro da Europa<\/p>\n<p>Esta reorganiza\u00e7\u00e3o da rede paroquial insere-se num processo encetado no in\u00edcio da segunda d\u00e9cada deste s\u00e9culo, e pretende adaptar a a\u00e7\u00e3o da Igreja \u00e0s atuais realidades demogr\u00e1ficas e pastorais, marcadas pela perda de popula\u00e7\u00e3o, pelo envelhecimento e pela diminui\u00e7\u00e3o do n\u00famero de sacerdotes.<\/p>\n<p>As primeiras cinco Unidades Pastorais entram em funcionamento no ano pastoral 2026-2027 e abrangem as zonas da Covilh\u00e3 Urbana, Covilh\u00e3 Norte, Covilh\u00e3 Sul, Penamacor e Seia Urbana.<\/p>\n<p>O decreto resulta de um processo de reflex\u00e3o desenvolvido na Diocese ao longo da \u00faltima d\u00e9cada, refor\u00e7ado pela escuta realizada durante o percurso sinodal e pelas consultas aos diferentes \u00f3rg\u00e3os diocesanos.<\/p>\n<p>Al\u00e9m da cria\u00e7\u00e3o das Unidades Pastorais, o bispo determinou a configura\u00e7\u00e3o dos Arciprestados na raia, tendo em conta as indica\u00e7\u00f5es do clero dos respetivos arciprestados, ouvido o Pr\u00f3-Conselho episcopal e o Conselho de Arciprestes.<\/p>\n<p>Nesse sentido, o concelho de Penamacor deixa o Arciprestado de Fund\u00e3o-Penamacor para integrar o novo Arciprestado de Sabugal-Penamacor.<\/p>\n<p>Por sua vez, o Arciprestado do Fund\u00e3o passa a reunir apenas as par\u00f3quias do concelho do Fund\u00e3o e as da Diocese situadas no concelho de Castelo Branco e o concelho de Almeida passa a integrar o novo Arciprestado de Pinhel-Almeida-Figueira de Castelo Rodrigo.<\/p>\n<p>Al\u00e9m do decreto, o bispo publicou um documento de instru\u00e7\u00e3o pastoral sobre a reconfigura\u00e7\u00e3o da pastoral paroquial e a constitui\u00e7\u00e3o das unidades pastorais, com o t\u00edtulo \u201cComo nos ensina a Igreja\u201d.<\/p>\n<p>\u201cAs Unidades Pastorais n\u00e3o s\u00e3o a simples entrega de v\u00e1rias par\u00f3quias ao cuidado do(s) mesmo(s) p\u00e1roco(s); s\u00e3o antes a tradu\u00e7\u00e3o de que o cuidado das comunidades cabe, ainda que de modos diferentes consoante os seus carismas, voca\u00e7\u00f5es e minist\u00e9rios, a todos os batizados constitu\u00eddos em comunh\u00e3o para o efeito\u201d, indica.<\/p>\n<p>O texto assinala que as UP podem adotar um dos tr\u00eas modelos seguintes: modelo em rede (rural, disperso, sem um centro definido); modelo conc\u00eantrico (misto, com um centro, seja ele uma pequena cidade ou vila) e modelo homog\u00e9neo (urbano, com grande mobilidade interna).<\/p>\n<blockquote><p>As Unidades Pastorais n\u00e3o anulam as configura\u00e7\u00f5es administrativas das par\u00f3quias nem os seus Conselhos para os Assuntos Econ\u00f3micos (que, segundo as normas do Direito Can\u00f3nico, s\u00e3o obrigat\u00f3rios e atualizam as antigas Comiss\u00f5es Fabriqueiras). Mas potenciam-nas numa l\u00f3gica de comunh\u00e3o e coordena\u00e7\u00e3o, favorecendo a sinergia de esfor\u00e7os, meios e estruturas.&#8221;<\/p><\/blockquote>\n<p>O documento aponta tamb\u00e9m um conjunto de elementos estruturantes das UP, no qual se incluem o coordenador pastoral, que assumir\u00e1 a fun\u00e7\u00e3o de coordenador dos v\u00e1rios agentes (ministros ordenados, consagrados e leigos) e da a\u00e7\u00e3o pastoral e ser\u00e1 o p\u00e1roco de todas as par\u00f3quias desta estrutura.<\/p>\n<p>A lista prev\u00ea tamb\u00e9m a Comiss\u00e3o de Coordena\u00e7\u00e3o Pastoral, o Conselho Pastoral da Unidade, o Conselho Econ\u00f3mico e Fundo Comum da Unidade Pastoral, o Cart\u00f3rio, Centro(s) Pastoral(ais) e Minist\u00e9rios Comuns.<\/p>\n<p>As 27 Unidades Pastorais ser\u00e3o implementadas progressivamente, \u00e0 medida da possibilidade das par\u00f3quias e da constitui\u00e7\u00e3o de novas equipas pastorais de padres, di\u00e1conos e leigos, at\u00e9 ao ano pastoral 2032-2033, altura em que se iniciar\u00e1 o Jubileu Extraordin\u00e1rio dos 2.000 anos da Reden\u00e7\u00e3o.<\/p>\n<p>\u201cConfio este caminho de reorganiza\u00e7\u00e3o mission\u00e1ria e sinodal da nossa pastoral diocesana \u00e0 intercess\u00e3o e inspira\u00e7\u00e3o de S\u00e3o Bento, grande reformador da rede comunit\u00e1ria da Igreja na mudan\u00e7a epocal que sucedeu ao Imp\u00e9rio Romano no Ocidente. E \u00e0 prote\u00e7\u00e3o maternal de Nossa Senhora, M\u00e3e da Igreja e modelo da escuta obediente ao que o Esp\u00edrito Santo diz \u00e0 Igreja\u201d, conclui D. Jos\u00e9 Pereira.<\/p>\n<table style=\"width: 100%; border-collapse: collapse; background-color: #c2e8f7;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\">\n<p style=\"text-align: center;\"><strong>As 27 Unidades Pastorais<\/strong><\/p>\n<p><strong>ALMEIDA<\/strong><\/p>\n<p>Ade, Aldeia Nova, Almeida, Amoreira, Azinhal, Cabreira do C\u00f4a, Castelo Bom, Castelo Mendo, Freineda, Freixo, Jun\u00e7a, Leomil, Malhada Sorda, Malpartida, Mesquitela, Mido, Miuzela, Monteperobolso, Nave de Haver, Naves, Parada, Peva, Porto de Ovelha, S\u00e3o Pedro de Rio Seco, Senouras, Vale de Coelha, Vale da Mula, Valverde, Vilar Formoso.<\/p>\n<p><strong>BELMONTE<\/strong><\/p>\n<p>Belmonte, Bendada, Caria, Colmeal da Torre, Inguias, Ma\u00e7ainhas.<\/p>\n<p><strong>CELORICO DA BEIRA<\/strong><\/p>\n<p>A\u00e7ores, Bara\u00e7al, Cadafaz, Carrapichana, Corti\u00e7\u00f4 da Serra, Fornotelheiro, Juncais, Lageosa do Mondego, Linhares da Beira, Ma\u00e7al do Ch\u00e3o, Mesquitela, Minhocal, Prados, Rapa, Ratoeira, Salgueirais, Santa Maria (Celorico), S\u00e3o Pedro (Celorico), Vale de Azares, Velosa, Vide Entre Vinhas, Vila Boa do Mondego.<\/p>\n<p><strong>COVILH\u00c3 URBANA<\/strong><\/p>\n<p>Boidobra, Imaculada Concei\u00e7\u00e3o (Covilh\u00e3), Santa Maria (Covilh\u00e3), S\u00e3o Jos\u00e9 (Covilh\u00e3), S\u00e3o Martinho (Covilh\u00e3), S\u00e3o Pedro (Covilh\u00e3), Vila do Carvalho.<\/p>\n<p><strong>COVILH\u00c3 NORTE<\/strong><\/p>\n<p>Aldeia do Souto, Orjais, Sarzedo, Teixoso, Vale Formoso, Verdelhos.<\/p>\n<p><strong>COVILH\u00c3 Z\u00caZERE<\/strong><\/p>\n<p>Barco, Dominguiso, Ferro, Peraboa, Peso, Tortosendo.<\/p>\n<p><strong>COVILH\u00c3 SUL<\/strong><\/p>\n<p>Casegas, Cortes, Erada, Ourondo, Paul, Sobral de S\u00e3o Miguel, Unhais da Serra.<\/p>\n<p><strong>FIGUEIRA DE CASTELO RODRIGO<\/strong><\/p>\n<p>Algodres, Almendra, Almofala, Castelo Melhor, Castelo Rodrigo, Cinco Vilas, Colmeal, Escalh\u00e3o, Escarigo, Figueira de Castelo Rodrigo, Freixeda do Torr\u00e3o, Mata de Lobos, Penha de \u00c1guia, Quint\u00e3 de Pero Martins, Reigada, Vale de Afonsinho, Vermiosa, Vilar de Amargo, Vilar Torpim.<\/p>\n<p><strong>FUND\u00c3O NORTE<\/strong><\/p>\n<p>Alcaide, Alcaria, Alcongosta, Aldeia de Joanes, Aldeia Nova do Cabo, Capinha, Donas, Escarigo, Fatela, Fund\u00e3o, Peroviseu, Salgueiro, Souto da Casa, Telhado, Valverde.<\/p>\n<p><strong>FUND\u00c3O SUL<\/strong><\/p>\n<p>Almaceda, Alpedrinha, Atalaia do Campo, Castelo Novo, Louri\u00e7al do Campo, Ninho do A\u00e7or, Orca, P\u00f3voa da Atalaia, S\u00e3o Vicente da Beira, Soalheira, Vale de Prazeres, Zebras.<\/p>\n<p><strong>FUND\u00c3O POENTE<\/strong><\/p>\n<p>Aldeia de S\u00e3o Francisco de Assis, Barroca, Bogas de Baixo, Bogas de Cima, Castelejo, Janeiro de Cima, Lavacolhos, Silvares, S\u00e3o Jorge da Beira.<\/p>\n<p><strong>GOUVEIA SERRA<\/strong><\/p>\n<p>Aldeias, Figueir\u00f3 da Serra, Folgosinho, Freixo da Serra, Mangualde da Serra, Melo, Moimenta da Serra, Nabais, Nespereira, Pa\u00e7os da Serra, S\u00e3o Juli\u00e3o (Gouveia), S\u00e3o Paio, S\u00e3o Pedro (Gouveia), Vinh\u00f3.<\/p>\n<p><strong>GOUVEIA PLAN\u00cdCIE<\/strong><\/p>\n<p>Arcozelo, Cativelos, Girabolhos, Lagarinhos, Lages, Ribamondego, Rio Torto, Vila Cort\u00eas da Serra, Vila Franca da Serra, Vila Nova de T\u00e1zem, Vila Ruiva.<\/p>\n<p><strong>GUARDA URBANA<\/strong><\/p>\n<p>S\u00e3o Miguel (Guarda), S\u00e3o Vicente (Guarda), S\u00e9 (Guarda).<\/p>\n<p><strong>GUARDA NASCENTE<\/strong><\/p>\n<p>Ad\u00e3o, Albardo, Benespera, Carvalhal Me\u00e3o, Casal de Cinza, Castanheira, Cerdeira do C\u00f4a, Jo\u00e3o Ant\u00e3o, Marmeleiro, Monte Margarida, Pan\u00f3ias, Pega, Pousade, Ramela, Rochoso, Santa Ana da Azinha, Vila Fernando, Vila Garcia.<\/p>\n<p><strong>GUARDA NORTE<\/strong><\/p>\n<p>Alvendre, Arrifana, Avel\u00e3s da Ribeira, Avel\u00e3s de Ambom, Codeceiro, Gon\u00e7albocas, Pera do Mo\u00e7o, Ribeira dos Carinhos, Rocamondo, S\u00e3o Miguel (Jarmelo), S\u00e3o Pedro (Jarmelo), Vila Franca do De\u00e3o.<\/p>\n<p><strong>GUARDA POENTE<\/strong><\/p>\n<p>Aldeia do Bispo, Aldeia Vi\u00e7osa, Corujeira, Cavadoude, Faia, Fern\u00e3o Joanes, Ma\u00e7ainhas, Meios, Misarela, Pero Soares, Porto da Carne, Sobral da Serra, Trinta, Vale de Estrela, Videmonte, Vila Cort\u00eas do Mondego, Vila Soeiro.<\/p>\n<p><strong>GUARDA SUL<\/strong><\/p>\n<p>Famalic\u00e3o da Serra, Gon\u00e7alo, Santa Maria (Manteigas), S\u00e3o Pedro (Manteigas), Sameiro, Seixo Amarelo, Vale de Amoreira, Valhelhas, Vela.<\/p>\n<p><strong>PENAMACOR<\/strong><\/p>\n<p>\u00c1guas, Aldeia de Jo\u00e3o Pires, Aldeia do Bispo, Aranhas, Bemposta, Benqueren\u00e7a, Meim\u00e3o, Meimoa, Pedr\u00f3g\u00e3o de S\u00e3o Pedro, Penamacor, Salvador, Vale de Nossa Senhora da P\u00f3voa.<\/p>\n<p><strong>PINHEL<\/strong><\/p>\n<p>Alverca da Beira, Atalaia, Azevo, Bogalhal, Bou\u00e7a Cova, Carvalhal, Cerejo, Cidadelhe, Ervas Tenras, Ervedosa, Freixedas, Gouveias, Lamegal, Lameiras, Manigoto, Pala, Pereiro, Pinhel, P\u00ednzio, Pomares, P\u00f3voa d\u2019El Rei, Safurd\u00e3o, Santa Euf\u00e9mia, Sorval, Souropires, Valbom, Vale de Madeira, Vascoveiro, Vendada.<\/p>\n<p><strong>SABUGAL C\u00d4A<\/strong><\/p>\n<p>\u00c1guas Belas, Aldeia de Santo Ant\u00f3nio, Bara\u00e7al, Casteleiro, Lomba, Malcata, Moita, Penalobo, Pousafoles do Bispo, Quadrazais, Quintas de S\u00e3o Bartolomeu, Rapoula do C\u00f4a, Rendo, Sabugal, Santo Est\u00eav\u00e3o, Seixo do C\u00f4a, Sortelha, Valongo do C\u00f4a, Vila do Touro.<\/p>\n<p><strong>SABUGAL RAIA<\/strong><\/p>\n<p>Aldeia do Bispo, Aldeia da Ponte, Aldeia da Ribeira, Aldeia Velha, Alfaiates, Badamalos, Bismula, Foios, Forcalhos, Lageosa, Nave, Rebolosa, Ruiv\u00f3s, Ruvina, Soito, Vale das \u00c9guas, Vale de Espinho, Vila Boa, Vilar Maior.<\/p>\n<p><strong>SEIA URBANA<\/strong><\/p>\n<p>Seia, Sabugueiro, Santiago, S\u00e3o Rom\u00e3o, Vila Cova \u00e0 Coelheira.<\/p>\n<p><strong>SEIA PLAN\u00cdCIE<\/strong><\/p>\n<p>Carragozela, Folhadosa, Paranhos da Beira, Pinhan\u00e7os, Sameice, Santa Comba, Santa Eul\u00e1lia, Santa Marinha, S\u00e3o Martinho, Torroselo, Tourais, Travancinha, V\u00e1rzea de Meruge.<\/p>\n<p><strong>SEIA SERRA<\/strong><\/p>\n<p>Alvoco da Serra, Cabe\u00e7a, Loriga, Sandomil, S\u00e3o Gi\u00e3o, Sazes da Beira, Teixeira, Valezim, Vide.<\/p>\n<p><strong>TRANCOSO POENTE<\/strong><\/p>\n<p>Aldeia Nova, Fi\u00e3es, Castanheira, Falachos, Guilheiro, Moreira de Rei, Palhais, Reboleiro, Rio de Mel, Santa Maria (Trancoso), S\u00e3o Pedro (Trancoso), Sebadelhe, Soito Maior, Tamanhos, Terrenho, Torre do terrenho, Valdujo.<\/p>\n<p><strong>TRANCOSO NASCENTE<\/strong><\/p>\n<p>Carnic\u00e3es, Cogula, C\u00f3timos, Feital, Freches, Granja, Moimentinha, P\u00f3voa do Concelho, Torres, Vale de Mouro, Vale do Seixo, Vila Franca das Naves, Vila Garcia, Vilares.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>LJ\/OC<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D. Jos\u00e9 Pereira explica que implementa\u00e7\u00e3o ser\u00e1 feita de forma gradual at\u00e9 ao Jubileu dos Dois Mil Anos da Reden\u00e7\u00e3o, em 2033<\/p>\n","protected":false},"author":17,"featured_media":272408,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1020,3],"tags":[168],"class_list":["post-434503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manchete-ultimas2","category-nacional","tag-diocese-da-guarda"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/434503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=434503"}],"version-history":[{"count":3,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/434503\/revisions"}],"predecessor-version":[{"id":434510,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/434503\/revisions\/434510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/272408"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=434503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=434503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=434503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}