{"id":4322,"date":"2006-04-03T14:44:19","date_gmt":"2006-04-03T14:44:19","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/04\/03\/assembleia-anual-dos-missionarios-de-s-carlos\/"},"modified":"2006-04-03T14:44:19","modified_gmt":"2006-04-03T14:44:19","slug":"assembleia-anual-dos-missionarios-de-s-carlos","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/assembleia-anual-dos-missionarios-de-s-carlos\/","title":{"rendered":"Assembleia anual dos Mission\u00e1rios de S. Carlos"},"content":{"rendered":"<p>Realizou-se em Triuggio, vila na periferia de Mil\u00e3o (Italia), de 19 a 22 de Janeiro, a Assembleia anual dos Mission\u00e1rios de S. Carlos (Scalabrinianos) empenhados, em nome da Igreja local,  na promo\u00e7\u00e3o humana e evangeliza\u00e7\u00e3o de diversas comunidades cat\u00f3licas, constitu\u00eddas por migrantes.  A Congrega\u00e7\u00e3o encontra-se presente em 8 na\u00e7\u00f5es da Europa, entre as quais Portugal, e tamb\u00e9m se ocupa de refugiados e imigrantes na \u00c1frica do Sul.  Actualmente a \u201cProv\u00edncia Europeia\u201d serve emigrantes europeus &#8211; italianos, espanh\u00f3is e portugueses -, e de outros Continentes: africanos, cabo-verdianos, latino-americanos, brasileiros, filipinos, indianos, entre outros.    N\u00e3o obstante a escassez de voca\u00e7\u00f5es europeias e as r\u00e1pidas muta\u00e7\u00f5es nos movimentos migrat\u00f3rios no seio da Europa, da Assembleia destacam-se os seguintes pontos onde se prev\u00ea uma renova\u00e7\u00e3o da ac\u00e7\u00e3o pastoral e estilo de presen\u00e7a consagrada:  1.Numa sociedade sempre mais multicultural, urge reafirmar a aposta na reflex\u00e3o e aplica\u00e7\u00e3o da \u201cpastoral inter-comunit\u00e1ria\u201d que, partindo da ac\u00e7\u00e3o das Miss\u00f5es Cat\u00f3licas ligadas a um grupo linguistico particular, procura por em interac\u00e7\u00e3o as varias culturas presentes na paroquia e na diocese, com vista a reciprocidade de perten\u00e7as e de itiner\u00e1rios de f\u00e9 \u201cinculturados\u201d. 2.Intensificar a ac\u00e7\u00e3o de defesa dos direitos dos migrantes, suas fam\u00edlias e suas identidades culturais, tornando-os sempre cada vez mais, atrav\u00e9s da consciencializa\u00e7\u00e3o, sujeitos e actores numa Europa que n\u00e3o pode sobreviver sem a presen\u00e7a e contributo dos imigrantes. Os programas de \u201cforma\u00e7\u00e3o permanente\u201d dos mission\u00e1rios debru\u00e7ar-se-\u00e3o sobre os temas da \u201cIntercultura\u201d e dos \u201cdireitos\u201d. 3.Diante dos novos desafios lan\u00e7ados pelo laicado crist\u00e3o e pela \u201cglobaliza\u00e7\u00e3o da solidariedade\u201d \u00e0s Congrega\u00e7\u00f5es Missionarias na Europa, e obedecendo a uma directiva da Cap\u00edtulo Geral, os Scalabrinianos v\u00e3o constituir ao longo deste ano uma Organiza\u00e7\u00e3o n\u00e3o governamental, com vista \u00e0 Coopera\u00e7\u00e3o, Desenvolvimento e Protec\u00e7\u00e3o dos Direitos no \u00e2mbito especifico das Migra\u00e7\u00f5es. Deste modo, ser\u00e3o garantidas m\u00faltiplas parcerias com a sociedade civil em nome do Evangelho. 4.Celebrar com os imigrantes, com a Igreja e as ONG, a efem\u00e9ride do Centen\u00e1rio da morte do beato Jo\u00e3o Baptista Scalabrini, precursor da tutela dos direitos civis e religiosos dos migrantes, a acontecer no ano 2005. Encontra-se em fase ultima de elabora\u00e7\u00e3o o programa das celebra\u00e7\u00f5es, a n\u00edvel mundial, que envolvera todas as comunidades num processo de refontaliza\u00e7ao carism\u00e1tica da vida fraterna e testemunho mission\u00e1rio.  Durante a Assembleia, o Superior Geral, Pe. Isaias Birillo, ao termo da sua Visita Can\u00f3nica \u00e0 Regi\u00e3o, transmitiu \u00e0 centena de mission\u00e1rios presentes as conclus\u00f5es do Relat\u00f3rio da Visita e apelou a que todos se envolvam sem desfalecer e com criatividade, na anima\u00e7\u00e3o vocacional e na abertura mental \u00e0s novas imigra\u00e7\u00f5es, incluindo as de matriz religiosa mu\u00e7ulmana.  Triuggio, Milao  23 de Janeiro de 2004<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizou-se em Triuggio, vila na periferia de Mil\u00e3o (Italia), de 19 a 22 de Janeiro, a Assembleia anual dos Mission\u00e1rios de S. Carlos (Scalabrinianos) empenhados, em nome da Igreja local, na promo\u00e7\u00e3o humana e evangeliza\u00e7\u00e3o de diversas comunidades cat\u00f3licas, constitu\u00eddas por migrantes. A Congrega\u00e7\u00e3o encontra-se presente em 8 na\u00e7\u00f5es da Europa, entre as quais Portugal, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9],"tags":[101,122,203,206,258,261,291,305,314],"class_list":["post-4322","post","type-post","status-publish","format-standard","hentry","category-documentos","tag-africa","tag-brasil","tag-europa","tag-familia","tag-migracoes","tag-missoes","tag-refugiados","tag-scalabrinianos","tag-solidariedade"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/4322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=4322"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/4322\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=4322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=4322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=4322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}