{"id":42897,"date":"2010-01-09T15:29:56","date_gmt":"2010-01-09T15:29:56","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2010\/01\/09\/papa-pede-cultura-intelectual-genuinamente-catolica\/"},"modified":"2010-01-09T15:29:56","modified_gmt":"2010-01-09T15:29:56","slug":"papa-pede-cultura-intelectual-genuinamente-catolica","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/papa-pede-cultura-intelectual-genuinamente-catolica\/","title":{"rendered":"Papa pede \u00abcultura intelectual genuinamente cat\u00f3lica\u00bb"},"content":{"rendered":"<p>Bento XVI recordou viagem aos Estados Unidos da Am\u00e9rica <!--more--> <\/p>\n<p>Bento XVI pediu que a Igreja dos EUA seja capaz de &ldquo;cultivar uma cultura intelectual genuinamente cat&oacute;lica, confiante na harmonia profunda entre f&eacute; e raz&atilde;o, e preparada para levar a riqueza da vis&atilde;o da f&eacute; no contacto com as quest&otilde;es urgentes que concernem ao futuro da sociedade americana&rdquo;.<\/p>\n<p>O Papa recebeu esta manh&atilde;, em audi&ecirc;ncia, os superiores, alunos e ex-alunos do Pontif&iacute;cio Col&eacute;gio Norte-americano, por ocasi&atilde;o dos 150 de sua funda&ccedil;&atilde;o.<\/p>\n<p>No discurso aos cerca de 550 presentes, Bento XVI recordou a sua viagem apost&oacute;lica aos EUA, realizada em Abril de 2008, e louvou o compromisso do Col&eacute;gio que, passados 150 anos de sua funda&ccedil;&atilde;o, continua a formar &ldquo;pastores s&aacute;bios e generosos&#8221;.<\/p>\n<p>O Papa recordou que foi Pio IX quem quis, em 1859, a funda&ccedil;&atilde;o do Pontif&iacute;cio Col&eacute;gio Norte-americano, e reiterou que, &agrave; dist&acirc;ncia de um s&eacute;culo e meio de sua institui&ccedil;&atilde;o, o Col&eacute;gio &ldquo;permaneceu fiel &agrave; sua vis&atilde;o de funda&ccedil;&atilde;o&rdquo;, ou seja, &ldquo;formar louv&aacute;veis pregadores do Evangelho e ministros dos sacramentos, devotos ao Sucessor de Pedro e comprometidos com a constru&ccedil;&atilde;o da Igreja nos EUA&rdquo;.<\/p>\n<p>O encontro &eacute; tamb&eacute;m uma oportunidade, focou o Papa, para o Col&eacute;gio, &ldquo;reafirmar a afei&ccedil;&atilde;o filial &agrave; Igreja de Roma, para recordar o trabalho apost&oacute;lico realizado por numerosos alunos e para comprometer-se novamente com os altos ideais da santidade, da fidelidade e do zelo pastoral&rdquo;.<\/p>\n<p>Bento XVI focou a &ldquo;excepcional experi&ecirc;ncia da universalidade da Igreja, a vastid&atilde;o da sua tradi&ccedil;&atilde;o intelectual e espiritual, a sua miss&atilde;o de levar a verdade salv&iacute;fica de Cristo a todos os espa&ccedil;os e a todos os lugares&rdquo; que o Col&eacute;gio, desde a sua funda&ccedil;&atilde;o, ofereceu aos seus estudantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bento XVI recordou viagem aos Estados Unidos da Am\u00e9rica<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[104,120,294],"class_list":["post-42897","post","type-post","status-publish","format-standard","hentry","category-vaticano","tag-america","tag-bento-xvi","tag-sacramentos"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/42897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=42897"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/42897\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=42897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=42897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=42897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}