{"id":422773,"date":"2026-04-27T17:15:22","date_gmt":"2026-04-27T16:15:22","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=422773"},"modified":"2026-05-19T15:22:39","modified_gmt":"2026-05-19T14:22:39","slug":"cep-prioridades-para-um-novo-mandato-com-o-tema-da-protecao-de-menores-na-agenda-sinodalidade-familia-e-o-papa-em-portugal","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/cep-prioridades-para-um-novo-mandato-com-o-tema-da-protecao-de-menores-na-agenda-sinodalidade-familia-e-o-papa-em-portugal\/","title":{"rendered":"CEP: Prioridades para um novo mandato, com o tema da prote\u00e7\u00e3o de menores na agenda, sinodalidade, fam\u00edlia e o Papa em Portugal"},"content":{"rendered":"<p style=\"font-weight: 400;\"><span style=\"font-size: 16px;\">D. Virg\u00edlio Antunes foi eleito presidente da Confer\u00eancia Episcopal Portuguesa, numa assembleia plen\u00e1ria que eleigeu mais de metade dos coordenadores dos v\u00e1rios setores da pastoral<\/span><\/p>\n<p style=\"font-weight: 400;\"><!--more--><\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_71873\"  width=\"480\" height=\"270\"  data-origwidth=\"480\" data-origheight=\"270\" src=\"https:\/\/www.youtube.com\/embed\/_RIB7pVqhec?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=pt&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p style=\"font-weight: 400;\"><em>Ag\u00eancia ECCLESIA &#8211; Disse na primeira mensagem ap\u00f3s a elei\u00e7\u00e3o como presidente da Confer\u00eancia Episcopal Portuguesa (CEP), e repetiu na confer\u00eancia de imprensa que n\u00e3o h\u00e1 dossiers fechados, enumerando uma s\u00e9rie deles, desde as quest\u00f5es fraturantes, dos abusos sexuais, a liturgia, a renova\u00e7\u00e3o da Igreja. A partir da forma como olha para a Igreja Cat\u00f3lica em Portugal, se tivesse de escolher um deles, por onde \u00e9 que come\u00e7aria?<\/em><\/p>\n<p>D. Virg\u00edlio Antunes &#8211; Na Igreja h\u00e1 uma hist\u00f3ria, muito longa. H\u00e1 uma hist\u00f3ria feliz, com alguns atropelos pelo meio, todos conhecemos, e que lamentamos, n\u00e3o gostar\u00edamos que fosse assim, mas a Hist\u00f3ria da Igreja \u00e9 toda voltada para a evangeliza\u00e7\u00e3o, para o an\u00fancio da Boa Nova de Jesus Cristo. Esse \u00e9 que \u00e9 o nosso foco central. Depois, a Igreja tem uma dimens\u00e3o social, tem as pessoas que fazem caminho, tamb\u00e9m tem as dificuldades que se v\u00e3o sentindo, tem os tempos da hist\u00f3ria, que v\u00e3o sendo diversos, n\u00e3o s\u00e3o todos iguais: desde o s\u00e9culo I d.C. at\u00e9 o s\u00e9culo XXI d.C. j\u00e1 se passou por muitos momentos grandes, tamb\u00e9m por muitas turbul\u00eancias. Aquilo que eu destaco como fundamental e que d\u00e1 o cont\u00ednuo \u00e0 hist\u00f3ria da Igreja \u00e9 o an\u00fancio do Evangelho, disso n\u00e3o h\u00e1 d\u00favida absolutamente nenhuma, porque esse \u00e9 o mandato e que tem vindo a ser renovado de um modo especial no s\u00e9culo XX e no s\u00e9culo XXI para a sociedade que n\u00f3s somos, para a humanidade que n\u00f3s somos e com os contornos que n\u00f3s conhecemos a partir, sobretudo, dos documentos pontif\u00edcios.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; H\u00e1 quest\u00f5es, h\u00e1 problemas que \u00e9 necess\u00e1rio resolver, caso contr\u00e1rio esse mandato essencial fica comprometido&#8230;<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Toda a gente sabe que nos \u00faltimos tempos, nos \u00faltimos anos, em Portugal e no mundo, aquilo que tem marcado de uma forma mais vis\u00edvel e medi\u00e1tica a agenda da Igreja e da sociedade \u00e9 a quest\u00e3o dos abusos e, portanto, \u00e9 aquilo que temos tido entre m\u00e3os, de uma forma mais direta, mais pr\u00f3xima, tamb\u00e9m mais decidida, mais empenhada e \u00e9 absolutamente incontorn\u00e1vel.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; H\u00e1 uma determina\u00e7\u00e3o muito firme por parte do episcopado da Igreja Cat\u00f3lica em Portugal de enfrentar o problema, de afirmar essa toler\u00e2ncia zero, mas n\u00e3o haver\u00e1 uma perce\u00e7\u00e3o adequada, ou pelo menos correspondente \u00e0 determina\u00e7\u00e3o da Igreja Cat\u00f3lica?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; As perce\u00e7\u00f5es s\u00e3o muito variadas, desde o interior da Igreja, que nem toda a gente v\u00ea exatamente da mesma forma o tratamento que tem sido dado a todas as quest\u00f5es, inclusivamente a esta, e depois por parte da sociedade. E na sociedade tamb\u00e9m h\u00e1 diversidade de perspetivas.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Mas a\u00ed, o papel da comunica\u00e7\u00e3o \u00e9 determinante?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; \u00c9 determinante, mas n\u00e3o \u00e9 o \u00fanico. \u00c0s vezes n\u00f3s pensamos que \u00e9 tudo comunica\u00e7\u00e3o. H\u00e1 factos, h\u00e1 acontecimentos, h\u00e1 realidades, h\u00e1 procedimentos, e depois tamb\u00e9m h\u00e1 a comunica\u00e7\u00e3o mais assertiva, menos assertiva, que traz mais informa\u00e7\u00e3o, menos informa\u00e7\u00e3o&#8230; E as pessoas, diante das quest\u00f5es mais prementes e que marcam muito a sua vida e aquilo que \u00e9 o sentido comunit\u00e1rio, de algum modo exigem, e ainda que exigem, que haja comunica\u00e7\u00e3o adequada. E isso acontece umas vezes mais, outras vezes menos.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Neste cap\u00edtulo em concreto, poderia ter sido diferente a comunica\u00e7\u00e3o das v\u00e1rias etapas do processo?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA \u2013 Eu tenho dificuldade de ver qual seria a outra forma de comunica\u00e7\u00e3o. N\u00f3s \u00e0s vezes pomo-nos neste papel: \u201co que seria se tivesse sido?\u201d. Mas, dado que \u00e9 uma quest\u00e3o t\u00e3o relevante, t\u00e3o dram\u00e1tica, mesmo com a melhora das comunica\u00e7\u00f5es, haveria sempre perce\u00e7\u00f5es diferentes da realidade, dos acontecimentos e da pr\u00f3pria comunica\u00e7\u00e3o. E, portanto, temos de aceitar que o mais importante s\u00e3o inclusivamente os acontecimentos, s\u00e3o os factos, e nesses \u00e9 que nos devemos debru\u00e7ar. E s\u00e3o as pessoas, sobre elas devemos dedicar toda a nossa aten\u00e7\u00e3o, o nosso cuidado.<\/p>\n<p style=\"font-weight: 400;\">\u00c0s vezes tenho dito que era muito dif\u00edcil a Igreja ou qualquer outra institui\u00e7\u00e3o ou entidade ou sociedade sair-se sempre bem no meio de uma quest\u00e3o como esta.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Vamos voltar a este tema dos abusos&#8230; Mas este tema da comunica\u00e7\u00e3o na Igreja Cat\u00f3lica: nos tempos de hoje, e diante da prioridade de evangeliza\u00e7\u00e3o que falou, o p\u00falpito hoje n\u00e3o s\u00e3o os meios de comunica\u00e7\u00e3o social?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; H\u00e1 muitos p\u00falpitos, n\u00e3o h\u00e1 um \u00fanico p\u00falpito. \u00c9 evidente que h\u00e1 uma comunica\u00e7\u00e3o interna, para dentro da pr\u00f3pria igreja e que tem, sobretudo, grande lugar ao domingo, na homilia da missa e outras informa\u00e7\u00f5es, tem a catequese, tem os momentos de evangeliza\u00e7\u00e3o expl\u00edcitos ou impl\u00edcitos, e tem, com certeza, os meios de comunica\u00e7\u00e3o, a que a Igreja tem vindo a dar muita aten\u00e7\u00e3o, praticamente h\u00e1 um s\u00e9culo para c\u00e1. Mas, nos dias de hoje, com o desenvolvimento r\u00e1pido que temos vindo a ter no que diz respeito aos meios de comunica\u00e7\u00e3o, \u00e0s formas de comunica\u00e7\u00e3o e \u00e0 comunica\u00e7\u00e3o universal e global, o assunto \u00e9 evidentemente mais premente. E, nesse aspeto, penso que a Igreja, tanto a Igreja de Roma, que tem uma m\u00e1quina de comunica\u00e7\u00e3o, que tem muitos meios, tem muitas pessoas e tem um programa bem definido, at\u00e9 h\u00e1 comunica\u00e7\u00e3o dentro de cada um dos pa\u00edses, onde existem as dioceses&#8230; Nas pr\u00f3prias dioceses, tem-se vindo a fazer caminho, \u00e0s vezes com dificuldades pela falta de meios e de recursos e de pessoas. Nem sempre n\u00f3s temos conseguido fazer a comunica\u00e7\u00e3o que nos pede a pr\u00f3pria Igreja e que foi real\u00e7ada, de uma forma muito especial, no \u00faltimo s\u00ednodo sobre sinodalidade, comunh\u00e3o, participa\u00e7\u00e3o e miss\u00e3o, ao dizer que a Igreja tem de estar nos diferentes f\u00f3runs onde se faz comunica\u00e7\u00e3o, seja do ponto de vista da informa\u00e7\u00e3o, seja do ponto de vista da forma\u00e7\u00e3o e a tal finalidade primeira e \u00faltima que \u00e9 o an\u00fancio.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; N\u00e3o referiu a comunica\u00e7\u00e3o na Confer\u00eancia Episcopal, tamb\u00e9m \u00e9 necess\u00e1rio? <\/em><\/p>\n<p style=\"font-weight: 400;\">VA \u2013 Evidentemente. A Confer\u00eancia Episcopal tamb\u00e9m tem de ter, e tem procurado, alguns meios, que no passado n\u00e3o existiam, para fazer comunica\u00e7\u00e3o. N\u00f3s hoje estamos muito melhor do ponto de vista comunicacional na pr\u00f3pria Confer\u00eancia Episcopal do que est\u00e1vamos noutras d\u00e9cadas mais para tr\u00e1s.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; \u00c9 fundamental que a Igreja Cat\u00f3lica em Portugal possa dialogar com a sociedade, com os outros interlocutores da sociedade a uma voz e tenha na Confer\u00eancia Episcopal essa voz?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; \u00c9 muito importante que a Igreja tenha uma voz, mas \u00e9 naquilo que s\u00e3o os aspetos fundamentais da vida da pr\u00f3pria Igreja. Depois, cada pessoa, cada comunidade, cada diocese, cada institui\u00e7\u00e3o tem a sua liberdade, felizmente estamos no tempo da liberdade de comunica\u00e7\u00e3o. E na Igreja tamb\u00e9m existe: as pessoas podem pensar, podem raciocinar, podem dizer, podem informar&#8230; Naturalmente h\u00e1 um conjunto de par\u00e2metros, mas o \u00faltimo reduto, por assim dizer, seria aquilo que \u00e9 a ortodoxia da f\u00e9, e a\u00ed n\u00e3o devemos tocar, n\u00e3o podemos tocar, mas no que diz respeito \u00e0 vida, aos procedimentos, \u00e0s realidades de cada dia, tem que haver pluralidade de informa\u00e7\u00e3o e de comunica\u00e7\u00e3o.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; A quest\u00e3o ser\u00e1 mais da comunica\u00e7\u00e3o para o exterior, por parte da Igreja Cat\u00f3lica: que o exterior encontre uma refer\u00eancia por parte da Igreja Cat\u00f3lica&#8230;<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; As pessoas \u00e0s vezes ficam perturbadas se ouvem dizer num lugar uma coisa e no outro lugar o seu contr\u00e1rio. Em todas as mat\u00e9rias! Mesmo em mat\u00e9ria de f\u00e9, em mat\u00e9ria de costumes, em qualquer setor. E, portanto, tem de haver alguns par\u00e2metros fundamentais. No caso da Confer\u00eancia Episcopal Portuguesa, que \u00e9 uma confer\u00eancia episcopal, n\u00e3o pura e simplesmente a soma de um conjunto de bispos, embora os bispos, cada um com a sua individualidade, de representantes das suas comunidades, temos de tender para a comunica\u00e7\u00e3o a uma voz, mesmo admitindo a pluralidade de perspetivas.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Ainda sobre esta elei\u00e7\u00e3o, na \u00faltima Assembleia Plen\u00e1ria, mais de metade das comiss\u00f5es episcopais foram renovadas, muitas delas com bispos de idade jovem. Que expectativa t\u00eam para o dinamismo nesses v\u00e1rios setores e, claro, tamb\u00e9m nos outros, onde permanecem os coordenadores dessas comiss\u00f5es?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Quando entr\u00e1mos nesta \u00faltima Assembleia da Confer\u00eancia Episcopal, vimos um panorama muito diferente de outras Assembleias Plen\u00e1rias da Confer\u00eancia.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Houve uma renova\u00e7\u00e3o da Episcopal?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Houve, evidentemente. Nos \u00faltimos anos foram nomeados bastantes bispos, alguns bispos diocesanos, um grupo bastante grande de bispos auxiliares e que trazem, inclusivamente, uma forma\u00e7\u00e3o teol\u00f3gica diferente dos mais velhos, trazem uma inser\u00e7\u00e3o na sociedade tamb\u00e9m diferente, um modo de ver a Igreja tamb\u00e9m diferente, respeitando, com certeza, aquilo que \u00e9 a unidade de todos. H\u00e1 sangue novo, h\u00e1 ideias novas, h\u00e1 perspetivas novas, h\u00e1 sensibilidades novas. O facto de, para as comiss\u00f5es episcopais, terem sido eleitos bispos mais novos, alguns at\u00e9 de muito recente nomea\u00e7\u00e3o, s\u00f3 pode trazer aquela novidade do Esp\u00edrito Santo, quer que exista na Igreja de hoje.<\/p>\n<figure id=\"attachment_422296\" aria-describedby=\"caption-attachment-422296\" style=\"width: 400px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-422296\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2.jpg 1500w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-422296\" class=\"wp-caption-text\">Foto: Ag\u00eancia ECCLEISA\/TAM<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\"><strong>Prote\u00e7\u00e3o de menores<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Retomemos o tema dos agudos sexuais. Est\u00e1 em cima da mesa o modelo que vai continuar, ap\u00f3s o mandato do Grupo Vita. Defende a continuidade de um grupo externo \u00e0 Igreja Cat\u00f3lica para acompanhar estes casos?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; A Igreja, ao longo destes anos, foi ensaiando um caminho. Era um caminho que n\u00f3s desconhec\u00edamos, t\u00ednhamos algumas ideias bem definidas e bem determinadas, de acordo com as indica\u00e7\u00f5es da Santa S\u00e9, atrav\u00e9s dos diferentes documentos que foram sendo publicados, particularmente pelo Papa Francisco e agora refor\u00e7ado o seu valor e a sua import\u00e2ncia pelo Papa Le\u00e3o XIV. H\u00e1 um conjunto de indica\u00e7\u00f5es bem claras! E n\u00f3s, os bispos portugueses, aceit\u00e1mos desde o primeiro momento que era para levar por diante todas as indica\u00e7\u00f5es que a Igreja de Roma, o Santo Padre, os dicast\u00e9rios e a comiss\u00e3o da tutela dos menores nos iam indicando. Essa determina\u00e7\u00e3o \u00e9 clara, est\u00e1 bem definida, ningu\u00e9m, com certeza, pensou nem pensa afastar-se da\u00ed.<\/p>\n<p style=\"font-weight: 400;\">O caminho que fomos trilhando foi o nosso caminho. Tamb\u00e9m conhecemos aquilo que se passou noutras Igrejas, noutros pa\u00edses do mundo, praticamente tudo diverso, porque os pa\u00edses s\u00e3o diferentes, porque as dioceses s\u00e3o diferentes&#8230; Mas, tamb\u00e9m eles e n\u00f3s, procur\u00e1mos respeitar as mesmas indica\u00e7\u00f5es fundamentais. \u00c9 um caminho que n\u00e3o conhec\u00edamos, t\u00ednhamos esta determina\u00e7\u00e3o!<\/p>\n<p style=\"font-weight: 400;\">Toda a gente conhece o caminho que foi feito na Igreja em Portugal: uma comiss\u00e3o independente para que se conhecesse a realidade sem qualquer tipo de interfer\u00eancia, fosse de quem fosse, independente na totalidade dos seus objetivos e do seu modo de trabalhar, como eles sempre aceitaram e reconheceram, e estamos muito gratos. De outra forma n\u00e3o ter\u00edamos uma perce\u00e7\u00e3o desta realidade t\u00e3o nua, t\u00e3o crua e t\u00e3o real como agora temos. Depois houve aquele momento, podemos dizer cr\u00edtico, da abertura dos arquivos, que nos levou a pedir \u00e0 Santa S\u00e9 que nos autorizasse a abrir os arquivos das dioceses. E os arquivos foram abertos, as pessoas puderam fazer a investiga\u00e7\u00e3o, dif\u00edcil de fazer, reconhe\u00e7amos, mas fizeram com a seu profissionalismo, uma vez que eram profissionais.<\/p>\n<p style=\"font-weight: 400;\">Depois houve a quest\u00e3o da conclus\u00e3o desse processo e a nomea\u00e7\u00e3o do Grupo Vita porque se achava que n\u00e3o est\u00e1vamos ainda em condi\u00e7\u00f5es para levar por diante este trabalho s\u00f3 enquanto Igreja, precis\u00e1vamos de outras entidades, de outra entidade concretamente, para ouvir, para dar um rosto, em que as pessoas confiassem&#8230; E isso tem vindo a acontecer com o Grupo Vita.<\/p>\n<p style=\"font-weight: 400;\">Houve outro momento muito importante, ali\u00e1s correspondendo \u00e0s indica\u00e7\u00f5es da Santa S\u00e9, que foi a nomea\u00e7\u00e3o das comiss\u00f5es diocesanas para a prote\u00e7\u00e3o de menores e adultos vulner\u00e1veis, que se criaram em todas as dioceses, com profissionais, sem a participa\u00e7\u00e3o ativa dos membros do clero, como foi ali\u00e1s pedido, para que pudesse haver uma abertura, uma isen\u00e7\u00e3o, para refor\u00e7ar a confian\u00e7a de todas as v\u00edtimas que quisessem dar a conhecer a sua hist\u00f3ria.<\/p>\n<p style=\"font-weight: 400;\">E depois cheg\u00e1mos a este momento das compensa\u00e7\u00f5es, que \u00e9 um projeto grande, um projeto arrojado, um projeto bem compreendido por uns, por outros mal compreendido.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; <\/em><em>Um projeto necess\u00e1rio na sua opini\u00e3o?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Um projeto absolutamente necess\u00e1rio! Porque uma coisa s\u00e3o palavras, \u00e9 o reconhecimento p\u00fablico ou privado, pessoal, no di\u00e1logo com as pessoas, e outra coisa \u00e9 dar-se um com algo que custa \u00e0 pr\u00f3pria Igreja, que \u00e9 o desembolsar alguns quantitativos, alguns montantes, para manifestar \u00e0s pessoas que isto n\u00e3o s\u00e3o s\u00f3 palavras, isto \u00e9 uma atitude determinada que n\u00f3s queremos levar por diante, enquanto Igreja, tendo em conta o sofrimento que essas mesmas pessoas viveram em primeira pessoa e que, em alguns casos, se arrastou por muitos anos, at\u00e9 ao momento da coragem de falar.<\/p>\n<p style=\"font-weight: 400;\"><em>AE \u2013 <\/em><em>Sobre as <\/em><em>compensa\u00e7\u00f5es, \u00e9 p\u00fablico que 50% \u00e9 suportado pela Confer\u00eancia Episcopal, o restante entre as CIRP e as dioceses. Cada cat\u00f3lico vai sentir tamb\u00e9m que est\u00e1 a contribuir para este fundo?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; N\u00f3s nunca pens\u00e1mos em fazer nenhum ofert\u00f3rio, nem nenhum pedit\u00f3rio. V\u00e3o ser os fundos de cada uma das dioceses que vai ter que retirar de outras verbas, que teriam outros destinos, para prover esse fundo com esses 50% atribu\u00eddos \u00e0s dioceses e \u00e0 CIRP e \u00e0 CNISP, completado com o fundo da Confer\u00eancia Episcopal. Agora, \u00e9 o dinheiro dos fi\u00e9is, porque a Igreja em Portugal n\u00e3o tem outras fontes de financiamento que n\u00e3o o dinheiro dos fi\u00e9is e alguns pequenos rendimentos de algumas obras que realizam.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; \u00c9 a hist\u00f3ria de todo este processo, at\u00e9 esta fase&#8230; Agora, daqui por diante, seja em novos casos que possam aparecer, seja em rela\u00e7\u00e3o ao Grupo Vita. Defende esse modelo de grupo externo \u00e0 Igreja Cat\u00f3lica?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Como dissemos na \u00faltima Assembleia Plen\u00e1ria ou na confer\u00eancia de imprensa, vamos reunir-nos com as comiss\u00f5es diocesanas e com o Grupo Vita para definirmos exatamente o modelo que devemos seguir nos tempos futuros, porque achamos que \u00e9 muit\u00edssimo importante dar o lugar que devem ter as comiss\u00f5es diocesanas, que s\u00e3o um \u00f3rg\u00e3o existente em cada uma das dioceses e que nos foi pedido pela Santa S\u00e9. N\u00e3o significa que n\u00e3o haja outras pessoas, outras pessoas que n\u00e3o pertencem \u00e0s comiss\u00f5es diocesanas, que que n\u00e3o sejam chamadas a dar o seu apoio. Mas \u00e9 uma realidade que procuraremos definir mais concretamente quando nos encontrarmos com as comiss\u00f5es e com o Grupo Vita.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; N\u00e3o se defende um outro grupo? Defende que as comiss\u00f5es diocesanas seriam a inst\u00e2ncia onde dar continuidade?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; O caminho futuro vai ser esse, porque a Igreja tem de cuidar das v\u00edtimas da pr\u00f3pria Igreja.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Mas n\u00e3o ser\u00e1 necess\u00e1rio algu\u00e9m externo que possa catalisar a confian\u00e7a de todos?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Eu n\u00e3o sei o que vai acontecer. Mas, um outro grupo com uma identidade semelhante, uma terceira comiss\u00e3o, n\u00e3o sei se ir\u00e1 existir. Agora, outras pessoas que n\u00e3o est\u00e3o envolvidas nas atividades da Igreja e que n\u00e3o s\u00e3o, por assim dizer, das fileiras da Igreja, embora, tanto nestes grupos todos havia gente de identidade crist\u00e3, de identidade cat\u00f3lica, gente de boa vontade e profissionais&#8230;Mas n\u00f3s tamb\u00e9m temos profissionais nas comiss\u00f5es diocesanas, temos psic\u00f3logos, temos pedopsiquiatras, temos juristas, temos ju\u00edzes, temos pessoas que trabalham nas For\u00e7as de Seguran\u00e7a. Esse tipo de profissionais acaba por estar presente em todas as institui\u00e7\u00f5es que foram sendo criadas, Grupo Vita e comiss\u00f5es diocesanas. Mas veremos como \u00e9 que vai ser a evolu\u00e7\u00e3o nos pr\u00f3ximos tempos.<\/p>\n<p style=\"font-weight: 400;\"><strong>Sinodalidade: \u201cEst\u00e1 nas vossas m\u00e3os\u201d<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; No encontro de janeiro das equipas sinodais, numa confer\u00eancia que fez, disse \u201cest\u00e1 nas vossas m\u00e3os\u201d, dirigindo-se precisamente a quem l\u00e1 estava, a dezenas ou centenas de participantes. Quer isto dizer que a ideia est\u00e1 transmitida? \u00c9 a concretiza\u00e7\u00e3o que agora est\u00e1 em causa?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Tive uma grande gra\u00e7a que foi participar no s\u00ednodo, sobre sinodalidade.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Nas duas assembleias em Roma&#8230;<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Nas duas assembleias, no m\u00eas de outubro. Foi uma grande gra\u00e7a, foi uma experi\u00eancia \u00fanica na vida de um bispo, ou na vida de qualquer crist\u00e3o, uma vez que naquela assembleia estavam bispos, estavam presb\u00edteros, di\u00e1conos, consagrados, leigos, portanto, era uma assembleia plural de todo o mundo. E esta troca de experi\u00eancias foi uma aut\u00eantica maravilha. Agora, o trabalho est\u00e1 feito, a mensagem est\u00e1 passada? \u00c9 evidente que n\u00e3o! Est\u00e1 em parte, mas esta mudan\u00e7a\u2026<\/p>\n<p style=\"font-weight: 400;\">H\u00e1 muit\u00edssimo trabalho feito, h\u00e1 muit\u00edssimas pessoas que est\u00e3o convertidas a esta Igreja sinodal e da sinodalidade, que veem, como o Papa disse, o caminho da Igreja no futuro, e h\u00e1 pessoas que ainda podem estar um pouco reticentes. Isso \u00e9 razo\u00e1vel, \u00e9 normal, porque n\u00e3o apanhamos todos ao mesmo tempo e n\u00e3o temos todos tamb\u00e9m a informa\u00e7\u00e3o ao mesmo tempo, ou as condi\u00e7\u00f5es para fazer o caminho ao mesmo tempo.<\/p>\n<p style=\"font-weight: 400;\">Em Portugal, h\u00e1 uma atitude de abertura fabulosa. Nas duas assembleias que realiz\u00e1mos, por iniciativa da Confer\u00eancia Episcopal, em F\u00e1tima, onde participaram membros de todas as dioceses, dos conselhos pastorais diocesanos e das comiss\u00f5es sinodais, via-se n\u00e3o s\u00f3 uma abertura, mas uma alegria, inclusivamente, muito grande\u2026<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; De compromisso com esta forma de ser igreja?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; De compromisso com esta ideia de ser Igreja, esta forma e com a sinodalidade. E nas dioceses todos temos acompanhado, tanto ao n\u00edvel diocesano, das estruturas diocesanas, como ao n\u00edvel das par\u00f3quias, das unidades pastorais, dos movimentos, um gosto grande das pessoas poderem manifestar o seu modo de ver, o seu modo de pensar, de serem escutadas, de poderem ter a sua palavra e de se envolverem na edifica\u00e7\u00e3o da Igreja. \u00c9 um caminho feito. N\u00e3o podemos concluir que o trabalho est\u00e1 realizado, que agora \u00e9 s\u00f3 esperar os frutos.<\/p>\n<p style=\"font-weight: 400;\">\u201cEst\u00e1 nas nossas m\u00e3os\u201d, era o que queria dizer nessa confer\u00eancia que tinha por t\u00edtulo \u201cA espiritualidade sinodal\u201d, para que n\u00e3o nos esque\u00e7amos que isto da sinodalidade n\u00e3o \u00e9 uma t\u00e9cnica, n\u00e3o \u00e9 uma t\u00e1tica, n\u00e3o \u00e9 uma estrutura, mas \u00e9 sobretudo um esp\u00edrito que se absorve, que se desenvolve e que nos leva a queremos ser Igreja tal como est\u00e1 a ser definida na sua concretiza\u00e7\u00e3o real nos nossos dias.<\/p>\n<p style=\"font-weight: 400;\"><strong>Sinodalidade na Diocese de Coimbra<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>AE \u2013 Podemos tomar por exemplo aqui a Diocese de Coimbra, onde desde cedo o D. Virg\u00edlio tentou implementar este esp\u00edrito sinodal na pastoral. Acredito que em muitas regi\u00f5es as estruturas estejam constitu\u00eddas, os conselhos pastorais estejam constitu\u00eddos, com a presen\u00e7a de leigos, jovens&#8230;<\/em> <em>A forma de trabalhar, para al\u00e9m das estruturas, a forma de ser Igreja j\u00e1 \u00e9, de facto, sinodal?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Em muitos aspetos j\u00e1 mudou. Concretamente, alguns desses aspetos que manifestam a exist\u00eancia dos conselhos pastorais, das unidades pastorais ou das dioceses e das par\u00f3quias, nalguns casos existiam, outros n\u00e3o existiam e \u00e0s vezes existiam um pouco adormecidos. Est\u00e3o todos a ser revitalizados e as dioceses est\u00e3o todas a fazer um esfor\u00e7o grande para que se levem por diante. Depois as equipas pastorais ou as equipas de anima\u00e7\u00e3o pastoral em cada par\u00f3quia, em cada unidade pastoral. Na Diocese de Coimbra est\u00e3o praticamente constitu\u00eddas em todas as unidades pastorais e tenho estado a fazer a visita a cada uma delas ao longo deste ano. E existem!<\/p>\n<p style=\"font-weight: 400;\">O pr\u00f3prio modo de exercer o minist\u00e9rio sacerdotal, que estava quase exclusivamente centrado na figura do padre, que pensava, que refletia, que decidia, que rezava e que ouvia tamb\u00e9m, com certeza, hoje tem \u00e0 sua volta um grupo de pessoas, de leigos ou de outros sacerdotes ou de di\u00e1conos, que refletem juntos, que rezam juntos e que programam juntos e que v\u00e3o definindo os passos a dar em cada um destes lugares, por cada uma destas comunidades em conjunto, liderados naturalmente pelo p\u00e1roco, que tem sempre essa responsabilidade de ser pastor.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; E na sua an\u00e1lise, o que poderia ser o negativo de uma pastoral n\u00e3o sinodal, que era um esp\u00edrito clerical, uma l\u00f3gica de poder, n\u00e3o reveste estas estruturas, nas unidades pastorais?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; N\u00e3o, as unidades pastorais ajudam a ultrapassar. \u00c0s vezes, quando se fala de l\u00f3gica de poder, n\u00e3o significa que fosse uma l\u00f3gica de poder pelo poder, nem que as pessoas quisessem o poder pelo poder. Era assim, era o modo como n\u00f3s v\u00ednhamos.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Era sempre a mesma pessoa que decidia?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Mas era o modo como v\u00ednhamos a ser igreja. Nem nos question\u00e1vamos muito&#8230; As pessoas aceitavam tranquilamente que era assim. E hoje, as pessoas j\u00e1 perceberam, o povo de Deus j\u00e1 percebeu que tem um lugar ativo e que tem n\u00e3o s\u00f3 o dever, mas tamb\u00e9m tem o direito de participar ativamente na edifica\u00e7\u00e3o da sua comunidade.<\/p>\n<p style=\"font-weight: 400;\">E isso transforma o pr\u00f3prio modo de as pessoas se relacionarem. Este cap\u00edtulo das rela\u00e7\u00f5es, que \u00e9 t\u00e3o importante na sociedade, entre n\u00f3s e tamb\u00e9m dentro da igreja, das rela\u00e7\u00f5es com os sacerdotes, com os pastores e tamb\u00e9m das rela\u00e7\u00f5es entre os pr\u00f3prios leigos, dentro das comunidades, um cap\u00edtulo a desenvolver.<\/p>\n<figure id=\"attachment_422297\" aria-describedby=\"caption-attachment-422297\" style=\"width: 400px\" class=\"wp-caption alignright\"><img decoding=\"async\" class=\"size-medium wp-image-422297\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra1-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra1-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra1-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra1-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra1-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra1.jpg 1500w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-422297\" class=\"wp-caption-text\">Foto: Ag\u00eancia ECCLEISA\/TAM<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\"><strong>Consist\u00f3rio em junho<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Vejamos ainda dois aspetos, sobretudo relacionados com a Igreja Universal e com o prop\u00f3sito do Papa Le\u00e3o XIV, a partir de duas refer\u00eancias. A primeira, de convocar um consist\u00f3rio para junho. Foi uma metodologia que o Papa Le\u00e3o desde cedo comunicou, consist\u00f3rios anuais para convocar os cardeais, sendo este pr\u00f3ximo de junho para olhar o tema de evangeliza\u00e7\u00e3o e a partir do documento do Papa Francisco \u201cA alegria do Evangelho\u201d. O que \u00e9 que diz esta decis\u00e3o do Papa Le\u00e3o, n\u00e3o s\u00f3 da atualidade do pontificado do Papa Francisco, mas da afirma\u00e7\u00e3o da continuidade?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; \u00c9 uma atitude plenamente sinodal, em conformidade com o esp\u00edrito sinodal. O Papa Francisco tinha ensaiado j\u00e1 aquele grupo de cardeais que o assessorava na reflex\u00e3o. Agora o Papa Le\u00e3o, que tamb\u00e9m esteve no s\u00ednodo e que, portanto, est\u00e1 imbu\u00eddo do mesmo esp\u00edrito, da mesma vis\u00e3o da Igreja, alargou, e alargou de uma forma que eu acho que \u00e9 muit\u00edssimo mais produtiva, que envolve muito mais pessoas. \u00c9 uma bel\u00edssima ideia para dar continuidade a tudo isto que est\u00e1 entre m\u00e3os, na Igreja nos dias de hoje.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; A permanecer essa marca da proximidade da Igreja, ao estilo do Papa Francisco?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA \u2013 Permanece! Ainda agora: tudo aquilo que vimos na viagem pastoral do Papa Le\u00e3o XIV \u00e0 \u00c1frica, n\u00f3s ficamos admirados com \u00e0-vontade, com a proximidade, com o encontro, numa pessoa que ainda n\u00e3o est\u00e1, por assim dizer, rodada nesta forma de ser Papa. Um ano n\u00e3o \u00e9 muito tempo para aquilo que \u00e9 a responsabilidade e para aquilo que \u00e9 a evolu\u00e7\u00e3o da pr\u00f3pria pessoa, que vem de outros servi\u00e7os, que vem de outros contextos. Ele tem-no dito&#8230; Ainda ontem, a prop\u00f3sito do primeiro anivers\u00e1rio da morte do Papa Francisco, todos gost\u00e1mos de ouvir aquela relev\u00e2ncia que ele p\u00f4s \u00e0 figura do Papa Francisco, \u00e0 doa\u00e7\u00e3o da sua vida, \u00e0 sua entrega, ao servi\u00e7o da igreja.<\/p>\n<p style=\"font-weight: 400;\"><strong>Fam\u00edlia: A Igreja n\u00e3o se pode isolar na norma<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Uma outra decis\u00e3o do Papa Le\u00e3o XIV foi convocar os presidentes das confer\u00eancias episcopais para uma reuni\u00e3o, em outubro, sobre a exorta\u00e7\u00e3o apost\u00f3lica p\u00f3s-sinodal \u201cAmoris Laetitia\u201d, um documento sobre a pastoral familiar, publicado h\u00e1 10 anos. De que forma \u00e9 necess\u00e1rio revisitar o documento? Em 10 anos, a transforma\u00e7\u00e3o neste tema da pastoral familiar foi ainda maior, na sua opini\u00e3o, e criou-se um estilo de pastoral \u201cpositiva e acolhedora\u201d, como queria o Papa Francisco?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Eu n\u00e3o pensava que fosse participar&#8230; Neste caso, em princ\u00edpio, estarei l\u00e1!<\/p>\n<p style=\"font-weight: 400;\">\u00c9 um documento, como todos os outros documentos que se referem \u00e0 quest\u00e3o da fam\u00edlia, que implica sempre um conjunto de aspetos de car\u00e1cter \u00e9tico, tem a ver com a sociedade atual, tem a ver com as transforma\u00e7\u00f5es&#8230; \u00c9 sempre um documento pol\u00e9mico, bem aceite por uns, menos aceito por outros, porque parece que vem p\u00f4r em crise algumas daquelas ideias fundamentais para algumas pessoas, mas a Igreja n\u00e3o pode ficar parada, nem fechada, \u00e0quilo que \u00e9 a realidade que se passa no nosso mundo.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; N\u00e3o se pode isolar na norma&#8230;<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; N\u00e3o se pode isolar na norma&#8230; Foi isso que o Papa Francisco quis dizer quando, em vez da Pastoral da Fam\u00edlia, come\u00e7ou a falar nas fam\u00edlias. E as fam\u00edlias t\u00eam alegrias muito grandes e t\u00eam desafios, mas tamb\u00e9m t\u00eam dificuldades, t\u00eam transtornos&#8230; E a Igreja n\u00e3o pode deixar de estar atenta \u00e0quilo que s\u00e3o as fam\u00edlias, nos dias de hoje, para lhes anunciar o Evangelho, para lhes ajudar a crescer, do ponto de vista \u00e9tico e moral e para abrir horizontes, mas com as fam\u00edlias. N\u00e3o pode ser, simplesmente, do alto da norma que se realize esta transforma\u00e7\u00e3o interior de uma sociedade.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; D. Virg\u00edlio \u00e9 biblista, investigou as ci\u00eancias b\u00edblicas. E este acolhimento de todas as pessoas, na sua hist\u00f3ria, nas suas circunst\u00e2ncias, na sua fragilidade, aproxima a Igreja das origens?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Hoje, essa palavra est\u00e1 em cima da mesa: a palavra escuta e a palavra acolhimento. Penso que ningu\u00e9m duvida que toda a pessoa, independentemente da sua hist\u00f3ria, que, mais de acordo com os padr\u00f5es e com as normas ou menos de acordo, tem o direito de ser acolhida pela Igreja porque \u00e9 acolhida pelo pr\u00f3prio Deus, por meio de Jesus Cristo e \u00e9 o que lemos nas p\u00e1ginas do Evangelho.<\/p>\n<p style=\"font-weight: 400;\">N\u00e3o significa que seja para concordar com tudo, que tudo esteja bem, que haja um vazio da norma ou um vazio \u00e9tico, mas as pessoas s\u00e3o, para l\u00e1 de todas essas circunst\u00e2ncias da sua vida. E hoje, as par\u00f3quias, as comunidades t\u00eam uma atitude de abertura, de acolhimento e de escuta que \u00e9 um ensaio muito positivo em rela\u00e7\u00e3o a tudo isto e, concretamente, em rela\u00e7\u00e3o \u00e0s fam\u00edlias que aparecem para o batismo, para o matrim\u00f3nio, para levar as crian\u00e7as \u00e0 catequese. Precisamos de ir ao seu encontro para que elas, de facto, sintam o apelo de Deus por meio da Igreja. Hoje estamos todos vocacionados para acolher e para integrar as pessoas.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; O que \u00e9 que espera desse encontro em Outubro?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Espero que seja um encontro, para j\u00e1, positivo&#8230; O Papa disse que era para tentarmos desenvolver, p\u00f4r em pr\u00e1tica, dar continuidade ao belo documento que \u00e9 a \u201cAmoris Laetitia\u201d. Tamb\u00e9m haver\u00e1 vozes em sentidos diversos, mas para isso \u00e9 que as pessoas se encontram, para isso \u00e9 que as pessoas partilham as experi\u00eancias e as realidades vividas em cada um dos pa\u00edses, para isso \u00e9 que se v\u00e3o p\u00f4r em comum os caminhos j\u00e1 percorridos e estamos sempre dispon\u00edveis para continuar a acolher as pessoas, propondo a novidade do Evangelho, porque n\u00f3s temos sempre a obriga\u00e7\u00e3o de propor aquilo que \u00e9 a novidade do Evangelho, que \u00e9 o encontro com Cristo e tamb\u00e9m a organiza\u00e7\u00e3o da pr\u00f3pria vida.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Por vezes a Igreja \u00e9 acusada de quase impedir o acesso a essa novidade do Evangelho, fechando-se na norma, fechando-se na estrutura&#8230;<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; A norma \u00e9 necess\u00e1ria, a norma existe, o Direito Can\u00f3nico tamb\u00e9m est\u00e1 publicado e \u00e9 para se p\u00f4r em pr\u00e1tica, \u00e9 para se cumprir, mas o Evangelho ainda est\u00e1 antes da norma.<\/p>\n<p style=\"font-weight: 400;\"><strong>Polariza\u00e7\u00f5es pol\u00edticas<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Podemos olhar agora um pouco a sociedade portuguesa nas suas diferentes express\u00f5es e nos seus diferentes setores. Perguntava-lhe como \u00e9 que analisa a tend\u00eancia da constru\u00e7\u00e3o democr\u00e1tica em Portugal?<\/em> <em>Nos \u00faltimos seis anos, o p\u00eandulo talvez tenha passado da esquerda para a direita, ou tocado os extremos, tanto a esquerda como agora a direita&#8230;<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Os p\u00eandulos s\u00e3o mesmo assim, e ao longo da hist\u00f3ria\u2026<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; <\/em><em>Mas \u00e9 desej\u00e1vel que seja assim?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Seja desej\u00e1vel ou n\u00e3o, \u00e9 a realidade. N\u00e3o nos adianta nada discutirmos se \u00e9 desej\u00e1vel ou se n\u00e3o \u00e9 desej\u00e1vel, mas \u00e9 a realidade. O p\u00eandulo j\u00e1 caminhou muito para um lado, porventura ficou ao centro, hoje diz-se que caminhou para o outro lado. Desde que as pessoas todas estejam determinadas a viver num ambiente de respeito pelos outros e tamb\u00e9m por aquilo que \u00e9 uma conquista das sociedades modernas num regime democr\u00e1tico, e essa \u00e9 uma palavra essencial que todos aceitamos&#8230;<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Acha que todos aceitam essa palavra?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Eu pensava que sim&#8230; Depois cada um entende \u00e0s vezes a democracia \u00e0 sua maneira, mas a democracia tem na base o respeito entre as pessoas e a capacidade de ouvir os outros e inclusivamente, no que diz respeito \u00e0s quest\u00f5es pol\u00edticas, o desejo das maiorias. \u00c9 assim que \u00e9 constitu\u00edda a democracia, como algu\u00e9m diz, o melhor dos regimes que n\u00f3s temos sido capazes de edificar. Temos de viver com a realidade que temos.<\/p>\n<p style=\"font-weight: 400;\">Nos dias de hoje, tanto na Igreja como nas sociedades, o p\u00eandulo tem oscilado, evidentemente, mas isso faz parte dos processos hist\u00f3ricos.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Como \u00e9 que reage quando v\u00ea a apropria\u00e7\u00e3o do discurso religioso, at\u00e9 evang\u00e9lico, para as express\u00f5es de natureza pol\u00edtica e, sobretudo, quando est\u00e3o em causa atitudes xen\u00f3fobas e racistas?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; A Igreja n\u00e3o tem partido e o Papa Le\u00e3o, ainda muito recentemente, em algumas pol\u00e9micas que t\u00eam surgido, tem dito concretamente que o aproveitamento da matriz crist\u00e3 ou das perspetivas do evangelho para defender esta ou aquela causa pol\u00edtica \u00e9 um perigo muit\u00edssimo grande. Melhor ser\u00e1 que as pessoas sejam capazes, por meio da reflex\u00e3o, por meio do estudo da vida das sociedades, porventura inspirados pelo Evangelho, todos podemos ser inspirados do Evangelho, tanto \u00e0 esquerda como \u00e0 direita como ao centro, o Evangelho pode e quer inspirar a todos, mas os aproveitamentos para fins eleitoralistas ou para fazer o argumento mais forte a favor de algumas causas sobre as quais n\u00e3o h\u00e1 consensos&#8230; Mas h\u00e1 causas que s\u00e3o universais e a Doutrina Social da Igreja tem algumas causas que considera essenciais e o respeito pela pessoa humana e pelo migrante e pelos que trabalham e pelas fam\u00edlias e pela vida, s\u00e3o quest\u00f5es das quais a Igreja n\u00e3o pode prescindir, inclusive tem o dever de o manifestar, independentemente de serem defendidas mais \u00e0 direita, mais \u00e0 esquerda ou seja por quem for. A agenda da Igreja \u00e9 esta defesa da pessoa humana, da sua igual dignidade e o discurso pol\u00edtico n\u00e3o deve entrar no meu discurso, no nosso discurso, mas por parte dos partidos tamb\u00e9m n\u00e3o deve haver um discurso religioso a tentar conquistar mais adeptos para a sua causa.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Quando existe a Igreja Cat\u00f3lica, as suas lideran\u00e7as devem denunci\u00e1-la?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; \u00c9 o que tem acontecido, ao mais alto n\u00edvel! N\u00e3o vamos meter-nos em guerras pol\u00edticas com ningu\u00e9m, porque isso n\u00e3o faz parte da nossa miss\u00e3o, nem do nosso modo de ser, nem de estar no mundo. A afirma\u00e7\u00e3o dos princ\u00edpios, essa temos de continuar a faz\u00ea-la. Na B\u00edblia chamava-se o dinamismo prof\u00e9tico, ou a dimens\u00e3o prof\u00e9tica que continua hoje na vida da Igreja, que tamb\u00e9m tem a ver com a den\u00fancia daquilo com que n\u00e3o concordamos, porque n\u00e3o est\u00e1 de acordo, pensamos n\u00f3s, com os ditamos do Evangelho.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; A polariza\u00e7\u00e3o do discurso pol\u00edtico, essa tem acontecido, tem sido repetida, nomeadamente na sede da democracia, no Parlamento. E em eventos, como seria para dignificar a democracia, como a celebra\u00e7\u00e3o dos 50 anos da Constitui\u00e7\u00e3o&#8230;<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Em todo lugar, deve haver uma linguagem adequada, respeito pelas posi\u00e7\u00f5es dos outros&#8230; Toda a gente tem o direito de expressar o seu pr\u00f3prio modo de ver e de pensar, mas de uma forma civilizada, de uma forma dialogante, de uma forma adequada para as circunst\u00e2ncias, e n\u00e3o h\u00e1 circunst\u00e2ncia em que isso n\u00e3o deva acontecer.<\/p>\n<p style=\"font-weight: 400;\"><strong>Sess\u00e3o comemorativa do 25 de abril<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Para o D. Virg\u00edlio, o que vai significar participar na sess\u00e3o da Assembleia da Rep\u00fablica dos 25 de Abril? <\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Vou com muito gosto, devo dizer, vou com muito gosto! Tamb\u00e9m h\u00e1 alguma curiosidade, mas \u00e9 mais gosto pelo facto de manifestar que a Igreja presente nas dioceses portuguesas, que manifestou o desejo de me ver neste cargo, quer caminhar com todos, inclusivamente com aqueles que t\u00eam nas suas m\u00e3os os destinos do nosso pa\u00eds, do ponto de vista econ\u00f3mico, do ponto de vista social, do ponto de vista pol\u00edtico. Pode ser que a figura de um bispo possa ajudar a criar esses elos de unidade, de servi\u00e7o ao bem comum, que \u00e9 a causa que um bispo ali representa, porque, com certeza, a sua matriz \u00e9 a f\u00e9, mas \u00e9 manifestar o servi\u00e7o que todos devemos prestar ao bem comum.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Afirma tamb\u00e9m o envolvimento da Igreja Cat\u00f3lica nestes 50 anos, 52 anos de constru\u00e7\u00e3o democr\u00e1tica?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; A Igreja Cat\u00f3lica \u00e9 uma parceira importante na edifica\u00e7\u00e3o da democracia, sem fazer a tal pol\u00edtica partid\u00e1ria, mas tem sido uma presen\u00e7a grande na transforma\u00e7\u00e3o da sociedade, e h\u00e1 algumas \u00e1reas que toda a gente reconhece como \u00e1reas fundamentais, como \u00e9 a dimens\u00e3o social da vida das comunidades e como \u00e9 a assist\u00eancia \u00e0s pessoas em situa\u00e7\u00f5es de maior debilidade, crian\u00e7as, jovens, adultos, idosos, o ensino, que \u00e9 um setor t\u00e3o importante da vida de qualquer comunidade e a Igreja tem estado ali presente, mas tamb\u00e9m \u00e0 cria\u00e7\u00e3o desta consci\u00eancia da responsabilidade na edifica\u00e7\u00e3o do bem de todos e do bem comum, a Igreja tem estado l\u00e1.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Que desfecho espera nesta discuss\u00e3o j\u00e1 longa do Pacote Laboral?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; O que eu desejo \u00e9 que se chegue \u00e0 melhor lei, que respeita os direitos das pessoas que trabalham e que s\u00e3o criadoras de riqueza e que o pa\u00eds conhe\u00e7a que tamb\u00e9m as empresas s\u00e3o absolutamente indispens\u00e1veis para a cria\u00e7\u00e3o da mesma riqueza, que depois d\u00e1 origem a um maior bem-estar econ\u00f3mico, social e at\u00e9 espiritual \u00e0s pessoas e \u00e0s fam\u00edlias. Felizmente, as pessoas v\u00e3o dialogando e v\u00e3o dialogar e o que eu espero \u00e9 que se chegue a uma lei que seja justa para todos dentro da sociedade portuguesa e que permita o crescimento, o aumento da riqueza e o bem-estar social das popula\u00e7\u00f5es.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; O risco da precariedade excessiva n\u00e3o coloca em causa essa justi\u00e7a?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; A precariedade excessiva \u00e9 sempre uma coisa negativa, porque as pessoas precisam ter algumas seguran\u00e7as na vida. Tamb\u00e9m n\u00e3o pode ser uma liga\u00e7\u00e3o que seja absolutamente e sempre, em todos os casos, intoc\u00e1vel. A precariedade em si mesma cria dificuldades \u00e0s pessoas e \u00e0s fam\u00edlias.<\/p>\n<figure id=\"attachment_422742\" aria-describedby=\"caption-attachment-422742\" style=\"width: 400px\" class=\"wp-caption alignleft\"><img decoding=\"async\" class=\"size-medium wp-image-422742\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2026a-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2026a-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2026a-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2026a-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2026a-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2026\/04\/virgilio-antunes-coimbra2026a.jpg 1500w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-422742\" class=\"wp-caption-text\">Foto: Ag\u00eancia ECCLEISA\/TAM<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\"><strong>O pontificado do Papa Le\u00e3o XIV<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; D. Virg\u00edlio Antunes, falemos um pouco deste pontificado do Papa Le\u00e3o XIV, nomeadamente essa determina\u00e7\u00e3o que desde a primeira hora ele tem manifestado de um convite \u00e0 paz, de um desafio \u00e0 paz. Como \u00e9 que analisou a troca, n\u00e3o digo de galhardetes, mas pelo menos na comunica\u00e7\u00e3o social assim que aconteceu, a troca de mensagens entre o presidente norte-americano e o Papa Le\u00e3o XIV?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Em primeiro lugar fiquei triste que tivesse acontecido. Espero que seja uma coisa facilmente ultrapass\u00e1vel. O Papa, tudo aquilo que disse e afirmou, bem na linha dos seus predecessores, concretamente do Papa Francisco, todos os domingos, todas as quartas-feiras e quando escreveu e quando fez homilias, falou a favor da paz, que deve ser edificada com base no di\u00e1logo, na justi\u00e7a. As interven\u00e7\u00f5es que v\u00e3o contra isto deixam-nos tristes e depois quando se metem com cr\u00edticas diretas \u00e0 palavra do Papa, penso que seria a todos os t\u00edtulos de evitar, que n\u00e3o devia acontecer e depois n\u00e3o devia haver reincid\u00eancias que parece que agravam ainda mais este caso que nem sequer devia acontecer.<\/p>\n<p style=\"font-weight: 400;\">O Papa disse o que devia dizer, continuar\u00e1 a dizer, como ele afirmou, aquilo que tem de dizer e est\u00e1 determinado a levar por diante a sua miss\u00e3o, gra\u00e7as a Deus! N\u00e3o sab\u00edamos como iria reagir assim o Papa Le\u00e3o, porque n\u00e3o conhec\u00edamos a sua personalidade, mas felizmente est\u00e1 decidido a levar por diante a sua miss\u00e3o, com todos os custos que isso implicar.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Estar um presidente de um pa\u00eds ou uma lideran\u00e7a pol\u00edtica a evocar argumentos teol\u00f3gicos ou at\u00e9 do evangelho \u00e9 desajustado&#8230;<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; \u00c9 desajustado, evidentemente. Assim como n\u00f3s temos o dever de n\u00e3o nos intermeter nas quest\u00f5es da pol\u00edtica partid\u00e1ria direta ou mesmo na pol\u00edtica interna ou externa de um Estado, os Estados tamb\u00e9m n\u00e3o devem abusar, utilizando argumentos dessa ordem.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; A Am\u00e9rica tem neste momento duas vozes com alcance global, o Papa Le\u00e3o XIV, o presidente norte-americano. \u00c9 claro que \u00e9 inquestion\u00e1vel que a voz que o mundo deve ouvir \u00e9 a de Le\u00e3o XIV&#8230;<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Eu escolho o Papa Le\u00e3o, evidentemente, mas \u00e9 uma evid\u00eancia, porque \u00e9 pela paz. Quem \u00e9 pela paz tem sempre o meu voto em primeiro lugar, evidentemente. \u00c9 pela paz, \u00e9 pela justi\u00e7a, \u00e9 pela equidade, \u00e9 pelo tratamento respeitoso pelas pessoas e povos, \u00e9 por uma economia que d\u00e1 vida em vez de ser por uma economia que mata.<\/p>\n<p style=\"font-weight: 400;\">Ainda agora, na \u00c1frica, falou do extrativismo, daquela extra\u00e7\u00e3o abusiva de minerais, etc, para proveito de alguns&#8230; Que voz \u00e9 que n\u00f3s precisamos de ouvir, no mundo em que n\u00f3s estamos se n\u00e3o aquela que apela ao bom senso, \u00e0 justi\u00e7a, \u00e0 equidade, ao respeito pelas pessoas e povos, a uma economia que d\u00e1 vida a todos? \u00c9 a do Papa&#8230;<\/p>\n<p style=\"font-weight: 400;\"><em>AE \u2013 <\/em><em>D. Virg\u00edlio <\/em><em>conhece-se bem toda a regi\u00e3o do M\u00e9dio Oriente, uma regi\u00e3o marcada por conflitos ao longo de s\u00e9culos, que se est\u00e3o a agudizar nos dias de hoje. Que perspetivas podemos lan\u00e7ar para a resolu\u00e7\u00e3o desses conflitos, quando as guerras s\u00e3o cada vez mais digitais quase, com consequ\u00eancias reais muito efetivas?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; O M\u00e9dio Oriente est\u00e1 no n\u00famero e no lugar das civiliza\u00e7\u00f5es mais antigas, o Ir\u00e3o, o Iraque, a Jord\u00e2nia, L\u00edbano, S\u00edria, depois Palestina, Israel, Egito&#8230; Guerras sempre houve ali e sempre pela disputa dos territ\u00f3rios, sempre por motiva\u00e7\u00f5es que n\u00e3o t\u00eam a ver com o bem-estar das pessoas, mas outro tipo de motiva\u00e7\u00f5es. Eu gostaria muito que aquela regi\u00e3o da terra estivesse pacificada, porque d\u00e1 a impress\u00e3o que a terra estaria mais pacificada, ou estaria mesmo pacificada.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Se \u00e9 o ber\u00e7o do cristianismo, pode ser tamb\u00e9m o ber\u00e7o da paz?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; \u00c9 o ber\u00e7o de muitas das religi\u00f5es abra\u00e2micas, \u00e9 o ber\u00e7o do juda\u00edsmo, \u00e9 o ber\u00e7o do cristianismo, \u00e9 o ber\u00e7o do isl\u00e3o, e n\u00e3o gostar\u00edamos nunca que a quest\u00e3o das motiva\u00e7\u00f5es religiosas estivesse presente em nenhum destes conflitos, como as outras motiva\u00e7\u00f5es n\u00e3o deviam existir. Ali, a s\u00e3 conviv\u00eancia entre pessoas e povos devia ser como em todas as outras partes do mundo: todos t\u00eam o direito de existir, todos t\u00eam o direito \u00e0 sua identidade, \u00e0 sua identidade enquanto povo, \u00e0 sua identidade religiosa, \u00e0 sua identidade social, evidentemente, mas d\u00e1 a impress\u00e3o que n\u00e3o est\u00e3o ainda encontradas as condi\u00e7\u00f5es para que aquela regi\u00e3o seja uma regi\u00e3o de paz, como modelo da paz que devia existir em toda a terra.<\/p>\n<p style=\"font-weight: 400;\"><strong>Papa em Portugal em 2027<\/strong><\/p>\n<p style=\"font-weight: 400;\"><em>AE \u2013 D. Virg\u00edlio, gostava ainda de lhe perguntar sobre o Santu\u00e1rio de F\u00e1tima, o acontecimento de F\u00e1tima em Portugal, n\u00e3o na sua dimens\u00e3o religiosa, a centralidade que tem para os crentes em Portugal e os crentes de todo o mundo, mas, sociologicamente, o que representa aquele Santu\u00e1rio para Portugal, at\u00e9 para a afirma\u00e7\u00e3o de Portugal no mundo?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA \u2013 F\u00e1tima, de facto, ajudou a moldar muito daquilo que \u00e9 a religiosidade e a f\u00e9 dos crentes, dos crist\u00e3os, dos cat\u00f3licos, mas inclusivamente das popula\u00e7\u00f5es em geral. No mundo, tem uma relev\u00e2ncia que ainda \u00e9, em grand\u00edssima parte, desconhecida por n\u00f3s. Quem tem a possibilidade de percorrer um pouco do mundo e ver o impacto que tem uma simples imagem de Nossa Senhora do Ros\u00e1rio de F\u00e1tima, seja onde for, e ver a liga\u00e7\u00e3o afetiva que as pessoas t\u00eam, que os cat\u00f3licos t\u00eam, e mesmo, \u00e0s vezes, no contexto de outras religi\u00f5es, \u00e0 figura da Virgem de F\u00e1tima, \u00e9 uma coisa fabulosa.<\/p>\n<p style=\"font-weight: 400;\">Grande parte do mundo, pelo menos em alguns contextos, conhece Portugal por F\u00e1tima, conhece primeiro F\u00e1tima e depois Portugal. N\u00f3s n\u00e3o somos pessoas de estar a explorar os sentimentos das pessoas, nem esta dimens\u00e3o afetiva, mas \u00e9 um potencial muit\u00edssimo grande que Portugal, como pa\u00eds, tem, evidentemente.<\/p>\n<p style=\"font-weight: 400;\"><em>AE \u2013 Para quando a presen\u00e7a do Papa em Portugal, na sua opini\u00e3o, do Papa Le\u00e3o XIV?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; N\u00f3s gostar\u00edamos que fosse em 2027. Como \u00e9 sabido, a Confer\u00eancia Episcopal, pela m\u00e3o do antigo presidente D. Jos\u00e9 Ornelas, que tamb\u00e9m \u00e9 o bispo de Leiria-F\u00e1tima, j\u00e1 endere\u00e7ou um convite, outras pessoas j\u00e1 endere\u00e7aram esse convite ao Papa. Ele ter\u00e1 com toda a certeza o desejo de vir a Portugal.<\/p>\n<p style=\"font-weight: 400;\">A agenda do Papa \u00e9 o que \u00e9, e ele tem com certeza as suas prioridades relativamente \u00e0s suas viagens apost\u00f3licas, mas eu gostaria muito que fosse nos 110 anos das apari\u00e7\u00f5es de F\u00e1tima e no d\u00e9cimo anivers\u00e1rio dessa comemora\u00e7\u00e3o.<\/p>\n<p style=\"font-weight: 400;\"><em>AE &#8211; Vai, pretende articular, nomeadamente com o Presidente da Rep\u00fablica, esse convite tamb\u00e9m formal?<\/em><\/p>\n<p style=\"font-weight: 400;\">VA &#8211; Evidentemente, agora tem de se esperar para saber o que \u00e9 que pensa o Santo Padre acerca dessa possibilidade. Estamos todos dispon\u00edveis e penso que o senhor Presidente da Rep\u00fablica tamb\u00e9m ter\u00e1 todo o gosto e todo o desejo de se envolver nesta quest\u00e3o da hip\u00f3tese de uma visita do Santo Padre a Portugal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D. Virg\u00edlio Antunes foi eleito presidente da Confer\u00eancia Episcopal Portuguesa, numa assembleia plen\u00e1ria que eleigeu mais de metade dos coordenadores dos v\u00e1rios setores da pastoral<\/p>\n","protected":false},"author":5,"featured_media":422296,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6,980],"tags":[147],"class_list":["post-422773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","category-video","tag-conferencia-episcopal-portuguesa"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/422773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=422773"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/422773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/422296"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=422773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=422773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=422773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}