{"id":402374,"date":"2025-12-02T11:33:53","date_gmt":"2025-12-02T11:33:53","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=402374"},"modified":"2025-12-03T11:34:16","modified_gmt":"2025-12-03T11:34:16","slug":"libano-papa-defende-novo-rumo-para-medio-oriente-para-superar-divisoes-politicas-sociais-e-religiosas","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-defende-novo-rumo-para-medio-oriente-para-superar-divisoes-politicas-sociais-e-religiosas\/","title":{"rendered":"L\u00edbano: Papa defende novo rumo para M\u00e9dio Oriente, para superar \u00abdivis\u00f5es pol\u00edticas, sociais e religiosas\u00bb"},"content":{"rendered":"<p><em>Le\u00e3o XIV encerra viagem com apelo ao fim dos \u00abataques e hostilidades\u00bb e pedido de justi\u00e7a pelas v\u00edtimas do porto de Beirute<\/em><!--more--><\/p>\n<figure id=\"attachment_402376\" aria-describedby=\"caption-attachment-402376\" style=\"width: 1920px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-402376 size-full\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-1.jpg\" alt=\"\" width=\"1920\" height=\"1313\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-1.jpg 1920w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-1-400x274.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-1-1024x700.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-1-768x525.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-1-474x324.jpg 474w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-1-1536x1050.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption id=\"caption-attachment-402376\" class=\"wp-caption-text\">Foto: Lusa\/EPA<\/figcaption><\/figure>\n<p>Beirute, 02 dez 2025 (Ecclesia) \u2013 O Papa Le\u00e3o XIV encerrou hoje a sua visita ao L\u00edbano com um apelo ao fim dos conflitos armados na regi\u00e3o, defendendo um novo rumo para o M\u00e9dio Oriente, com a ajuda da comunidade internacional.<\/p>\n<p>\u201cO M\u00e9dio Oriente necessita de novas abordagens para rejeitar a mentalidade de vingan\u00e7a e viol\u00eancia, para superar as divis\u00f5es pol\u00edticas, sociais e religiosas e para abrir novos cap\u00edtulos em nome da reconcilia\u00e7\u00e3o e da paz\u201d, disse, no final da Missa a que presidiu em Beirute, perante dezenas de milhares de pessoas.<\/p>\n<p>\u201cPe\u00e7o mais uma vez \u00e0 comunidade internacional que n\u00e3o poupe esfor\u00e7os na promo\u00e7\u00e3o de processos de di\u00e1logo e reconcilia\u00e7\u00e3o, e fa\u00e7o um apelo sincero \u00e0queles que det\u00eam autoridade pol\u00edtica e social aqui e em todos os pa\u00edses marcados pela guerra e pela viol\u00eancia. Ou\u00e7am o clamor dos vossos povos que pedem a paz. Coloquemo-nos todos ao servi\u00e7o da vida, do bem comum e do desenvolvimento integral das pessoas\u201d, acrescentou.<\/p>\n<p>Na primeira viagem internacional do pontificado, que come\u00e7ou na Turquia, o Papa assumiu o desejo de estar como \u201cperegrino de esperan\u00e7a ao M\u00e9dio Oriente, implorando a Deus o dom da paz para esta terra amada, marcada pela instabilidade, pelas guerras e pelo sofrimento\u201d.<\/p>\n<p>\u201cSejam artes\u00e3os da paz, arautos da paz, testemunhas da paz. O caminho da hostilidade m\u00fatua e da destrui\u00e7\u00e3o no horror da guerra foi percorrido por demasiado tempo, com os resultados deplor\u00e1veis que est\u00e3o diante dos olhos de todos\u201d, declarou.<\/p>\n<blockquote><p>Precisamos de mudar de rumo. Precisamos de educar os nossos cora\u00e7\u00f5es para a paz. Desta pra\u00e7a, rezo pelo M\u00e9dio Oriente e por todos os povos que sofrem por causa da guerra.\u201d<\/p><\/blockquote>\n<p>A sauda\u00e7\u00e3o evocou ainda a crise pol\u00edtica na Guin\u00e9-Bissau e o inc\u00eandio em Hong Kong, que provocou mais de 140 mortes e v\u00e1rios desaparecidos na \u00faltima semana.<\/p>\n<p>J\u00e1 na cerim\u00f3nia de despedida no Aeroporto Internacional de Beirute, Le\u00e3o XIV alertou que \u201cas armas matam\u201d enquanto a negocia\u00e7\u00e3o edifica, afirmando que leva consigo a \u201csede de verdade e justi\u00e7a\u201d das fam\u00edlias das v\u00edtimas da explos\u00e3o do porto de Beirute.<\/p>\n<p>\u201cSa\u00fado todas as regi\u00f5es do L\u00edbano que n\u00e3o foi poss\u00edvel visitar: Tr\u00edpoli e o norte, o Vale do Beca e o sul do pa\u00eds, que vive, de modo particular, numa situa\u00e7\u00e3o de conflito e incerteza\u201d, declarou, pedindo que \u201ccessem os ataques e as hostilidades\u201d, perante o presidente da Rep\u00fablica e membros do Governo local.<\/p>\n<p>Le\u00e3o XIV refor\u00e7ou a sua condena\u00e7\u00e3o da viol\u00eancia: \u201cNingu\u00e9m acredite mais que a luta armada traz algum benef\u00edcio\u201d.<\/p>\n<p>\u201cAs armas matam; a negocia\u00e7\u00e3o, a media\u00e7\u00e3o e o di\u00e1logo edificam\u201d, prosseguiu.<\/p>\n<p>No seu \u00faltimo discurso em solo liban\u00eas, o Papa revelou que esta viagem foi tamb\u00e9m o cumprimento da vontade do seu antecessor.<\/p>\n<p>\u201cRegozijo-me por ter podido realizar a vontade do meu amado predecessor, o Papa Francisco, que tanto teria desejado estar aqui. Na verdade, ele est\u00e1 connosco\u201d, afirmou, sublinhando a continuidade espiritual do pontificado.<\/p>\n<div id='gallery-1' class='gallery galleryid-402374 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-defende-novo-rumo-para-medio-oriente-para-superar-divisoes-politicas-sociais-e-religiosas\/papa_libano_epa-2\/'><img decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-2-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-402375\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-2-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-2-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-2-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-2-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-2-1536x1024.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano_EPA-2.jpg 1920w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-402375'>\n\t\t\t\tFoto: Lusa\/EPA\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-rezou-em-silencio-no-porto-de-beirute\/papa_libano2025_epa-2\/'><img decoding=\"async\" width=\"400\" height=\"255\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano2025_EPA-2-400x255.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-402323\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano2025_EPA-2-400x255.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano2025_EPA-2-1024x653.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano2025_EPA-2-768x490.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano2025_EPA-2-1536x979.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_libano2025_EPA-2.jpg 1920w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-402323'>\n\t\t\t\tFoto: Lusa\/EPA\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-pede-aos-jovens-que-sejam-seiva-de-esperanca-sem-violencia-ou-desejo-de-vinganca\/papa_jovens_libano_vm2\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_jovens_libano_VM2-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-402318\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_jovens_libano_VM2-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_jovens_libano_VM2-1024x682.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_jovens_libano_VM2-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_jovens_libano_VM2-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_jovens_libano_VM2.jpg 1199w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-402318'>\n\t\t\t\tFoto: Vatican Media\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-e-lideres-religiosos-deixam-apelo-conjunto-a-paz-no-medio-oriente-rejeitando-extremismo\/papa_religioes_libano_epa-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_religioes_libano_EPA-3-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-402273\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_religioes_libano_EPA-3-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_religioes_libano_EPA-3-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_religioes_libano_EPA-3-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_religioes_libano_EPA-3-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_religioes_libano_EPA-3-1536x1024.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_religioes_libano_EPA-3.jpg 1920w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-402273'>\n\t\t\t\tFoto: Lusa\/EPA\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-evoca-crise-dos-refugiados-e-denuncia-conflitos-absurdos-e-impiedosos\/papa_harrisa_vm-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"264\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_harrisa_VM-4-400x264.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-402245\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_harrisa_VM-4-400x264.jpeg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_harrisa_VM-4-1024x675.jpeg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_harrisa_VM-4-768x506.jpeg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/papa_harrisa_VM-4.jpeg 1280w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-402245'>\n\t\t\t\tFoto: Vatican Media\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-chega-a-beirute-e-planta-cedro-da-amizade-no-palacio-presidencial\/doc-20251130-46121974-12559694\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"251\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/11\/DOC.20251130.46121974.12559694-400x251.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-402134\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/11\/DOC.20251130.46121974.12559694-400x251.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/11\/DOC.20251130.46121974.12559694-1024x642.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/11\/DOC.20251130.46121974.12559694-768x481.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/11\/DOC.20251130.46121974.12559694-1536x962.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/11\/DOC.20251130.46121974.12559694.jpg 1920w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-402134'>\n\t\t\t\tFoto: Lusa\/EPA\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-evoca-esperancas-e-dores-do-medio-oriente\/doc-20251201-46125664-12561523\/'><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"266\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/DOC.20251201.46125664.12561523-400x266.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-402181\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/DOC.20251201.46125664.12561523-400x266.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/DOC.20251201.46125664.12561523-1024x682.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/DOC.20251201.46125664.12561523-768x511.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/DOC.20251201.46125664.12561523-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/DOC.20251201.46125664.12561523-1536x1022.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/12\/DOC.20251201.46125664.12561523.jpg 1920w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-402181'>\n\t\t\t\tFoto: Lusa\/EPA\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Le\u00e3o XIV confessou que \u201c\u00e9 mais dif\u00edcil partir do que chegar\u201d, elogiando a cultura de encontro do povo liban\u00eas, e recordou os momentos de ora\u00e7\u00e3o no t\u00famulo de <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-evoca-esperancas-e-dores-do-medio-oriente\/\" target=\"_blank\" rel=\"noopener\">S\u00e3o Charbel<\/a> e no <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-rezou-em-silencio-no-porto-de-beirute\/\" target=\"_blank\" rel=\"noopener\">porto de Beirute<\/a>.<\/p>\n<p>\u201cA breve visita ao porto de Beirute &#8211; onde a explos\u00e3o devastou n\u00e3o s\u00f3 um lugar, mas muitas vidas &#8211; tocou-me o cora\u00e7\u00e3o. Rezei por todas as v\u00edtimas e levo comigo a dor e a sede de verdade e justi\u00e7a de tantas fam\u00edlias e de um pa\u00eds inteiro\u201d, disse.<\/p>\n<p>Recuperando a defini\u00e7\u00e3o hist\u00f3rica de S\u00e3o Jo\u00e3o Paulo II, o Papa reafirmou que \u201co L\u00edbano, mais do que um pa\u00eds, \u00e9 uma mensagem\u201d, despedindo-se com um \u201cat\u00e9 breve\u201d em \u00e1rabe.<\/p>\n<p>Ainda esta manh\u00e3, na <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-desafia-todas-as-religioes-a-rejeitar-logica-da-violencia\/\" target=\"_blank\" rel=\"noopener\">Missa<\/a> a que presidiu junto ao Mediterr\u00e2neo, Le\u00e3o XIV convidou toda a sociedade libanesa a superar a \u201cl\u00f3gica da viol\u00eancia\u201d.<\/p>\n<p>A agenda da viagem, <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-pede-aos-politicos-que-coloquem-a-paz-acima-de-tudo-para-enfrentar-feridas-pessoais-e-coletivas\/\" target=\"_blank\" rel=\"noopener\">iniciada<\/a> no domingo, incluiu a <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-critica-sociedade-que-ignora-fragilidade-e-corre-atras-de-falsos-mitos\/\" target=\"_blank\" rel=\"noopener\">visita<\/a> a um hospital psiqui\u00e1trico, a <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-evoca-crise-dos-refugiados-e-denuncia-conflitos-absurdos-e-impiedosos\/\" target=\"_blank\" rel=\"noopener\">celebra\u00e7\u00e3o<\/a> com a comunidade cat\u00f3lica no Santu\u00e1rio de Nossa Senhora do L\u00edbano, em Harissa, um encontro de ora\u00e7\u00e3o com <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-pede-aos-jovens-que-sejam-seiva-de-esperanca-sem-violencia-ou-desejo-de-vinganca\/\" target=\"_blank\" rel=\"noopener\">jovens<\/a> e uma cerim\u00f3nia inter-religiosa na Pra\u00e7a dos M\u00e1rtires, onde cat\u00f3licos e mu\u00e7ulmanos se uniram num <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/libano-papa-e-lideres-religiosos-deixam-apelo-conjunto-a-paz-no-medio-oriente-rejeitando-extremismo\/\" target=\"_blank\" rel=\"noopener\">apelo<\/a> de paz, contra o extremismo.<\/p>\n<p>Tr\u00eas Papas tinham, at\u00e9 hoje, visitado o L\u00edbano, na \u00e9poca contempor\u00e2nea: Paulo VI, em 1964; Jo\u00e3o Paulo II, em 1997; e Bento XVI, em 2012.<\/p>\n<p>A primeira etapa da viagem internacional decorreu entre 27 e 30 de novembro, na <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/turquia-papa-encerra-visita-marcada-por-busca-da-unidade-entre-igrejas-e-condenacao-da-violencia-com-justificacao-religiosa\/\" target=\"_blank\" rel=\"noopener\">Turquia<\/a>, numa visita marcada pela busca da unidade entre Igrejas e condena\u00e7\u00e3o da viol\u00eancia com justifica\u00e7\u00e3o religiosa.<\/p>\n<p>O programa do Papa evocou, em particular, os 1700 anos do Conc\u00edlio da Niceia e sublinhou aproxima\u00e7\u00e3o ao Patriarcado de Constantinopla (Igreja Ortodoxa), Bartolomeu, com quem Le\u00e3o XIV assinou uma declara\u00e7\u00e3o conjunta.<\/p>\n<p>Na viagem entre Istambul e Beirute, Le\u00e3o XIV falou aos jornalistas, para refor\u00e7ar a defesa da solu\u00e7\u00e3o dos dois Estados para o conflito israelo-palestino, <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/medio-oriente-papa-defende-solucao-de-dois-estados-e-sugere-grande-encontro-ecumenico-em-jerusalem-em-2033\/\" target=\"_blank\" rel=\"noopener\">apontando<\/a> ainda a um grande encontro ecum\u00e9nico em Jerusal\u00e9m em 2033.<\/p>\n<p><em>OC<\/em><\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_31305\"  width=\"480\" height=\"270\"  data-origwidth=\"480\" data-origheight=\"270\" src=\"https:\/\/www.youtube.com\/embed\/vFcj3lbQx8A?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=pt&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le\u00e3o XIV encerra viagem com apelo ao fim dos \u00abataques e hostilidades\u00bb e pedido de justi\u00e7a pelas v\u00edtimas do porto de Beirute<\/p>\n","protected":false},"author":2,"featured_media":402376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[56,4],"tags":[974,742,351,990],"class_list":["post-402374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-internacional","tag-leao-xiv","tag-libano","tag-medio-oriente","tag-turquia"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/402374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=402374"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/402374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/402376"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=402374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=402374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=402374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}