{"id":391309,"date":"2025-09-12T15:06:26","date_gmt":"2025-09-12T14:06:26","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=391309"},"modified":"2025-09-13T14:08:24","modified_gmt":"2025-09-13T13:08:24","slug":"mocambique-episcopados-lusofonos-condenam-barbaros-atos-de-violencia-em-cabo-delgado","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/mocambique-episcopados-lusofonos-condenam-barbaros-atos-de-violencia-em-cabo-delgado\/","title":{"rendered":"Mo\u00e7ambique: Episcopados lus\u00f3fonos condenam \u00abb\u00e1rbaros atos de viol\u00eancia\u00bb em Cabo Delgado"},"content":{"rendered":"<p><em>XVI Encontro de Bispos dos Pa\u00edses Lus\u00f3fonos decorreu em Lisboa<\/em><!--more--><\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_47653\"  width=\"480\" height=\"270\"  data-origwidth=\"480\" data-origheight=\"270\" src=\"https:\/\/www.youtube.com\/embed\/95yPP3c3Fgw?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=pt&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p>Alfragide, 12 set 2025 (Ecclesia) \u2013 Os episcopados lus\u00f3fonos condenaram hoje, em comunicado, os \u201cb\u00e1rbaros atos de viol\u00eancia\u201d em Cabo Delgado, norte de Mo\u00e7ambique, que enfrenta uma rebeli\u00e3o armada, respons\u00e1vel por milhares de mortes e mais de um milh\u00e3o deslocados.<\/p>\n<p>\u201cManifestamos de modo especial a nossa profunda solidariedade e apoio para com o povo de Cabo Delgado (Mo\u00e7ambique), desde 2017 v\u00edtima de b\u00e1rbaros atos de viol\u00eancia, destrui\u00e7\u00e3o e morte, que veementemente condenamos. Exortamos de novo a comunidade internacional a contribuir para uma efetiva situa\u00e7\u00e3o de paz em Cabo Delgado\u201d, referem os participantes no XVI Encontro de Bispos dos Pa\u00edses Lus\u00f3fonos, no comunicado final do encontro, que se iniciou esta ter\u00e7a-feira, em Lisboa.<\/p>\n<p>O <a href=\"https:\/\/www.conferenciaepiscopal.pt\/v1\/xvi-encontro-de-bispos-dos-paises-lusofonos-comunicado-final\/\" target=\"_blank\" rel=\"noopener\">documento<\/a> foi apresentado em confer\u00eancia de imprensa, no Semin\u00e1rio de Nossa Senhora de F\u00e1tima (Dehonianos), em Alfragide.<\/p>\n<p>Sob o lema \u2018viver a paz na hospitalidade\u2019, os trabalhos reuniram respons\u00e1veis cat\u00f3licos de oito na\u00e7\u00f5es, os quais deixaram um apelo a uma \u201ccultura de pontes, reconcilia\u00e7\u00e3o e paz\u201d.<\/p>\n<p>\u201cLamentamos vivamente as guerras em curso que tiram a dignidade e a vida de milh\u00f5es de pessoas em diferentes regi\u00f5es do mundo, especialmente na \u00c1frica, na Europa e no Pr\u00f3ximo Oriente\u201d, indicam os bispos.<\/p>\n<blockquote><p>Rezamos pelos povos que s\u00e3o v\u00edtimas das extremas viol\u00eancias e mortes, e apelamos aos l\u00edderes pol\u00edticos que acabem as guerras e estabele\u00e7am o di\u00e1logo para a edifica\u00e7\u00e3o da paz.\u201d<\/p><\/blockquote>\n<div id='gallery-1' class='gallery galleryid-391309 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/bispos-paises-lusofonos-alfragide2025\/'><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-391253\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025.jpg 1500w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-391253'>\n\t\t\t\tFoto: Ag\u00eancia ECCLESIA\/OC\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/bispos-paises-lusofonos-alfragide2025b\/'><img decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025b-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-391251\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025b-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025b-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025b-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025b-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025b.jpg 1500w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-391251'>\n\t\t\t\tFoto: Ag\u00eancia ECCLESIA\/OC\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/brasil-vice-presidente-da-cnbb-diz-que-pais-e-as-instituicoes-saem-reforcadas-apos-julgamento-por-tentativa-de-golpe\/bispos-paises-lusofonos-alfragide2025c\/'><img decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025c-400x267.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-391250\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025c-400x267.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025c-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025c-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025c-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2025\/09\/bispos-paises-lusofonos-alfragide2025c.jpg 1500w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-391250'>\n\t\t\t\tFoto: Ag\u00eancia ECCLESIA\/OC\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Segundo os bispos lus\u00f3fonos, \u201cnum momento em que as rela\u00e7\u00f5es internacionais e o sentido de uma comunidade global est\u00e3o amea\u00e7ados e em que aumenta a tend\u00eancia para a defesa e protecionismo, \u00e9 fundamental restabelecer a diplomacia da fraternidade\u201d.<\/p>\n<p>Os participantes convidaram as v\u00e1rias Igrejas de l\u00edngua portuguesa a \u201cidentificar programas concretos de parceria e coopera\u00e7\u00e3o\u201d.<\/p>\n<p>O comunicado final sustentou a defini\u00e7\u00e3o das \u201ccondi\u00e7\u00f5es e crit\u00e9rios de colabora\u00e7\u00e3o em rela\u00e7\u00e3o ao interc\u00e2mbio de padres e agentes pastorais\u201d.<\/p>\n<p>Os passos propostos devem passar pela \u201cexist\u00eancia de um protocolo entre a diocese que envia e a diocese que acolhe, envolvendo as confer\u00eancias episcopais como coordenadoras nesse processo; defini\u00e7\u00e3o do objetivo e projetos de modo concreto (estudo, forma\u00e7\u00e3o, trabalho pastoral, dura\u00e7\u00e3o da colabora\u00e7\u00e3o, etc.); previs\u00e3o de processos de inser\u00e7\u00e3o e incultura\u00e7\u00e3o, preparados pelas confer\u00eancias episcopais\u201d.<\/p>\n<p>D. Jos\u00e9 Manuel Imbamba, presidente da CEAST \u2013 Confer\u00eancia Episcopal de Angola e S\u00e3o Tom\u00e9, respondeu a uma quest\u00e3o sobre o corte ao financiamento nas ajudas ao desenvolvimento, por parte de pa\u00edses europeus e dos EUA, pedindo uma \u201cnova vis\u00e3o\u201d.<\/p>\n<p>\u201c\u00c0s vezes queremos viver de ajudas, na eterna depend\u00eancia\u201d, advertiu o arcebispo de Saurimo.<\/p>\n<p>O respons\u00e1vel deixou votos de que \u201cos pr\u00f3prios governos africanos saibam aproveitar os recursos dispon\u00edveis, sem se deixarem instrumentalizar\u201d.<\/p>\n<p>Os participantes no encontro acompanham, entre hoje e amanh\u00e3, as celebra\u00e7\u00f5es da peregrina\u00e7\u00e3o anivers\u00e1ria internacional de setembro, em F\u00e1tima.<\/p>\n<p>O XVII Encontro de Bispos dos Pa\u00edses Lus\u00f3fonos vai decorrer em S\u00e3o Tom\u00e9 e Pr\u00edncipe, de 12 a 17 de janeiro de 2027.<\/p>\n<p><em>OC<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XVI Encontro de Bispos dos Pa\u00edses Lus\u00f3fonos decorreu em Lisboa<\/p>\n","protected":false},"author":2,"featured_media":391251,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[922,4,980],"tags":[230,262],"class_list":["post-391309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-4-noticias","category-internacional","category-video","tag-igrejas-lusofonas","tag-mocambique"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/391309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=391309"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/391309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/391251"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=391309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=391309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=391309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}