{"id":350867,"date":"2024-11-28T12:52:16","date_gmt":"2024-11-28T12:52:16","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=350867"},"modified":"2025-03-28T10:21:07","modified_gmt":"2025-03-28T10:21:07","slug":"seul-jmj-2027-vai-ser-oportunidade-de-dialogo-de-fraternidade-e-de-comunhao-com-outras-religioes-afirma-o-secretario-do-dicasterio-para-os-leigos-a-familia-e-a-vida","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/seul-jmj-2027-vai-ser-oportunidade-de-dialogo-de-fraternidade-e-de-comunhao-com-outras-religioes-afirma-o-secretario-do-dicasterio-para-os-leigos-a-familia-e-a-vida\/","title":{"rendered":"Seul: JMJ 2027 vai ser \u00aboportunidade de di\u00e1logo, de fraternidade e de comunh\u00e3o\u00bb com outras religi\u00f5es, afirma o secret\u00e1rio do Dicast\u00e9rio para os Leigos, a Fam\u00edlia e a Vida (c\/v\u00eddeo)"},"content":{"rendered":"<p><em>Gleison de Paula Souza salienta que Igreja coreana tem tentando envolver todos os atores da sociedade civil e de outras confiss\u00f5es religiosas \u00abpara serem tamb\u00e9m protagonistas\u00bb na Jornada, a primeira que vai decorrer num pa\u00eds em que \u00abo n\u00famero de cat\u00f3licos \u00e9 inferior ao das outras religi\u00f5es\u00bb<\/em><\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_350869\" aria-describedby=\"caption-attachment-350869\" style=\"width: 1544px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/8DDDE481-AE38-4ED3-ABA7-CC541DD8EFBC-32069-0000057DDE39EF6E.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-350869 size-full\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/8DDDE481-AE38-4ED3-ABA7-CC541DD8EFBC-32069-0000057DDE39EF6E.jpg\" alt=\"\" width=\"1544\" height=\"954\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/8DDDE481-AE38-4ED3-ABA7-CC541DD8EFBC-32069-0000057DDE39EF6E.jpg 1544w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/8DDDE481-AE38-4ED3-ABA7-CC541DD8EFBC-32069-0000057DDE39EF6E-400x247.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/8DDDE481-AE38-4ED3-ABA7-CC541DD8EFBC-32069-0000057DDE39EF6E-1024x633.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/8DDDE481-AE38-4ED3-ABA7-CC541DD8EFBC-32069-0000057DDE39EF6E-768x475.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/8DDDE481-AE38-4ED3-ABA7-CC541DD8EFBC-32069-0000057DDE39EF6E-1536x949.jpg 1536w\" sizes=\"(max-width: 1544px) 100vw, 1544px\" \/><\/a><figcaption id=\"caption-attachment-350869\" class=\"wp-caption-text\">Foto: Ag\u00eancia ECCLESIA\/HM<\/figcaption><\/figure>\n<p><em>Henrique Matos, enviado da Ag\u00eancia ECCLESIA a Roma<\/em><\/p>\n<p>Cidade do Vaticano, 28 nov 2024 (Ecclesia) &#8211; O secret\u00e1rio do Dicast\u00e9rio para os Leigos, a Fam\u00edlia e a Vida destacou a oportunidade que a JMJ 2027, na Coreia do Sul, vai representar para o di\u00e1logo com outras religi\u00f5es, onde os cat\u00f3licos s\u00e3o apenas 10% da popula\u00e7\u00e3o.<\/p>\n<p>\u201cVai ser a primeira Jornada Mundial da Juventude onde o n\u00famero de cat\u00f3licos \u00e9 inferior ao das outras religi\u00f5es. Ent\u00e3o \u00e9 uma oportunidade, eu vejo isso como uma oportunidade de di\u00e1logo, de fraternidade, de comunh\u00e3o\u201d, afirmou Gleison de Paula Souza, em declara\u00e7\u00f5es \u00e0 Ag\u00eancia ECCLESIA, em Roma.<\/p>\n<p>O respons\u00e1vel acredita que \u201cviver juntos em harmonia e serenidade\u201d ser\u00e1 uma mensagem a transmitir nesta edi\u00e7\u00e3o internacional do encontro com o Papa.<\/p>\n<p>Em julho, o Secret\u00e1rio do Dicast\u00e9rio para os Leigos, a Fam\u00edlia e a Vida esteve na Coreia do Sul, e explica que a Igreja coreana tem \u201ctentando envolver todos os atores da sociedade civil, de outras religi\u00f5es, para serem tamb\u00e9m protagonistas\u201d.<\/p>\n<p>Apesar das rela\u00e7\u00f5es tensas entre os dois pa\u00edses, Gleison de Paula Souza manifestou tamb\u00e9m o desejo de a JMJ Seul 2027 acolher jovens da Coreia do Norte.<\/p>\n<blockquote><p>\u201cEsse \u00e9 um sonho. \u00c9 um sonho que, eu tenho a certeza que o Comit\u00e9 Local procurar\u00e1 trabalhar sobre isso, n\u00f3s ainda n\u00e3o temos informa\u00e7\u00e3o em rela\u00e7\u00e3o ao tema, mas vamos continuar em ora\u00e7\u00e3o para que tudo v\u00e1 para esse caminho, que d\u00ea tudo certo\u201d, expressou.<\/p><\/blockquote>\n<p>Os jovens da Coreia do Sul receberam os s\u00edmbolos da JMJ no \u00faltimo domingo, no Vaticano, numa celebra\u00e7\u00e3o com jovens portugueses, que passaram o testemunho para a pr\u00f3xima edi\u00e7\u00e3o do encontro, no ver\u00e3o de 2027.<\/p>\n<div id='gallery-1' class='gallery galleryid-350867 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4714.jpeg'><img decoding=\"async\" width=\"390\" height=\"260\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4714-390x260.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-350455\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4714-390x260.jpeg 390w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4714-1024x683.jpeg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4714-768x512.jpeg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4714-391x260.jpeg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4714.jpeg 1200w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-350455'>\n\t\t\t\tFoto Ag\u00eancia ECCLESIA\/HM, Passagem dos s\u00edmbolos de Portugal para a Coreia do Sul\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4608.jpeg'><img decoding=\"async\" width=\"390\" height=\"260\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4608-390x260.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-350452\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4608-390x260.jpeg 390w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4608-1024x683.jpeg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4608-768x512.jpeg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4608-391x260.jpeg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4608.jpeg 1200w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-350452'>\n\t\t\t\tFoto Ag\u00eancia ECCLESIA\/HM, Passagem dos s\u00edmbolos de Portugal para a Coreia do Sul\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4754.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"260\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4754-390x260.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-350457\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4754-390x260.jpeg 390w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4754-1024x683.jpeg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4754-768x512.jpeg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4754-391x260.jpeg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/Passagem-dos-Simbolos-de-Portugal-para-a-Coreia-do-Sul4754.jpeg 1200w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-350457'>\n\t\t\t\tFoto Ag\u00eancia ECCLESIA\/HM, Passagem dos s\u00edmbolos de Portugal para a Coreia do Sul\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>\u201cLisboa foi uma experi\u00eancia espetacular para os jovens, para o Papa, para o nosso dicast\u00e9rio\u201d, assinalou Gleison de Paula Souza em declara\u00e7\u00f5es transmitidas hoje, no programa Ecclesia, na RTP2, que acrescenta que, tal como fez com os jovens de Portugal, tamb\u00e9m agora o Papa entregou a Cruz peregrina e o \u00edcone de Nossa Senhora, enviando os jovens sul-coreanos em miss\u00e3o.<\/p>\n<blockquote><p>\u201cA nova miss\u00e3o \u00e9 que comecem a preparar-se. Comecem a preparar-se para acolher os jovens do mundo todo, acolherem os jovens de Portugal, acolherem os jovens da Am\u00e9rica Latina, da \u00c1sia, de um modo especial, e da Europa, para anunciar Cristo vivo. Cristo vivo, que quer transformar as vidas\u201d, referiu.<\/p><\/blockquote>\n<figure id=\"attachment_350899\" aria-describedby=\"caption-attachment-350899\" style=\"width: 390px\" class=\"wp-caption alignright\"><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/jmj-roma-coreia-sul.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-350899 size-medium\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/jmj-roma-coreia-sul-390x260.jpg\" alt=\"\" width=\"390\" height=\"260\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/jmj-roma-coreia-sul-390x260.jpg 390w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/jmj-roma-coreia-sul-1024x683.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/jmj-roma-coreia-sul-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/jmj-roma-coreia-sul-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/jmj-roma-coreia-sul-1536x1024.jpg 1536w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2024\/11\/jmj-roma-coreia-sul.jpg 1800w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/a><figcaption id=\"caption-attachment-350899\" class=\"wp-caption-text\">Foto: Jornada Mundial da Juventude 2027<\/figcaption><\/figure>\n<p>O secret\u00e1rio do Dicast\u00e9rio para os Leigos, a Fam\u00edlia e a Vida exortou os jovens a n\u00e3o terem medo e a ter coragem \u201cpara enfrentar as dificuldades do dia a dia\u201d: \u201cCristo vivo, que quer transformar as vidas. Cristo vivo, que quer nos dizer que n\u00e3o temos que ter medo\u201d.<\/p>\n<p>Sobre o elevado desenvolvimento tecnol\u00f3gico do Coreia do Sul, o secret\u00e1rio do Dicast\u00e9rio para os Leigos, a Fam\u00edlia e a Vida salientou que o mundo digital \u201c\u00e9 um novo lugar de evangeliza\u00e7\u00e3o\u201d e \u201cde miss\u00e3o\u201d, apelando aos jovens do mundo inteiro e do pa\u00eds que recebe a pr\u00f3xima JMJ a trabalhar nele.<\/p>\n<p>\u201cDevem tentar utilizar este novo campo para evangelizar, para apresentar o testemunho de Cristo para os outros jovens\u201d, defendeu.<\/p>\n<p>Embora existam riscos no mundo digital, como o isolamento, o entrevistado real\u00e7a que este tem tamb\u00e9m \u201clados positivos\u201d, como a possibilidade de \u201cchegar a mais pessoas\u201d e transmitir Cristo.<\/p>\n<p>Relativamente \u00e0 quest\u00e3o da veracidade que se imp\u00f5e com o desenvolvimento da Intelig\u00eancia Artificial, o secret\u00e1rio do Dicast\u00e9rio para os Leigos, a Fam\u00edlia e a Vida refere que \u201cpara a Igreja \u00e9 muito claro que a verdade \u00e9 Cristo, n\u00e3o existe outra verdade\u201d.<\/p>\n<p>\u201cA fabrica\u00e7\u00e3o de n\u00e3o-verdades \u00e9 fruto n\u00e3o do meio, n\u00e3o do digital, n\u00e3o da intelig\u00eancia artificial, \u00e9 fruto do homem que n\u00e3o quer falar a verdade\u201d, sublinha.<\/p>\n<p>Segundo Gleison de Paula Souza, \u00e9 fun\u00e7\u00e3o da Igreja apresentar aos jovens, no caso da JMJ, e \u201capresentar a todos os fi\u00e9is do mundo, essa maturidade, n\u00e3o s\u00f3 para distinguir o que \u00e9 verdade ou n\u00e3o \u00e9 verdade, mas a maturidade de experimentar a verdade que \u00e9 Cristo com muita tranquilidade, com muita sabedoria, saber distinguir aquilo que \u00e9 realmente a mensagem de Cristo\u201d.<\/p>\n<p>A entrevista ao secret\u00e1rio do Dicast\u00e9rio para os Leigos, a Fam\u00edlia e a Vida \u00e9 emitida no programa Ecclesia desta quinta-feira, na RTP2, onde se apresenta uma reportagem alargada sobre a passagem dos s\u00edmbolos da JMJ dos jovens portugueses para os sul-coreanos, no \u00faltimo domingo.<\/p>\n<table style=\"width: 100%; border-collapse: collapse; background-color: #c2e8f7;\">\n<tbody>\n<tr>\n<td style=\"width: 100%;\">Lisboa acolheu a edi\u00e7\u00e3o internacional da Jornada Mundial da Juventude entre 1 e 6 de agosto de 2023, com mais de 1,5 milh\u00f5es de participantes nas celebra\u00e7\u00f5es conclusivas, presididas por Francisco no Parque Tejo.<\/p>\n<p>A pr\u00f3xima edi\u00e7\u00e3o internacional da JMJ vai decorrer em Seul, capital da Coreia do Sul, em 2027, com o tema \u2018Tende coragem: eu venci o mundo!\u2019, uma passagem do Evangelho segundo S\u00e3o Jo\u00e3o (Jo 16,33).<\/p>\n<p>A primeira edi\u00e7\u00e3o aconteceu em 1986, em Roma, e desde ent\u00e3o a JMJ j\u00e1 passou pelas seguintes cidades: Buenos Aires (1987), Santiago de Compostela (1989), Czestochowa (1991), Denver (1993), Manila (1995), Paris (1997), Roma (2000), Toronto (2002), Col\u00f3nia (2005), Sidney (2008), Madrid (2011), Rio de Janeiro (2013), Crac\u00f3via (2016), Panam\u00e1 (2019) e Lisboa (2023).<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><em>HM\/LJ\/PR<\/em><\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_45815\"  width=\"480\" height=\"270\"  data-origwidth=\"480\" data-origheight=\"270\" src=\"https:\/\/www.youtube.com\/embed\/4me4BgajXq4?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=pt&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<blockquote class=\"wp-embedded-content\" data-secret=\"nvb6A9pz9U\"><p><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/jmj-coreira-2027-rezamos-para-que-possam-vir-jovens-da-coreia-do-norte-d-peter-chung-soon-tae\/\">JMJ 2027: \u00abRezamos para que possam vir jovens da Coreia do Norte\u00bb &#8211; Arcebispo de Seul (c\/v\u00eddeo)<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;JMJ 2027: \u00abRezamos para que possam vir jovens da Coreia do Norte\u00bb &#8211; Arcebispo de Seul (c\/v\u00eddeo)&#8221; &#8212; Ag\u00eancia ECCLESIA\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/jmj-coreira-2027-rezamos-para-que-possam-vir-jovens-da-coreia-do-norte-d-peter-chung-soon-tae\/embed\/#?secret=Dc27SNb1xV#?secret=nvb6A9pz9U\" data-secret=\"nvb6A9pz9U\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gleison de Paula Souza salienta que Igreja coreana tem tentando envolver todos os atores da sociedade civil e de outras confiss\u00f5es religiosas \u00abpara serem tamb\u00e9m protagonistas\u00bb na Jornada, a primeira que vai decorrer num pa\u00eds em que \u00abo n\u00famero de cat\u00f3licos \u00e9 inferior ao das outras religi\u00f5es\u00bb<\/p>\n","protected":false},"author":17,"featured_media":350899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[56,5],"tags":[448,372,240,400],"class_list":["post-350867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-vaticano","tag-asia","tag-coreia","tag-jornadas-mundiais-da-juventude","tag-vaticano"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/350867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=350867"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/350867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/350899"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=350867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=350867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=350867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}