{"id":35026,"date":"2008-11-03T13:22:32","date_gmt":"2008-11-03T13:22:32","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2008\/11\/03\/papa-nega-contradicao-entre-criacao-e-evolucao\/"},"modified":"2008-11-03T13:22:32","modified_gmt":"2008-11-03T13:22:32","slug":"papa-nega-contradicao-entre-criacao-e-evolucao","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/papa-nega-contradicao-entre-criacao-e-evolucao\/","title":{"rendered":"Papa nega contradi\u00e7\u00e3o entre cria\u00e7\u00e3o e evolu\u00e7\u00e3o"},"content":{"rendered":"<p>Bento XVI voltou a abordar a rela\u00e7\u00e3o entre cria\u00e7\u00e3o e evolu\u00e7\u00e3o, defendendo que o cosmos n\u00e3o \u00e9 um sistema ca\u00f3tico, mas sim ordenado, sendo poss\u00edvel &#8220;ler&#8221; nas suas regras internas a presen\u00e7a de um criador.  O Papa falava na passada Sexta-feira, num discurso dirigido aos participantes da assembleia plen\u00e1ria da Academia Pontif\u00edcia das Ci\u00eancias, que prolonga at\u00e9 4 de Novembro, para debater as \u00faltimas contribui\u00e7\u00f5es da pesquisa cient\u00edfica sobre as origens e a evolu\u00e7\u00e3o do universo, da mat\u00e9ria e da vida.  Para Bento XVI, afirmar que a cria\u00e7\u00e3o do cosmos e o seu desenvolvimento sejam fruto da &#8220;providencial sabedoria&#8221; de um criador n\u00e3o \u00e9 o mesmo dizer que a cria\u00e7\u00e3o remonta apenas ao in\u00edcio da hist\u00f3ria do mundo e da vida. O criador &#8220;d\u00e1 origem\u201d aos seus desenvolvimentos&#8221; e &#8220;ampara-os continuamente&#8221;.   \u201cMuitos dos nossos contempor\u00e2neos reflectem hoje, sobre a origem \u00faltima dos seres vivos, sobre a sua causa inicial e sobre o seu fim \u00faltimo, e ainda sobre o significado da hist\u00f3ria humana e do universo&#8221;, admitiu.  Nesse contento, afirmou o Papa, \u201csurgem, naturalmente, quest\u00f5es relativas \u00e0 rela\u00e7\u00e3o entre a leitura cient\u00edfica do mundo e a leitura oferecida pela Revela\u00e7\u00e3o crist\u00e3. Os meus predecessores Pio XII e Jo\u00e3o Paulo II observaram que n\u00e3o existe nenhuma oposi\u00e7\u00e3o entre a compreens\u00e3o da cria\u00e7\u00e3o ditada pela f\u00e9 e as provas oferecidas pelas ci\u00eancias emp\u00edricas\u201d.  Na \u00f3ptica da f\u00e9, portanto, ler a evolu\u00e7\u00e3o \u00e9 como &#8220;ler um livro&#8221;, segundo uma antiga compara\u00e7\u00e3o, adoptada por muitos cientistas, entre os quais Galileu Galilei, livro cuja hist\u00f3ria \u201clemos com base nas diversas abordagens das ci\u00eancias&#8221;.  &#8220;Apesar dos elementos irracionais, ca\u00f3ticos e destrutivos que encontramos no longo processo de modifica\u00e7\u00e3o do cosmos, a mat\u00e9ria  como tal  \u00e9 \u2018leg\u00edvel\u2019. \u00c9 uma constru\u00e7\u00e3o interna \u2018matem\u00e1tica\u2019. A mente humana pode, portanto empenhar-se n\u00e3o apenas numa \u2018cosmografia\u2019, estudando os fen\u00f3menos mensur\u00e1veis, mas tamb\u00e9m numa \u2018cosmologia\u2019, discernindo a l\u00f3gica interna vis\u00edvel do cosmos&#8221;, explicou.  <i>(Com R\u00e1dio Vaticano) <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bento XVI voltou a abordar a rela\u00e7\u00e3o entre cria\u00e7\u00e3o e evolu\u00e7\u00e3o, defendendo que o cosmos n\u00e3o \u00e9 um sistema ca\u00f3tico, mas sim ordenado, sendo poss\u00edvel &#8220;ler&#8221; nas suas regras internas a presen\u00e7a de um criador. O Papa falava na passada Sexta-feira, num discurso dirigido aos participantes da assembleia plen\u00e1ria da Academia Pontif\u00edcia das Ci\u00eancias, que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[120,237],"class_list":["post-35026","post","type-post","status-publish","format-standard","hentry","category-vaticano","tag-bento-xvi","tag-joao-paulo-ii"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/35026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=35026"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/35026\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=35026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=35026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=35026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}