{"id":3462,"date":"2006-04-03T14:44:19","date_gmt":"2006-04-03T14:44:19","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/04\/03\/esperanca-em-viana-do-castelo\/"},"modified":"2006-04-03T14:44:19","modified_gmt":"2006-04-03T14:44:19","slug":"esperanca-em-viana-do-castelo","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/esperanca-em-viana-do-castelo\/","title":{"rendered":"Esperan\u00e7a em Viana do Castelo"},"content":{"rendered":"<p>Adolescentes fazem experi\u00eancia de Semin\u00e1rio <!--more--> Perto de 40 adolescentes responderam positivamente \u00e0 chamada tendo iniciado, ontem, uma caminhada de Pr\u00e9-Semin\u00e1rio, reunindo-se no Semin\u00e1rio Diocesano de Viana do Castelo em animado conv\u00edvio, espa\u00e7o de forma\u00e7\u00e3o e tempo de ora\u00e7\u00e3o. O reitor do Semin\u00e1rio disse ao Di\u00e1rio do Minho que a resposta superou qualquer expectativa, assinalando que, face ao momento de dificuldade em encontrar voca\u00e7\u00f5es, e recorde-se que no presente ano n\u00e3o houve qualquer candidato ao Semin\u00e1rio em Viana, este \u00e9 um grande \u00absinal de esperan\u00e7a\u00bb para uma diocese que acaba de completar 26 anos de exist\u00eancia. Embora no grupo existam 13 jovens que j\u00e1 estavam inseridos nesta outra \u00abmodalidade de semin\u00e1rio\u00bb, o padre Alfredo Domingues est\u00e1 esperan\u00e7ado que \u00aba maior parte, sen\u00e3o todos\u00bb (raz\u00f5es de for\u00e7a maior impediram alguns de comparecer) possam vir ainda a integrar a forma\u00e7\u00e3o neste Semin\u00e1rio que actualmente tem cinco alunos. Paulo Gon\u00e7alves, de 13 anos de idade, veio pela primeira vez fazer esta experi\u00eancia porque, mesmo sem saber muito bem o que quer ser, agrada-lhe a ideia de ser padre e entende que o encontro lhe pode ajudar a \u00abescolher\u00bb. Natural da par\u00f3quia de Refoios, do arciprestado de Ponte de Lima, este jovem tomou conhecimento do Pr\u00e9-Semin\u00e1rio atrav\u00e9s de uma senhora l\u00e1 da terra e mesmo antes do primeiro encontro ter terminado j\u00e1 nos confidenciava que \u00abvaleu a pena vir\u00bb e que por isso \u00e9 um caminho \u00abpara continuar\u00bb. Na figura do padre, a este pr\u00e9-adolescente a frequentar o 8.\u00ba ano de escolaridade, sobressai \u00abo homem que serve Deus\u00bb. \u00abPositivo\u00bb foi a classifica\u00e7\u00e3o atribu\u00edda por Manuel Rodrigues ao reflectir sobre como decorreu o ano passado o seu primeiro ano em Pr\u00e9-Semin\u00e1rio, adiantando ter \u00abesclarecido muitas d\u00favidas\u00bb, ter aprendido \u00abmuitas coisas\u00bb e ter conseguido um excelente \u00abconv\u00edvio com os colegas\u00bb das diversas partes da diocese. Para este mon\u00e7anense de 14 anos, natural da comunidade de S. Martinho de Parada, \u00abser padre \u00e9 algo que continua a fascinar\u00bb e diz mesmo que a vida de sacerdote n\u00e3o \u00e9 muito complicada \u00abporque n\u00e3o est\u00e1 retirado do mundo, est\u00e1 no meio das pessoas\u00bb. A \u00abmaneira de ser\u00bb, a \u00abfor\u00e7a de vontade\u00bb e a \u00abajuda \u00e0s pessoas atrav\u00e9s do conselho\u00bb s\u00e3o qualidades que v\u00ea no padre e que o fazem sonhar poder entregar-se para desempenhar a miss\u00e3o de servi\u00e7o aos homens numa doa\u00e7\u00e3o total a Deus. Trabalhar com as fam\u00edlias A nova equipa do Semin\u00e1rio Diocesano de Viana do Castelo entende que esta modalidade de semin\u00e1rio \u00e9 \u00abum caminho de forma\u00e7\u00e3o e prepara\u00e7\u00e3o em ordem a integrar o semin\u00e1rio\u00bb. Contudo para ter continuidade e dar frutos \u00e9 essencial trabalhar com as fam\u00edlias porque elas \u00e9 que \u00abs\u00e3o os verdadeiros e mais directos formadores do mi\u00fado, fazendo a ponte entre o Semin\u00e1rio e o jovem que est\u00e1 \u00e0 descoberta da voca\u00e7\u00e3o\u00bb. Por isso, referiu o Reitor, \u00abvamos fazer um acompanhamento das fam\u00edlias\u00bb, estando a ser programado um encontro, durante um dia de domingo, de tr\u00eas em tr\u00eas meses, atrav\u00e9s do qual se vai proporcionar alguma forma\u00e7\u00e3o em diversas vertentes, sobretudo clarificar o que \u00e9 que o Semin\u00e1rio pretende. Esta \u00abaposta forte no Pr\u00e9-Semin\u00e1rio\u00bb, e refira-se que o Semin\u00e1rio est\u00e1 aberto a receber um jovem para esta modalidade em qualquer altura do ano, leva a que para aqueles que agora iniciaram o percurso esteja programado um encontro mensal, ao s\u00e1bado, no Semin\u00e1rio Diocesano. De tr\u00eas em tr\u00eas meses, e o pr\u00f3ximo acontece entre o dia 6 e o dia 8 de Dezembro, os jovens s\u00e3o convidados a passar um fim-de-semana em comunidade nas instala\u00e7\u00f5es de Viana do Castelo. Em caminhada de Pr\u00e9-Semin\u00e1rio pode entrar todo aquele jovem que completou 11 anos ou seja est\u00e1 a frequentar o 6.\u00ba ano de escolaridade. Contudo, refere o padre Alfredo Domingues, o Semin\u00e1rio garante um acompanhamento a todos aqueles que mesmo antes desta idade manifestarem vontade de fazer esta experi\u00eancia, assinalando que este ano \u00abapareceram algumas inscri\u00e7\u00f5es\u00bb.  Neste caso os formadores do Semin\u00e1rio v\u00e3o junto do jovem, no contexto da fam\u00edlia, \u00abse nos abrir as portas\u00bb, diz o Reitor, e junto da pr\u00f3pria comunidade e p\u00e1roco. O padre Alfredo Domingues revelou que para este ano foi delineada uma estrat\u00e9gia de abordagem da quest\u00e3o vocacional que passa pelo envio de documenta\u00e7\u00e3o para todos os catequistas e professores da disciplina de Educa\u00e7\u00e3o Moral e Religiosa Cat\u00f3lica (alguns vieram depois de conversar com o professor ou professora), por ir ao encontro dos sacerdotes nos respectivos arciprestados e mesmo pela tem\u00e1tica abordada no F\u00f3rum Sacerdotal que tamb\u00e9m \u00abdeu um empurr\u00e3o\u00bb. O Semin\u00e1rio, alunos e formadores, est\u00e1 dispon\u00edvel para \u00abuma ou outra vez\u00bb se deslocar \u00e0s comunidades, privilegiando aquelas donde s\u00e3o oriundos os adolescentes que est\u00e3o em Pr\u00e9-Semin\u00e1rio.      <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adolescentes fazem experi\u00eancia de Semin\u00e1rio<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[182,193,206],"class_list":["post-3462","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-diocese-de-viana-do-castelo","tag-educacao","tag-familia"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/3462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=3462"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/3462\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=3462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=3462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=3462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}