{"id":32238,"date":"2008-05-31T11:35:21","date_gmt":"2008-05-31T11:35:21","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2008\/05\/31\/bispo-de-viana-quer-eucaristia-no-centro\/"},"modified":"2008-05-31T11:35:21","modified_gmt":"2008-05-31T11:35:21","slug":"bispo-de-viana-quer-eucaristia-no-centro","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/bispo-de-viana-quer-eucaristia-no-centro\/","title":{"rendered":"Bispo de Viana quer Eucaristia no centro"},"content":{"rendered":"<p>A \u00abEucaristia \u00e9 o centro da vida da Igreja e nenhuma outra express\u00e3o religiosa pode substitu\u00ed-la ou ser considerada ao mesmo n\u00edvel\u00bb, alertou D. Jos\u00e9 Pedreira ontem em Santa Luzia, o monte donde irradia o culto ao amor de Cristo, simbolizado pelo seu divino cora\u00e7\u00e3o. Na celebra\u00e7\u00e3o eucar\u00edstica da solenidade do Sagrado Cora\u00e7\u00e3o de Jesus, o Bispo de Viana do Castelo frisou que da devo\u00e7\u00e3o popular, onde aparecem elementos que n\u00e3o se coadunam com a doutrina \u00abdevem ser purificados com prud\u00eancia e paci\u00eancia\u00bb propondo uma catequese \u00abatenta e respeitosa\u00bb, a n\u00e3o ser que incongru\u00eancias exijam medidas mais radicais. Numa refer\u00eancia ao S\u00ednodo recordou que propostas sobre a religiosidade ou piedade populares podem resumir-se em poucas palavras: \u00abvalorizar as suas riquezas, fazer da Eucaristia o verdadeiro centro dessas celebra\u00e7\u00f5es, criar mecanismos e formas de participa\u00e7\u00e3o mais alargadas\u00bb. Apesar destas advert\u00eancias, o prelado salientou a profundidade a que se encontra enraizada na f\u00e9 do povo do Alto Minho, a devo\u00e7\u00e3o ao Sagrado Cora\u00e7\u00e3o de Jesus que \u00e9 express\u00e3o do \u00abreconhecimento do profundo amor de Deus a todos os seres humanos, testemunhado pelo envio do seu Filho \u00danico Jesus Cristo que se fez homem para nossa salva\u00e7\u00e3o\u00bb. A devo\u00e7\u00e3o ao Sagrado Cora\u00e7\u00e3o de Jesus e \u00e0 Eucaristia, sublinhou, andam profundamente unidos, da\u00ed que se tenha estabelecido na Igreja a \u00abdevo\u00e7\u00e3o \u00e0 comunh\u00e3o em nove sextas-feiras seguidas\u00bb e na festa lit\u00fargica do Sagrado Cora\u00e7\u00e3o de Jesus. No dia que, a n\u00edvel mundial, \u00e9 particularmente dedicado \u00e0 ora\u00e7\u00e3o pela santifica\u00e7\u00e3o dos sacerdotes, na Diocese de Viana do Castelo os cinco jovens di\u00e1conos candidatos ao sacerd\u00f3cio ministerial, diante do altar do Sagrado Cora\u00e7\u00e3o de Jesus, fizeram a sua profiss\u00e3o de f\u00e9 e a sua consagra\u00e7\u00e3o. O Santo Padre dirigiu um apelo a que em todas as dioceses do mundo se promovesse um movimento espiritual que, favorecendo uma consci\u00eancia cada vez maior da liga\u00e7\u00e3o intr\u00ednseca entre Eucaristia e Sacerd\u00f3cio e da especial Maternidade da Maria em rela\u00e7\u00e3o a todos os sacerdotes. Espera-se que esse movimento d\u00ea vida a uma corrente de adora\u00e7\u00e3o perp\u00e9tua para a santifica\u00e7\u00e3o dos cl\u00e9rigos, e a um novo empenho das almas femininas consagradas para que, a exemplo da Virgem Maria, e de modo singular associadas \u00e0 sua participa\u00e7\u00e3o na obra da Reden\u00e7\u00e3o, queiram adoptar espiritualmente sacerdotes (um sacerdote concreto), para ajud\u00e1-los com a oferta de si, a ora\u00e7\u00e3o e a penit\u00eancia. Dirigindo-se aos zeladores, que mais de uma centena participaram ontem no Encontro Diocesano, o prelado desafiou-os a cultivarem a contempla\u00e7\u00e3o, a ora\u00e7\u00e3o e o desagravo pelos pecados com que Deus \u00e9 ofendido e tomarem parte de forma activa de apostolado, nas nossas comunidades crist\u00e3s. O promotor Diocesano, durante o encontro, anunciou estarem a ser desenvolvidos todos os esfor\u00e7os para que as rel\u00edquias de Santa Margarida Maria, possam estar no santu\u00e1rio durante a solenidade do pr\u00f3ximo ano e na peregrina\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A \u00abEucaristia \u00e9 o centro da vida da Igreja e nenhuma outra express\u00e3o religiosa pode substitu\u00ed-la ou ser considerada ao mesmo n\u00edvel\u00bb, alertou D. Jos\u00e9 Pedreira ontem em Santa Luzia, o monte donde irradia o culto ao amor de Cristo, simbolizado pelo seu divino cora\u00e7\u00e3o. Na celebra\u00e7\u00e3o eucar\u00edstica da solenidade do Sagrado Cora\u00e7\u00e3o de Jesus, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[127,182],"class_list":["post-32238","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-catequese","tag-diocese-de-viana-do-castelo"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/32238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=32238"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/32238\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=32238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=32238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=32238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}