{"id":29538,"date":"2008-01-23T10:54:05","date_gmt":"2008-01-23T10:54:05","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2008\/01\/23\/devocao-e-fe-na-festa-de-sao-vicente\/"},"modified":"2008-01-23T10:54:05","modified_gmt":"2008-01-23T10:54:05","slug":"devocao-e-fe-na-festa-de-sao-vicente","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/devocao-e-fe-na-festa-de-sao-vicente\/","title":{"rendered":"Devo\u00e7\u00e3o e f\u00e9 na festa de S\u00e3o Vicente"},"content":{"rendered":"<p>D. Ant\u00f3nio Carrilho, Bispo do Funchal, presidiu \u00e0 festa lit\u00fargica de S\u00e3o Vicente, celebrada ontem na respectiva igreja, que registou uma grande aflu\u00eancia de pessoas. Na homilia o prelado funchalense real\u00e7ou alguns aspectos do m\u00e1rtir S\u00e3o Vicente sublinhando que ele \u00e9 um exemplo para os crist\u00e3os de hoje continuarem a ter a preocupa\u00e7\u00e3o de conhecer e seguir Jesus.   A par\u00f3quia de S\u00e3o Vicente celebrou ontem a festa do seu padroeiro, sendo presidida por D. Ant\u00f3nio Carrilho, que pela primeira vez visitava aquela localidade, pelo que foi recebido com muito entusiasmo.  No in\u00edcio da celebra\u00e7\u00e3o eucar\u00edstica o Pe. Humberto Vasconcelos, p\u00e1roco de S\u00e3o Vicente, manifestou a sua alegria bem como a da comunidade paroquial pela presen\u00e7a do prelado funchalense. Referiu que tinha recebido uma mensagem do presidente da C\u00e2mara Municipal de S\u00e3o Vicente que, juntamente com um grupo de entidades daquele munic\u00edpio, se encontra de visita \u00e0 Venezuela em que dava conta que a Confraria de S\u00e3o Vicente, em Caracas, composta por 57 elementos, saudava o senhor bispo do Funchal e que estava em uni\u00e3o com a sua terra natal celebrando tamb\u00e9m, naquele pa\u00eds, a festa de S\u00e3o Vicente.  D. Ant\u00f3nio Carrilho ao agradecer as palavras do p\u00e1roco, sublinhou que \u201c\u00e9 bom que nos sintamos solid\u00e1rios em comunh\u00e3o uns com os outros no dia-a-dia da vida, mas de um modo especial, em certos momentos como este em que celebramos o padroeiro. \u00c9 importante sentir que para al\u00e9m desta comunidade aqui na Madeira, tamb\u00e9m muitos que daqui sa\u00edram mant\u00eam a mesma f\u00e9 e devo\u00e7\u00e3o a S\u00e3o Vicente no estrangeiro\u201d.  Na homilia o prelado funchalense referiu-se \u00e0 vida do m\u00e1rtir S\u00e3o Vicente, assinalando que o seu testemunho de f\u00e9 continua a ser exemplo para os crist\u00e3os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D. Ant\u00f3nio Carrilho, Bispo do Funchal, presidiu \u00e0 festa lit\u00fargica de S\u00e3o Vicente, celebrada ontem na respectiva igreja, que registou uma grande aflu\u00eancia de pessoas. Na homilia o prelado funchalense real\u00e7ou alguns aspectos do m\u00e1rtir S\u00e3o Vicente sublinhando que ele \u00e9 um exemplo para os crist\u00e3os de hoje continuarem a ter a preocupa\u00e7\u00e3o de conhecer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[186,267],"class_list":["post-29538","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-diocese-do-funchal","tag-natal"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/29538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=29538"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/29538\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=29538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=29538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=29538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}