{"id":273186,"date":"2023-03-01T10:14:40","date_gmt":"2023-03-01T10:14:40","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=273186"},"modified":"2023-03-01T10:14:40","modified_gmt":"2023-03-01T10:14:40","slug":"conhecereis-a-verdade-e-a-verdade-vos-libertara-jo-832","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/conhecereis-a-verdade-e-a-verdade-vos-libertara-jo-832\/","title":{"rendered":"\u00abConhecereis a verdade e a verdade vos libertar\u00e1\u00bb (Jo 8,32)"},"content":{"rendered":"<p><em>Padre Miguel Neto, Diocese do Algarve<\/em><\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_167647\" aria-describedby=\"caption-attachment-167647\" style=\"width: 391px\" class=\"wp-caption alignright\"><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/03\/Miguel_Neto.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-167647 size-medium\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/03\/Miguel_Neto-391x260.jpg\" alt=\"\" width=\"391\" height=\"260\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/03\/Miguel_Neto-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/03\/Miguel_Neto-1024x681.jpg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/03\/Miguel_Neto-768x511.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/03\/Miguel_Neto-1080x719.jpg 1080w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/03\/Miguel_Neto-980x652.jpg 980w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/03\/Miguel_Neto-480x319.jpg 480w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/03\/Miguel_Neto.jpg 1142w\" sizes=\"(max-width: 391px) 100vw, 391px\" \/><\/a><figcaption id=\"caption-attachment-167647\" class=\"wp-caption-text\">Padre Miguel Neto<\/figcaption><\/figure>\n<p>Aquele que todos os Crist\u00e3os devem seguir manda-nos, desde sempre, conhecer a verdade e anunci\u00e1-la ao mundo. \u00c9 esse um dos mais importantes mandatos divinos. \u00c9 essa uma das formas mais sublimes, pr\u00e1ticas, concretas de anunciar o Evangelho aos povos. Mesmo sabendo que \u00e9 uma frase de um dos Evangelhos Ap\u00f3crifos (mais precisamente do Evangelho de Nicodemos), esta passagem, nos \u00faltimos dias, n\u00e3o sai da minha cabe\u00e7a: \u201c\u00abJesus diz a Pilatos: -\u201cV\u00eas como os que dizem a verdade s\u00e3o julgados por aqueles que t\u00eam autoridade na terra\u00bb. Vem-me ao pensamento a prop\u00f3sito do Relat\u00f3rio Final da Comiss\u00e3o Independente para o estudo dos abusos sexuais de crian\u00e7as na Igreja Cat\u00f3lica Portuguesa. E vem-me \u00e0 cabe\u00e7a, n\u00e3o porque gostasse aqui de analisar o conte\u00fado desse t\u00e3o importante documento, mas de deter o meu olhar sobre o que se disse mediaticamente acerca do mesmo.<\/p>\n<p>Num primeiro ponto, entriste\u00e7o-me quando pessoas crist\u00e3s e n\u00e3o crist\u00e3s real\u00e7am, somente, o encobrimento dos casos e n\u00e3o olham com admira\u00e7\u00e3o para a Confer\u00eancia Episcopal Portuguesa (CEP), sobretudo para o seu presidente, D. Jos\u00e9 Ornelas, que em 2021 teve a coragem, contra muitas vozes internas da Igreja Cat\u00f3lica Portuguesa, de avan\u00e7ar para a cria\u00e7\u00e3o de uma comiss\u00e3o totalmente independente, que permitisse um conhecimento profundo desta quest\u00e3o. Noutros pa\u00edses tradicionalmente crist\u00e3os, como por exemplo a Espanha e a It\u00e1lia, as Confer\u00eancias Episcopais ou n\u00e3o avan\u00e7aram por medo, ou tiveram de reagir pressionadas pelo governo. Aqui n\u00e3o! Foi uma atitude livre, consciente, de quem queria, finalmente, saber a verdade que escondia esta monstruosidade, praticada por pessoas possuidoras de parafilia sexual, que simultaneamente s\u00e3o cl\u00e9rigos, ou agentes de pastoral com poder de decis\u00e3o. Fez-se mal em encobrir? FEZ-SE! Mas a atitude, agora, n\u00e3o \u00e9 essa, ou n\u00e3o se teria avan\u00e7ado para a produ\u00e7\u00e3o desta investiga\u00e7\u00e3o. N\u00e3o creio que seja produtivo, ou mais ainda, justo criticar quem est\u00e1 a fazer o que lhe compete, mesmo com dificuldades. E se n\u00e3o as veem, procurem alguns artigos de ilustres membros do clero na imprensa; procurem nas redes sociais, porque rapidamente encontrar\u00e3o quem manifeste o lado mais triste da Igreja, o lado que n\u00e3o v\u00ea com bons olhos este revelar do que n\u00e3o deveria jamais ter acontecido. Argumentam de um modo que me impressiona (para n\u00e3o usar uma linguagem mais pesada, mas mais expressiva!), esgrimindo algo que, para mim, \u00e9 vergonhoso, enquanto crist\u00e3o cat\u00f3lico: que abusos sexuais ocorridos no contexto familiar e laboral diminuem a import\u00e2ncia dos abusos sexuais dentro da Igreja Cat\u00f3lica. Nem que houvesse uma s\u00f3 v\u00edtima, como disse o Papa Francisco, o pecado seria menor! E seguindo esta linha de racioc\u00ednio, coloquem-se no lugar de D. Jos\u00e9 Ornelas e de outros, que tiveram e t\u00eam nas m\u00e3os um processo que ser\u00e1 dos mais duros e complexos de conduzir. Talvez percebam como foi\/foram corajosos e dignos. Mas, l\u00e1 est\u00e1, \u00abos que dizem a verdade s\u00e3o julgados por aqueles que t\u00eam autoridade na terra\u00bb \u2026<\/p>\n<p>Outro ponto da quest\u00e3o que, tamb\u00e9m j\u00e1 come\u00e7a a ser aflorado por v\u00e1rias vozes e sempre me preocupou sobremaneira, prende-se com a forma\u00e7\u00e3o dos sacerdotes, uma forma\u00e7\u00e3o anacr\u00f3nica e que impede o desenvolvimento de uma verdadeira intelig\u00eancia emocional. E questiono-me: como \u00e9 que algu\u00e9m (ou tantas pessoas doentes) consegue sobreviver a anos e anos de semin\u00e1rio\/forma\u00e7\u00e3o, durante os quais (supostamente) vive escrutinado e em comunidade, 24 sobre 24 horas, sem que algu\u00e9m reparasse que estava diante de um doente, que n\u00e3o tinha condi\u00e7\u00f5es ps\u00edquicas para exercer qualquer minist\u00e9rio na Igreja Cat\u00f3lica? Mais: durante o processo de sele\u00e7\u00e3o daqueles que passaram pelo sacramento da ordem, de que modo foram respondidas as v\u00e1rias proclamas (question\u00e1rios feitos a pessoas muito diversas), sem que esse assunto fosse abordado, aprofundado, evidenciado? Como \u00e9 que uma Institui\u00e7\u00e3o que faz da Moral Sexual dos seus fi\u00e9is um dos basti\u00f5es fort\u00edssimos da sua perten\u00e7a em plenitude, n\u00e3o olha para as doen\u00e7as sexuais de alguns dos membros do clero e agentes de Pastoral, nomeadamente quando os prepara?<\/p>\n<p>Na verdade, n\u00e3o ouvi, nesses mon\u00f3logos, ou di\u00e1logos medi\u00e1ticos dos \u00faltimos dias, algu\u00e9m questionar porque \u00e9 admitimos pessoas na hierarquia da Igreja (e em lugares de decis\u00e3o) possuidoras de uma parafilia sexual, que atenta contra a vida de inocentes. Se um dos meus irm\u00e3os cometesse um crime, eu n\u00e3o estaria preocupado em perceber o fen\u00f3meno da criminalidade no mundo, mas estaria profundamente interessado em saber como, porqu\u00ea e onde falh\u00e1mos como fam\u00edlia, para que tal pudesse acontecer!<\/p>\n<p>Por isso, a mim n\u00e3o me interessam os n\u00fameros das doen\u00e7as ps\u00edquicas e sexuais fora da Igreja Cat\u00f3lica, mas sim, os n\u00fameros de membros do clero e agentes de pastoral da Igreja Cat\u00f3lica, que, n\u00e3o tendo condi\u00e7\u00f5es ps\u00edquicas e sexuais para exercer essas fun\u00e7\u00f5es, est\u00e3o a exerc\u00ea-las na Igreja, a mesma institui\u00e7\u00e3o que \u00e9 a garante da presen\u00e7a de Deus no mundo e, por isso, tem de dar o exemplo a todos, sob pena de que a sua credibilidade ser nula.<\/p>\n<p>E n\u00e3o pensem j\u00e1 os mais obstinados com a moral sexual, que a origem deste problema se centra na homossexualidade, heterossexualidade, ou na continuidade (ou n\u00e3o) da disciplina do celibato sacerdotal. Para mim, o foco da quest\u00e3o est\u00e1 em dois itens: na dete\u00e7\u00e3o das doen\u00e7as que anteriormente mencionei &#8211; e se os atos s\u00e3o crime, quem os pratica \u00e9 doente, n\u00e3o esque\u00e7amos! &#8211; e numa aposta forte e consciente nas rela\u00e7\u00f5es humanas e interpessoais, que permitissem que, durante a sua forma\u00e7\u00e3o, os futuros sacerdotes (e mesmo os agentes de pastoral) compreendessem que \u00e9 imprescind\u00edvel valorizar a capacidade de rela\u00e7\u00e3o humana, o di\u00e1logo, a toler\u00e2ncia, a compreens\u00e3o. De que serve ter um semin\u00e1rio cheio de jovens e de pessoas \u00e0 volta destes, se nesse espa\u00e7o s\u00f3 h\u00e1 lugar para a certeza lit\u00fargica, para a moral e os dogmas e muitos preconceitos, esquecendo que o centro da forma\u00e7\u00e3o de um futuro padre deve ser a preocupa\u00e7\u00e3o de entender (e fazer entender) que a sua miss\u00e3o \u00e9, antes e mais que tudo, trazer Deus \u00e0s vidas daqueles que estiverem nas suas comunidades?<\/p>\n<p>Melhor seria se se encorajasse firmemente os seminaristas a conhecerem-se, a respeitarem-se, a procurarem um caminho de felicidade; melhor seria se se promovesse neles uma vontade, preocupa\u00e7\u00e3o de discernir, de forma mais assertiva, aquelas que s\u00e3o as reais preocupa\u00e7\u00f5es das pessoas; melhor seria, sem qualquer sombra de d\u00favida, se se promovesse um acompanhamento mais cuidado daqueles que revelassem, nesse percurso formativo, problemas sexuais\/psiqui\u00e1tricos, para garantir que a Igreja, que \u00e9 m\u00e3e e acolhedora, tivesse uma resposta caridosa e competente para cada um: os que fossem capazes de chegar ao sacerd\u00f3cio e os que, por quest\u00f5es de sa\u00fade, n\u00e3o pudessem ser ordenados.<\/p>\n<p>Se n\u00e3o alterarmos procedimentos, olhares, formas de reagir\/agir nada mudar\u00e1 e dentro de algum tempo estaremos a apontar mais e mais casos tristes.\u00a0 E, se assim for, de que vale passar por tudo isto, por este processo que implica o favorecimento de uma imagem altamente negativa de todos n\u00f3s, que somos sacerdotes, ordenados, leigos empenhados, ainda que n\u00e3o sejamos todos abusadores?<\/p>\n<p>A resposta est\u00e1 na frase que me assalta constantemente: \u00abConhecereis a verdade e a verdade vos libertar\u00e1\u00bb (Jo 8,32). \u00c9 preciso fazer da verdade uma bandeira, permanentemente desfraldada ao vento, para que nada se oculte e s\u00f3 brilhe, limpa e pura, a Palavra, o Amor de Deus e ao pr\u00f3ximo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Padre Miguel Neto, Diocese do Algarve<\/p>\n","protected":false},"author":1,"featured_media":167647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[10],"tags":[],"class_list":["post-273186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniao"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/273186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=273186"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/273186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/167647"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=273186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=273186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=273186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}