{"id":27185,"date":"2007-09-25T15:16:56","date_gmt":"2007-09-25T15:16:56","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2007\/09\/25\/centenario-da-igreja-de-milheiros-de-poiares\/"},"modified":"2007-09-25T15:16:56","modified_gmt":"2007-09-25T15:16:56","slug":"centenario-da-igreja-de-milheiros-de-poiares","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/centenario-da-igreja-de-milheiros-de-poiares\/","title":{"rendered":"Centen\u00e1rio da Igreja de Milheir\u00f3s de Poiares"},"content":{"rendered":"<p>A Comiss\u00e3o Organizadora do 1\u00ba Centen\u00e1rio da Igreja de Milheir\u00f3s de Poiares (Santa Maria da Feira) promove, nos dias 28, 29 e 30 de Setembro, um conjunto de actividades culturais e religiosas para assinalar a efem\u00e9ride. A inaugura\u00e7\u00e3o de uma exposi\u00e7\u00e3o evocativa, o lan\u00e7amento de uma revista e a realiza\u00e7\u00e3o de um sarau cultural marcam o programa de comemora\u00e7\u00f5es.  Inaugurada a 18 de Maio de 1907, a Igreja de Milheir\u00f3s de Poiares foi alvo de diversas interven\u00e7\u00f5es e obras de restauro, sendo que a mais significativa decorreu entre 1984 e 1987. Um comunicado da C\u00e2mara Municipal da Feira enviado \u00e0 Ag\u00eancia ECCLESIA real\u00e7a que &#8220;s\u00e3o escassos os registos que documentam a evolu\u00e7\u00e3o desta igreja ao longo dos tempos, sobretudo durante os primeiros cinquenta anos de vida&#8221;.  No pr\u00f3ximo dia 29 de Setembro ser\u00e1 inaugurada uma exposi\u00e7\u00e3o de fotografias, livros e objectos, no audit\u00f3rio do Centro Paroquial, que &#8220;documentam o importante papel que esta igreja desempenhou, e continua a desempenhar, no seio da sua comunidade&#8221; &#8211; sublinha o comunicado. Na mesma data ser\u00e1 lan\u00e7ada a revista \u201c1\u00ba Centen\u00e1rio da Igreja Paroquial de Milheir\u00f3s de Poiares\u201d, que conta com a participa\u00e7\u00e3o do Bispo Auxiliar de Lisboa, D. Carlos Azevedo, do professor Manuel Joaquim Concei\u00e7\u00e3o e dos padres Manuel Le\u00e3o e Fernando Gon\u00e7alves, sendo que todos eles escreveram sobre temas relacionados com a Igreja de Milheir\u00f3s de Poiares. A apresenta\u00e7\u00e3o da revista estar\u00e1 a cargo do presidente do Centro Regional do Porto da Universidade Cat\u00f3lica Portuguesa, Manuel Joaquim Azevedo. <b>Programa das Comemora\u00e7\u00f5es<\/b> &#8211; 28 de Setembro \/ 21h30 \/ Cine-Teatro S. Miguel Sarau cultural, pelas colectividades de Milheir\u00f3s de Poiares &#8211; 29 de Setembro \/ 17h30 \/ audit\u00f3rio do Centro Paroquial Inaugura\u00e7\u00e3o de exposi\u00e7\u00e3o evocativa Lan\u00e7amento da revista \u201c1\u00ba Centen\u00e1rio da Igreja Paroquial de Milheir\u00f3s de Poiares\u201d 19h00\/ Igreja Paroquial de Milheir\u00f3s de Poiares Missa Solene presidida por D. Manuel Clemente, Bispo do Porto &#8211; 30 de Setembro \/ 11h00 \/ Igreja Paroquial de Milheir\u00f3s de Poiares Missa Crismal presidida por D. Carlos Azevedo, Bispo Auxiliar de Lisboa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o Organizadora do 1\u00ba Centen\u00e1rio da Igreja de Milheir\u00f3s de Poiares (Santa Maria da Feira) promove, nos dias 28, 29 e 30 de Setembro, um conjunto de actividades culturais e religiosas para assinalar a efem\u00e9ride. A inaugura\u00e7\u00e3o de uma exposi\u00e7\u00e3o evocativa, o lan\u00e7amento de uma revista e a realiza\u00e7\u00e3o de um sarau cultural marcam [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[187],"class_list":["post-27185","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-diocese-do-porto"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/27185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=27185"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/27185\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=27185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=27185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=27185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}