{"id":25785,"date":"2007-07-07T13:04:32","date_gmt":"2007-07-07T13:04:32","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2007\/07\/07\/para-compostela-desde-o-alentejo\/"},"modified":"2007-07-07T13:04:32","modified_gmt":"2007-07-07T13:04:32","slug":"para-compostela-desde-o-alentejo","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/para-compostela-desde-o-alentejo\/","title":{"rendered":"Para Compostela desde o Alentejo"},"content":{"rendered":"<p>Exposi\u00e7\u00e3o mostra que o Caminho de Santiago \u00e9 hoje uma realidade que come\u00e7a a despontar no Baixo Alentejo <!--more--> Durante muitos anos esquecido, o Caminho de Santiago \u00e9 hoje uma realidade que come\u00e7a a despontar em terras do Baixo Alentejo. A ideia de que este itiner\u00e1rio de peregrina\u00e7\u00e3o para Compostela se iniciava apenas no Norte de Portugal \u00e9 um mito. A Diocese de Beja, o Munic\u00edpio de Santiago do Cac\u00e9m e o Governo Regional da Galiza unem esfor\u00e7os para dar a conhecer o not\u00e1vel patrim\u00f3nio espiritual, art\u00edstico e antropol\u00f3gico associado ao Caminho numa exposi\u00e7\u00e3o que tem como palco um dos mais belos monumentos do G\u00f3tico alentejano, a igreja matriz de Santiago do Cac\u00e9m, alvo de importantes obras de requalifica\u00e7\u00e3o. O presidente da Rep\u00fablica, An\u00edbal Cavaco Silva, inaugura esta iniciativa no dia 11 de Julho.  O culto de Santiago, na sua irradia\u00e7\u00e3o europeia e internacional, e o fen\u00f3meno da peregrina\u00e7\u00e3o que lhe est\u00e1 associado s\u00e3o o mote para uma exposi\u00e7\u00e3o, iniciativa tripartida do Departamento do Patrim\u00f3nio Hist\u00f3rico e Art\u00edstico da Diocese de Beja, do Munic\u00edpio de Santiago do Cac\u00e9m e da Xunta de Galicia que se prefigura como um dos acontecimentos culturais do Ver\u00e3o.       Centrando-se na figura de Santiago Maior (Ap\u00f3stolo, Peregrino, Cavaleiro, Refer\u00eancia da Reconquista), a iniciativa \u00e9 comissariada por Jos\u00e9 Ant\u00f3nio Falc\u00e3o, director do Departamento do Patrim\u00f3nio Hist\u00f3rico e Art\u00edstico da Diocese de Beja. \u201cNo Caminho sob as Estrelas \u2013 Santiago e a Peregrina\u00e7\u00e3o a Compostela\u201d re\u00fane cerca de 150 obras de arte e documentos, dos s\u00e9culos X a XXI, vindas de museus, igrejas e colec\u00e7\u00f5es particulares de Espanha e Portugal, mas tamb\u00e9m de Fran\u00e7a, Alemanha, It\u00e1lia, Inglaterra, Flandres, M\u00e9xico, Peru, Bol\u00edvia e Col\u00f4mbia. Em paralelo, numa interven\u00e7\u00e3o contempor\u00e2nea, foi encomendada uma pe\u00e7a \u00e0 artista Joana Vasconcelos, a incluir futuramente no Tesouro da Colegiada de Santiago.       Para al\u00e9m do valor dos elementos de arte sacra, releva da exposi\u00e7\u00e3o uma forte dimens\u00e3o hist\u00f3rica e antropol\u00f3gica, integrando pe\u00e7as de grande interesse desse ponto de vista (como \u00e9 o caso de um Santiago Mata-Espanh\u00f3is, trabalho peruano do s\u00e9c. XIX, entre outros).  Santiago do Cac\u00e9m constitui, pelo seu significado hist\u00f3rico, uma refer\u00eancia fundamental para a identidade do Alentejo Litoral. \u00c9 nesta cidade que se encontra o principal conjunto monumental da zona. Existe actualmente um esfor\u00e7o muito grande para recuperar as suas ra\u00edzes e o seu patrim\u00f3nio, sem esquecer a liga\u00e7\u00e3o ao Caminho de Santiago, ao culto do ap\u00f3stolo e \u00e0 Ordem Militar de Santiago da Espada. De facto, n\u00e3o \u00e9 poss\u00edvel de ignorar a clareza de muitos ind\u00edcios das ra\u00edzes de Santiago do Cac\u00e9m: sinais da vinda de colonos galegos nos s\u00e9culos XII-XIII (top\u00f3nimos como Galiza, Espanha, Melides e Santo Andr\u00e9 s\u00e3o muito expl\u00edcito a este respeito), liga\u00e7\u00f5es ao culto de Santiago e a Compostela, testemunhos da presen\u00e7a da Ordem Militar de Santiago de Espada, que neste concelho teve uma das suas principais e mais ricas comendas.       O projecto foi realizado com o apoio institucional da Sociedade An\u00f3nima do Xacobeo, institui\u00e7\u00e3o estatal galega ligada ao turismo de Santiago de Compostela e traduz um investimento aut\u00e1rquico e diocesano de meio milh\u00e3o de euros. Pretende-se que a exposi\u00e7\u00e3o contribua para a afirma\u00e7\u00e3o de Santiago do Cac\u00e9m como um destino privilegiado do turismo cultural, para a valoriza\u00e7\u00e3o do centro hist\u00f3rico da cidade e para a divulga\u00e7\u00e3o da cultura galega, numa l\u00f3gica de estreitamento de rela\u00e7\u00f5es entre dois territ\u00f3rios ib\u00e9ricos que conduza a uma aproxima\u00e7\u00e3o estrat\u00e9gica.       A iniciativa marca o princ\u00edpio de um ciclo de parcerias com a Xunta de Galicia que prev\u00ea a realiza\u00e7\u00e3o pr\u00f3xima dos Encontros Galaico-Portugueses, com car\u00e1cter regular, de ciclos de concertos e, ainda, a cria\u00e7\u00e3o de um Centro de Estudos Jacobeus. Este \u00faltimo ficar\u00e1 sediado no edif\u00edcio dos antigos Pa\u00e7os do Concelho em Santiago do Cac\u00e9m e ter\u00e1 como miss\u00e3o promover o estudo e a divulga\u00e7\u00e3o do patrim\u00f3nio ligado ao culto de Santiago Maior, ao fen\u00f3meno das peregrina\u00e7\u00f5es e \u00e0 sua liga\u00e7\u00e3o \u00e0 Hist\u00f3ria Local. A nova institui\u00e7\u00e3o levar\u00e1 a cabo cursos de Ver\u00e3o com o apoio de universidades portuguesas e estrangeiras, exposi\u00e7\u00f5es tem\u00e1ticas, confer\u00eancias e outras actividades culturais relacionadas com estes objectivos. Dispor\u00e1 igualmente de um centro de documenta\u00e7\u00e3o e de uma biblioteca especializada, organizados com o apoio da Xunta de Galicia.   <b>Uma longa conjuntura hist\u00f3rica a recuperar<\/b>      A regi\u00e3o de Santiago do Cac\u00e9m possui uma profunda vincula\u00e7\u00e3o ao culto de Santiago Ap\u00f3stolo, ao Caminho de Santiago e \u00e0 Ordem Militar de Santiago de Espada (aqui estabelecida desde o s\u00e9culo XIII at\u00e9 \u00e0 sua extin\u00e7\u00e3o, em 1834). Esta vincula\u00e7\u00e3o remonta a \u00e9pocas muito antigas e prende-se \u00e0 exist\u00eancia de uma via de peregrina\u00e7\u00e3o que unia o \u201cPromont\u00f3rio Sacro\u201d \u2013 o Cabo de S\u00e3o Vicente \u2013 ao Noroeste Peninsular e passava ao longo da plan\u00edcie litoral, bordejando o oceano Atl\u00e2ntico e vencendo os rios Mira e Sado.        O Caminho de Santiago constituiu, ap\u00f3s a queda do Imp\u00e9rio Romano, uma estrutura fundamental para a circula\u00e7\u00e3o de pessoas, bens e ideias por todo o continente europeu. O Conselho da Europa reconheceu a import\u00e2ncia matricial desta realidade hist\u00f3rica, declarando o Caminho como o primeiro Itiner\u00e1rio Cultural Europeu. \u00c9 fundamental que tamb\u00e9m o Sul do nosso pa\u00eds reencontre os seus percursos neste \u00e2mbito e possa actuar em rede com outras regi\u00f5es do velho continente para a afirma\u00e7\u00e3o de uma heran\u00e7a cultural comum.       Santiago do Cac\u00e9m deve o seu nome e boa parte da sua prosperidade precisamente \u00e0 liga\u00e7\u00e3o \u00e0 devo\u00e7\u00e3o de Santiago Maior e \u00e0 passagem dos peregrinos, que tinham na igreja matriz desta localidade (not\u00e1vel edif\u00edcio da \u00e9poca g\u00f3tica, encastrado no conjunto do castelo e da autoria de um arquitecto aragon\u00eas ou catal\u00e3o) um santu\u00e1rio complementar no seu itiner\u00e1rio para Compostela e dispunham de outras infra-estruturas de acolhimento, como o Hospital do Esp\u00edrito Santo. A Ordem Militar de Santiago, que recebeu extensos territ\u00f3rios na regi\u00e3o ap\u00f3s a Reconquista, tomou tamb\u00e9m a seu cargo a protec\u00e7\u00e3o e o apoio espiritual aos peregrinos, cuja circula\u00e7\u00e3o significava riqueza e import\u00e2ncia pol\u00edtica e religioso, mas exigia tamb\u00e9m assist\u00eancia.        O segmento do Caminho de Santiago que passava pelo Alentejo Litoral caiu no esquecimento a partir das invas\u00f5es francesas, nos in\u00edcios do s\u00e9culo XIX, mas tem-se notado um gradual recrudescimento da passagem dos peregrinos, sobretudo a p\u00e9, a cavalo e de bicicleta, que v\u00eam solicitar na igreja matriz de Santiago do Cac\u00e9m e noutros templos da zona a aposi\u00e7\u00e3o da \u201cCompostelana\u201d (carimbo que atesta a passagem, para poderem obter benef\u00edcios espirituais) no Passaporte do Peregrino.   <b> Santiago Maior <\/b>      O ap\u00f3stolo Santiago Maior, filho de Zebedeu e Salom\u00e9 e irm\u00e3o de S\u00e3o Jo\u00e3o Evangelista, nasceu na Galileia. Pescador, tornou-se um dos disc\u00edpulos mais destacados de Jesus. Sofreu o mart\u00edrio em Jerusal\u00e9m no ano 44. A tradi\u00e7\u00e3o aponta-o com o evangelizador da Pen\u00ednsula Ib\u00e9rica e diz ter recebido em Sarago\u00e7a a apari\u00e7\u00e3o de Nossa Senhora do Pilar. Desde os meados do s\u00e9culo IX que lhe \u00e9 prestado o culto em Santiago de Compostela, local para onde ter\u00e3o sido levadas as suas rel\u00edquias.       Santiago aparece geralmente representado como ap\u00f3stolo, peregrino ou guerreiro. Este \u00faltimo tipo, o mais difundido no Sul de Portugal, recorda a lenda da sua apari\u00e7\u00e3o na batalha de Clavijo, em 834, triunfando sobre os Mouros. Padroeiro das Espanhas, deu tamb\u00e9m a uma Ordem militar que teve importante papel na Reconquista. Os seus principais atributos s\u00e3o a vieira, o bast\u00e3o, o chap\u00e9u e a caba\u00e7a de peregrino, a que se juntam por vezes o livro (s\u00edmbolo dos ap\u00f3stolos) e a palma (s\u00edmbolo dos m\u00e1rtires). Como cavaleiro, empunha uma espada. A sua festa lit\u00fargica celebra-se no dia 25 de Julho.      <i> Departamento do Patrim\u00f3nio Hist\u00f3rico e Art\u00edstico da Diocese de Beja <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Exposi\u00e7\u00e3o mostra que o Caminho de Santiago \u00e9 hoje uma realidade que come\u00e7a a despontar no Baixo Alentejo<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[119,171,203,285,299,320],"class_list":["post-25785","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-arte-sacra","tag-diocese-de-beja","tag-europa","tag-patrimonio","tag-santiago-de-compostela","tag-turismo"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/25785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=25785"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/25785\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=25785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=25785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=25785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}