{"id":253713,"date":"2022-09-19T16:12:54","date_gmt":"2022-09-19T15:12:54","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=253713"},"modified":"2022-09-21T09:10:17","modified_gmt":"2022-09-21T08:10:17","slug":"igreja-portugal-dialogo-sem-fronteiras-e-o-caminho-para-a-missao-da-igreja-padre-adelino-ascenso-c-video","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/igreja-portugal-dialogo-sem-fronteiras-e-o-caminho-para-a-missao-da-igreja-padre-adelino-ascenso-c-video\/","title":{"rendered":"Igreja\/Portugal: \u00abDi\u00e1logo sem fronteiras\u00bb \u00e9 o caminho para a miss\u00e3o da Igreja \u2013 Padre Adelino Ascenso (c\/v\u00eddeo)"},"content":{"rendered":"<p><em>Superior geral da Sociedade da Boa Nova destaca import\u00e2ncia do Congreso Mission\u00e1rio 2022<\/em><!--more--><\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_84209\"  width=\"480\" height=\"270\"  data-origwidth=\"480\" data-origheight=\"270\" src=\"https:\/\/www.youtube.com\/embed\/JOExp4EwCSo?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=pt&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>Lisboa, 19 set 2022 (Ecclesia) \u2013 O padre Adelino Ascenso, superior geral da Sociedade Mission\u00e1ria da Boa Nova, disse \u00e0 Ag\u00eancia ECCLESIA que a miss\u00e3o da Igreja passa por um \u201cdi\u00e1logo sem fronteiras\u201d, uma op\u00e7\u00e3o \u201cincontorn\u00e1vel\u201d para os cat\u00f3licos.<\/p>\n<p>\u201cA miss\u00e3o em si ter\u00e1 de passar por a\u00ed, pelo di\u00e1logo sem fronteiras\u201d, referiu o sacerdote, projetando o Congresso Mission\u00e1rio 2022, que vai decorrer em Lisboa, entre 14 e 15 de outubro.<\/p>\n<p>O entrevistado adianta que \u201cexistem algumas atividades, essencialmente no campo do di\u00e1logo inter-religioso e campo intercultural\u201d que mostram o caminho percorrido, em Portugal.<\/p>\n<p>As congrega\u00e7\u00f5es mission\u00e1rias e a Confer\u00eancia Episcopal Portuguesa (CEP) a organizar o congresso \u2018Fraternidade sem fronteiras\u2019, que vai decorrer no audit\u00f3rio Cardeal Medeiros, da Universidade Cat\u00f3lica Portuguesa, em Lisboa.<\/p>\n<p>O entrevistado desta segunda-feira no Programa ECCLESIA (RTP2) sublinha que \u00e9 preciso pensar o di\u00e1logo \u201cem tr\u00eas focos ou portais importantes: di\u00e1logo inter-religioso; di\u00e1logo com os indiferentes e di\u00e1logo com a cultura\u201d.<\/p>\n<p>O superior geral da Sociedade Mission\u00e1ria da Boa Nova salienta que o mission\u00e1rio \u201cn\u00e3o pode ir diretamente converter, ele deve ir para acompanhar as pessoas\u201d.<\/p>\n<p>\u201cOs mission\u00e1rios devem ir abertos ao diferente, s\u00f3 assim se pode trilhar um caminho\u201d, acentua o padre Adelino Ascenso, antigo mission\u00e1rio no Jap\u00e3o.<\/p>\n<p>O acompanhamento \u201cmoldou a forma de ser mission\u00e1rio\u201d porque \u201co proselitismo pode provocar crispa\u00e7\u00f5es e afastamentos\u201d, acrescenta.<\/p>\n<blockquote><p>Em vez de irmos converter pessoas, n\u00f3s vamos em primeiro lugar para nos convertermos a n\u00f3s pr\u00f3prios. E penso que o paradigma da miss\u00e3o ter\u00e1 de passar um pouco por a\u00ed: N\u00e3o termos a pretens\u00e3o de que vamos converter algu\u00e9m mas termos o desejo bem vincado de nos convertermos a n\u00f3s pr\u00f3prios\u201d.<\/p><\/blockquote>\n<p>O sacerdote sublinha que o Congresso Mission\u00e1rio 2022 quer ser \u201cum servi\u00e7o que a Igreja presta aos participantes\u201d, tanto para as pessoas que v\u00e3o estar como para quem vai acompanhar este encontro pelos meios digitais.<\/p>\n<p>\u201cSe vivemos com paix\u00e3o a nossa f\u00e9, n\u00f3s transmitimos isso atrav\u00e9s do testemunho, forma de agir e n\u00e3o \u00e9 necess\u00e1rio palavras\u201d, afirmou.<\/p>\n<p><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/09\/congresso-missionario2022-logo-980x653-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-253716 alignright\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/09\/congresso-missionario2022-logo-980x653-1-390x260.jpg\" alt=\"\" width=\"390\" height=\"260\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/09\/congresso-missionario2022-logo-980x653-1-390x260.jpg 390w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/09\/congresso-missionario2022-logo-980x653-1-768x512.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/09\/congresso-missionario2022-logo-980x653-1-391x260.jpg 391w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/09\/congresso-missionario2022-logo-980x653-1-480x320.jpg 480w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/09\/congresso-missionario2022-logo-980x653-1.jpg 980w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/a>O congresso inclui seis confer\u00eancias e dois pain\u00e9is &#8211; sobre as religi\u00f5es monote\u00edstas e sobre as religi\u00f5es m\u00edsticas, o hindu\u00edsmo, o budismo e o catolicismo.<\/p>\n<p>A organiza\u00e7\u00e3o do congresso mission\u00e1rio convidou o prefeito do Dicast\u00e9rio para o Di\u00e1logo Inter-Religioso (Santa S\u00e9), cardeal Miguel \u00c1ngel Ayuso Guixot, para apresentar a \u201cFraternidade sem Fronteiras e o Documento de Abu Dhabi\u201d; ainda no primeiro dia, v\u00e3o intervir a reitora da UCP, Isabel Capeloa Gil, e Guilherme d\u2019Oliveira Martins.<\/p>\n<p>No segundo dia, os participantes v\u00e3o ouvir D. Jos\u00e9 Ornelas, bispo de Leiria-F\u00e1tima e presidente da CEP; Diana de Vallescar Palanca, sobre interculturalidade e di\u00e1logo inter-religioso; e o cardeal Jos\u00e9 Tolentino Mendon\u00e7a, bibliotec\u00e1rio e arquivista da Santa S\u00e9.<\/p>\n<p>As inscri\u00e7\u00f5es online podem ser efetuadas no s\u00edtio <a href=\"https:\/\/conferenciaepiscopal.pt\/congressomissio22\/\" target=\"_blank\" rel=\"noopener\">online<\/a> da Confer\u00eancia Episcopal Portuguesa (CEP) e das Obras Mission\u00e1rias Pontif\u00edcias \u2013 Portugal, onde tamb\u00e9m pode ser consultado o programa, descarregado o cartaz e o desdobr\u00e1vel com v\u00e1rias informa\u00e7\u00f5es.<\/p>\n<p><em>HM\/LFS\/OC<\/em><\/p>\n<p>&nbsp;<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"Kqod2qbqEJ\"><p><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/fratelli-tutti-papa-destaca-papel-das-religioes-em-favor-da-fraternidade-humana\/\">\u00abFratelli Tutti\u00bb: Papa destaca papel das religi\u00f5es em favor da fraternidade humana<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;\u00abFratelli Tutti\u00bb: Papa destaca papel das religi\u00f5es em favor da fraternidade humana&#8221; &#8212; Ag\u00eancia ECCLESIA\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/fratelli-tutti-papa-destaca-papel-das-religioes-em-favor-da-fraternidade-humana\/embed\/#?secret=LUukZeVGmy#?secret=Kqod2qbqEJ\" data-secret=\"Kqod2qbqEJ\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Superior geral da Sociedade da Boa Nova destaca import\u00e2ncia do Congreso Mission\u00e1rio 2022<\/p>\n","protected":false},"author":2,"featured_media":253717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[89,3],"tags":[261],"class_list":["post-253713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque2","category-nacional","tag-missoes"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/253713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=253713"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/253713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/253717"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=253713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=253713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=253713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}