{"id":240732,"date":"2022-05-16T09:57:39","date_gmt":"2022-05-16T08:57:39","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=240732"},"modified":"2022-05-17T16:01:33","modified_gmt":"2022-05-17T15:01:33","slug":"porto-assembleia-diocesana-assumiu-intencao-de-prosseguir-percurso-sinodal","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/porto-assembleia-diocesana-assumiu-intencao-de-prosseguir-percurso-sinodal\/","title":{"rendered":"Porto: Assembleia Diocesana assumiu inten\u00e7\u00e3o de prosseguir percurso sinodal"},"content":{"rendered":"<p><em>Encontro reuniu mais de duas centenas de representantes de par\u00f3quias, movimentos e institutos<\/em><!--more--><\/p>\n<div id='gallery-1' class='gallery galleryid-240732 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/porto-assembleia-diocesana-assumiu-intencao-de-prosseguir-percurso-sinodal\/sinodo6-1024x769\/'><img fetchpriority=\"high\" decoding=\"async\" width=\"346\" height=\"260\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo6-1024x769-1-346x260.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-240741\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo6-1024x769-1-346x260.jpg 346w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo6-1024x769-1-768x577.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo6-1024x769-1-510x382.jpg 510w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo6-1024x769-1-980x736.jpg 980w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo6-1024x769-1-480x360.jpg 480w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo6-1024x769-1.jpg 1024w\" sizes=\"(max-width: 346px) 100vw, 346px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-240741'>\n\t\t\t\tFoto: Voz Portucalense\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/porto-assembleia-diocesana-assumiu-intencao-de-prosseguir-percurso-sinodal\/sinodo4-678x381\/'><img decoding=\"async\" width=\"400\" height=\"225\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo4-678x381-1-400x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-240740\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo4-678x381-1-400x225.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo4-678x381-1-480x270.jpg 480w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo4-678x381-1.jpg 678w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-240740'>\n\t\t\t\tFoto: Voz Portucalense\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/agencia.ecclesia.pt\/portal\/porto-assembleia-diocesana-assumiu-intencao-de-prosseguir-percurso-sinodal\/sinodo7-1024x769\/'><img decoding=\"async\" width=\"346\" height=\"260\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo7-1024x769-1-346x260.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-240742\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo7-1024x769-1-346x260.jpg 346w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo7-1024x769-1-768x577.jpg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo7-1024x769-1-510x382.jpg 510w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo7-1024x769-1-980x736.jpg 980w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo7-1024x769-1-480x360.jpg 480w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/sinodo7-1024x769-1.jpg 1024w\" sizes=\"(max-width: 346px) 100vw, 346px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-240742'>\n\t\t\t\tFoto: Voz Portucalense\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>Porto, 16 mai 2022 (Ecclesia) \u2013 A Diocese do Porto promoveu este s\u00e1bado, na Casa de Vilar, uma assembleia pr\u00e9-sinodal que reuniu mais de duas centenas de representantes de par\u00f3quias, movimentos e institutos.<\/p>\n<p>O coordenador da Comiss\u00e3o Sinodal Diocesana do Porto, c\u00f3nego Joaquim Santos, apresentou dados relativos ao trabalho da Comiss\u00e3o, salientando as vantagens dos encontros sinodais presenciais.<\/p>\n<p>Segundos os n\u00fameros divulgados pelo jornal diocesano \u2018Voz Portucalense\u2019 (VP), houve 181 respostas de grupo, enviadas por par\u00f3quias, grupos de par\u00f3quias, grupos paroquiais, institui\u00e7\u00f5es e comunidades de vida religiosa; tamb\u00e9m foram recebidas 517 respostas ao question\u00e1rio pessoal.<\/p>\n<p>O c\u00f3nego Joaquim Santos sublinhou que \u201cdar in\u00edcio a processos de participa\u00e7\u00e3o e escuta\u201d \u00e9 o mais importante, destacando as oportunidades que se abram para o di\u00e1logo nas comunidades cat\u00f3licas.<\/p>\n<p>\u201cO processo s\u00f3 agora come\u00e7ou\u201d, referiu um dos intervenientes citados pela VP.<\/p>\n<p>Entre as propostas apresentadas estava a de criar \u201cespa\u00e7os inclusivos para descobrir que Cristo ama cada pessoa\u201d.<\/p>\n<p>Caixas de resposta, inqu\u00e9ritos, encontros, proximidade aos mais afastados, ritmo paroquial ou vicarial e preocupa\u00e7\u00f5es com o acolhimento foram algumas das v\u00e1rias formas de trabalho utilizadas nesta tarefa de consulta sinodal, <a href=\"https:\/\/www.vozportucalense.pt\/2022\/05\/15\/continuar-o-processo-sinodal\/\" target=\"_blank\" rel=\"noopener\">indica<\/a> o jornal diocesano.<\/p>\n<figure id=\"attachment_240737\" aria-describedby=\"caption-attachment-240737\" style=\"width: 400px\" class=\"wp-caption alignright\"><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/bispo-sinodo-678x381-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-240737\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/bispo-sinodo-678x381-1-400x225.jpg\" alt=\"\" width=\"400\" height=\"225\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/bispo-sinodo-678x381-1-400x225.jpg 400w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/bispo-sinodo-678x381-1-480x270.jpg 480w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2022\/05\/bispo-sinodo-678x381-1.jpg 678w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><figcaption id=\"caption-attachment-240737\" class=\"wp-caption-text\">Foto: Voz Portucalense<\/figcaption><\/figure>\n<p>No final dos trabalhos, D. Manuel Linda revelou a sua satisfa\u00e7\u00e3o pelo trabalho desenvolvido, destacando que um S\u00ednodo deve partir \u201cdas bases\u201d.<\/p>\n<p>\u201cE eu, o que devo mudar para ajudar a igreja?\u201d, disse aos presentes.<\/p>\n<p>A primeira fase do processo sinodal lan\u00e7ado pelo Papa, em outubro de 2021, chega ao fim este m\u00eas, com as v\u00e1rias dioceses portuguesas a ultimar uma s\u00edntese do trabalho realizado a n\u00edvel local, que v\u00e3o entregar \u00e0 Confer\u00eancia Episcopal.<\/p>\n<p><em>OC<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encontro reuniu mais de duas centenas de representantes de par\u00f3quias, movimentos e institutos<\/p>\n","protected":false},"author":2,"featured_media":240741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[89,3],"tags":[187,311],"class_list":["post-240732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque2","category-nacional","tag-diocese-do-porto","tag-sinodo-dos-bispos"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/240732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=240732"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/240732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/240741"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=240732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=240732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=240732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}