{"id":21865,"date":"2006-12-26T12:56:56","date_gmt":"2006-12-26T12:56:56","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/12\/26\/humanizacao-de-deus-divinizacao-do-homem\/"},"modified":"2006-12-26T12:56:56","modified_gmt":"2006-12-26T12:56:56","slug":"humanizacao-de-deus-divinizacao-do-homem","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/humanizacao-de-deus-divinizacao-do-homem\/","title":{"rendered":"\u201cHumaniza\u00e7\u00e3o de Deus, diviniza\u00e7\u00e3o do Homem\u201d"},"content":{"rendered":"<p>Homilia do Patriarca de Lisboa na Solenidade do Natal do Senhor <!--more--> 1. A Encarna\u00e7\u00e3o do Verbo eterno de Deus no Homem Jesus Cristo \u00e9 o mist\u00e9rio central da nossa f\u00e9, e situa, em termos \u00fanicos e definitivos, a religi\u00e3o, concebida como rela\u00e7\u00e3o dos homens com Deus. A Encarna\u00e7\u00e3o \u00e9 uma manifesta\u00e7\u00e3o t\u00e3o ousada e inaudita da rela\u00e7\u00e3o de Deus com o homem, que s\u00f3 Deus, no Seu insond\u00e1vel des\u00edgnio, a podia imaginar e realizar. \tA f\u00e9 de Israel estava centrada na Alian\u00e7a entre Deus e o Seu Povo, proposta de intimidade e fidelidade m\u00fatua entre os homens e Deus. A Alian\u00e7a apresentava um Deus pr\u00f3ximo, bom e misericordioso, sol\u00edcito com os homens, presente e comprometido com a sua hist\u00f3ria. Pela Sua Palavra, revela-Se e desvela o Seu des\u00edgnio; pelo Seu poder conduz a hist\u00f3ria; pela Sua miseric\u00f3rdia est\u00e1 sempre disposto a perdoar e a transformar as infidelidades em momentos de reden\u00e7\u00e3o e de aprofundamento da Alian\u00e7a. Mas, como diz S\u00e3o Jo\u00e3o, \u201ca Deus ningu\u00e9m jamais O viu\u201d. Fala atrav\u00e9s dos Profetas, conduz o Povo atrav\u00e9s de Ju\u00edzes e de Reis que Ele deseja sejam \u201cpastores de Israel\u201d, e promete um tempo novo de consolida\u00e7\u00e3o definitiva da Alian\u00e7a, em que enviar\u00e1 um \u201cRei Justo\u201d, o Seu ungido, que conduzir\u00e1 o Povo \u00e0 plenitude da Alian\u00e7a. Na f\u00e9 de Israel, a densidade da Alian\u00e7a concentra-se na esperan\u00e7a messi\u00e2nica. \tMas em nenhum momento do Antigo Testamento, por mais profunda que seja a expectativa messi\u00e2nica, se ousa afirmar a divindade do Messias esperado. Ele \u00e9 um pr\u00edncipe da linhagem de David, realizar\u00e1 ac\u00e7\u00f5es que s\u00f3 Deus pode realizar, como salvar o Povo dos seus pecados; Ele realizar\u00e1 a obra de Deus, ser\u00e1 o Seu \u201cServo\u201d por excel\u00eancia. \u00c9 certo que, em perspectiva escatol\u00f3gica, chega a ser imaginado como uma figura celeste, um \u201cFilho do Homem\u201d, que aparece sobre as nuvens do C\u00e9u. Mas que o Messias seja a Encarna\u00e7\u00e3o do pr\u00f3prio Deus, \u00e9 a surpresa reservada por Deus para os que acreditarem na ressurrei\u00e7\u00e3o de Jesus Cristo. A divindade de Cristo continua a ser a surpresa inaudita da f\u00e9 crist\u00e3, afirma\u00e7\u00e3o da humaniza\u00e7\u00e3o de Deus e da diviniza\u00e7\u00e3o do homem, novo cap\u00edtulo da \u201cnova e definitiva Alian\u00e7a\u201d. Em rela\u00e7\u00e3o ao homem, Deus afirma-se mais pela proximidade do que pela dist\u00e2ncia; diz-nos que, vencido o pecado, h\u00e1 na profundidade do homem a capacidade de ser semelhante a Deus. Afinal Deus e o homem s\u00e3o da mesma fam\u00edlia, o que j\u00e1 estava sugerido na narra\u00e7\u00e3o da cria\u00e7\u00e3o, quando se diz que Deus criou o homem \u00e0 Sua imagem e semelhan\u00e7a.  \t2. Os crentes do Antigo Testamento encontravam dois obst\u00e1culos, aparentemente intranspon\u00edveis, para ousarem, sequer, imaginar que um homem pudesse ser Deus: a infinita dist\u00e2ncia entre o homem e Deus, dist\u00e2ncia de natureza, acentuada irremediavelmente na hist\u00f3ria do pecado do homem; e a compreens\u00e3o de Deus como uma \u00fanica Pessoa. S\u00f3 a revela\u00e7\u00e3o de Deus como comunidade de Pessoas, uno na natureza e trino nas pessoas, poderia permitir a ousadia de acreditar na Encarna\u00e7\u00e3o de uma das Pessoas divinas. A revela\u00e7\u00e3o crist\u00e3 resolve estas duas dificuldades: Cristo liberta radicalmente o homem do pecado e Ele pr\u00f3prio nos revela o mist\u00e9rio da comunh\u00e3o trinit\u00e1ria. \t\u00c9 por a\u00ed que come\u00e7a S\u00e3o Jo\u00e3o ao falar de Cristo como Encarna\u00e7\u00e3o de Deus: \u201cNo princ\u00edpio era o Verbo, o Verbo estava junto de Deus, e o Verbo era Deus\u2026 Tudo se fez por meio d\u2019Ele\u201d (Jo.1,1). S\u00f3 depois de afirmar esta alteridade, como Pessoa, do Verbo eterno em rela\u00e7\u00e3o a Deus, de Quem \u00e9 a Palavra, o Evangelista podia afirmar: \u201cE o Verbo fez-Se carne e habitou no meio de n\u00f3s. E n\u00f3s vimos a gl\u00f3ria d\u2019Ele, gl\u00f3ria que lhe vem do Pai, como o Filho \u00fanico, cheio de gra\u00e7a e de verdade\u201d (Jo. 1,14). O an\u00fancio deste mist\u00e9rio \u00e9 pr\u00e9vio a tudo o que se possa dizer sobre Jesus. \u00c9 por isso que S\u00e3o Jo\u00e3o faz deste an\u00fancio o pr\u00f3logo do seu Evangelho. O cristianismo \u00e9 uma coisa ou outra conforme se acredita ou n\u00e3o que Jesus Cristo \u00e9 o Filho de Deus feito Homem e se toma \u00e0 letra a pr\u00f3pria confiss\u00e3o de Jesus: \u201cEu e o Pai somos um\u201d (Jo. 10,30).  \t3. Esta realidade inaudita de um \u201cDeus-Homem\u201d muda radicalmente a fisionomia da religi\u00e3o. A ponte entre Deus e o homem est\u00e1 definitivamente feita, porque o homem n\u00e3o precisa de sair da sua humanidade para encontrar Deus, e reconhece em Deus o mais \u00edntimo da sua voca\u00e7\u00e3o humana. A primeira grande altera\u00e7\u00e3o acontece na maneira de escutar a Palavra de Deus: \u00e9 uma mudan\u00e7a radical na media\u00e7\u00e3o prof\u00e9tica. \u00c9 o que nos diz a Carta aos Hebreus: \u201cDeus, que muitas vezes e de muitos modos, falara antigamente a nossos pais pelos Profetas, nestes tempos, que s\u00e3o os \u00faltimos, falou-nos por Seu Filho\u201d (Heb. 1,1-2). Em Jesus Cristo cessa a media\u00e7\u00e3o prof\u00e9tica, porque Deus nos fala directamente atrav\u00e9s do Filho feito Homem. A Palavra de Deus \u00e9, agora, a Palavra de Jesus Cristo. E n\u2019Ele toda a Sua realidade, ensinamento e miss\u00e3o, \u00e9 Palavra. Deus j\u00e1 n\u00e3o precisa de media\u00e7\u00f5es simb\u00f3licas para revelar aos homens a Sua Palavra. Ele pr\u00f3prio, no Tabor, anunciou a nova etapa do di\u00e1logo do homem com Deus: \u201cEste \u00e9 o Meu Filho\u2026 escutai-O\u201d (Mt. 17,5). \tJesus Cristo, Filho de Deus, revela-nos o mais profundo des\u00edgnio de Deus a nosso respeito: seremos Seus filhos e entraremos na comunh\u00e3o de amor que Ele \u00e9. E isso aconteceu-nos, quando, pelo baptismo, nos unimos \u00e0 Sua morte e ressurrei\u00e7\u00e3o. A principal obriga\u00e7\u00e3o do homem em rela\u00e7\u00e3o a Deus, que \u00e9 glorific\u00e1-l\u2019O, est\u00e1 garantida por Jesus Cristo, no sacrif\u00edcio de louvor. Ao permitir-nos esta intimidade e esta verdade com Deus, Cristo revela ao homem o mais profundo do Seu cora\u00e7\u00e3o. S\u00f3 em Jesus Cristo o homem reconhece o seu mist\u00e9rio. Cristo revela o homem a si mesmo; Cristo humaniza o homem.  \t4. Num momento em que, num mundo globalizado, se fala na urg\u00eancia do di\u00e1logo inter-religioso como caminho para a paz, os crist\u00e3os s\u00f3 se podem comprometer, de forma construtiva, nesse di\u00e1logo, se n\u00e3o esquecerem este car\u00e1cter \u00fanico da sua f\u00e9: a proximidade de Deus, em Jesus Cristo. Noutras religi\u00f5es, encontramos o sentido da transcend\u00eancia de Deus, da Sua santidade e bondade, Senhor e Juiz de todos os homens. Mas s\u00f3 o cristianismo nos torna Deus acess\u00edvel, pr\u00f3ximo, expresso na realidade humana do Homem Jesus Cristo. Ele tornou-se o \u00fanico caminho por onde podemos chegar a Deus. \u00c9 tamb\u00e9m a partir de Jesus Cristo que podemos entrar em di\u00e1logo com crentes de outras religi\u00f5es, nossos irm\u00e3os. No que essas religi\u00f5es significam de caminho para Deus, elas s\u00e3o express\u00e3o silenciosa de Jesus Cristo, o \u00fanico caminho. Ao exprimir-se num Homem, Deus tocou no \u00e2mago de toda a hist\u00f3ria humana e do pr\u00f3prio Universo criado, no seio dos quais as \u201csementes do Verbo\u201d anseiam pela sua manifesta\u00e7\u00e3o plena. Foi assim que um grande Padre da Igreja, Santo Ireneu, designou os valores positivos de todas as religi\u00f5es como caminhos para Deus: \u201csementes do Verbo\u201d, Ele que Se fez carne, em Jesus Cristo. \tPorque o homem \u00e9 o centro do Universo, a Encarna\u00e7\u00e3o de Deus, em Jesus Cristo, \u00e9 um passo decisivo para a transforma\u00e7\u00e3o do Universo criado, em ordem \u00e0 sua plenitude definitiva. Ele \u00e9 uma for\u00e7a transformadora, a germinar no seio do cosmos, a anunciar a sua transforma\u00e7\u00e3o. S\u00e3o Jo\u00e3o lembra que por esse Verbo eterno, que Se fez carne, todas as coisas foram feitas. Tudo ser\u00e1 recapitulado n\u2019Ele, como afirma o Conc\u00edlio Vaticano II: \u201cO Verbo de Deus, por Quem tudo foi feito, Ele pr\u00f3prio Se fez carne, para que, Homem perfeito, salve todos os homens e recapitule todas as coisas n\u2019Ele\u201d (G.S. n.\u00ba45).  \tA nossa f\u00e9 em Jesus Cristo, Verbo de Deus Encarnado, compromete-nos com a evolu\u00e7\u00e3o do Universo e o destino da cria\u00e7\u00e3o. O drama do Universo \u00e9 indissoci\u00e1vel do drama do homem, e ambos encontram a resposta iluminadora na Cruz de Jesus Cristo. \u00c9 este o ensinamento de Paulo aos crist\u00e3os de Roma: \u201cEu penso que os sofrimentos do tempo presente n\u00e3o se podem comparar \u00e0 gl\u00f3ria que se revelar\u00e1 em n\u00f3s. Porque a cria\u00e7\u00e3o, em expectativa, aspira pela revela\u00e7\u00e3o dos filhos de Deus. Se ela foi submetida \u00e0 vaidade (\u2026) \u00e9 com esperan\u00e7a de ser, tamb\u00e9m ela, liberta da escravid\u00e3o da corrup\u00e7\u00e3o para entrar na liberdade da gl\u00f3ria dos filhos de Deus\u201d (Rom. 8,18-21). O crist\u00e3o \u00e9 chamado a encontrar Deus, em Jesus Cristo, tamb\u00e9m no \u00e2mago da cria\u00e7\u00e3o, ela pr\u00f3pria redimida por Jesus Cristo. Num Hino da Liturgia das Horas, a Igreja canta: \u201cPorque Ele est\u00e1 connosco, enquanto o tempo \u00e9 tempo, ningu\u00e9m espere, para O encontrar, o fim dos dias. Abrindo os olhos, busquemos o Seu rosto e a Sua imagem. Busquemo-l\u2019O na vida, sempre oculto, no \u00edntimo do mundo, como um fogo\u201d. \tAcreditar em Jesus Cristo, Verbo encarnado, significa introduzir Deus em todas as dimens\u00f5es da nossa vida: pessoais e \u00edntimas, de rela\u00e7\u00e3o com os outros numa hist\u00f3ria comum, nas nossas rela\u00e7\u00f5es com o Universo, insepar\u00e1vel do destino do homem. Deus est\u00e1 pr\u00f3ximo, passou a ser uma for\u00e7a cont\u00ednua, na nossa vida e na nossa hist\u00f3ria.  S\u00e9 Patriarcal, 25 de Dezembro de 2006 <i>\u2020 JOS\u00c9, Cardeal-Patriarca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Homilia do Patriarca de Lisboa na Solenidade do Natal do Senhor<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[9],"tags":[144,167,206,246,267],"class_list":["post-21865","post","type-post","status-publish","format-standard","hentry","category-documentos","tag-concilio-vaticano-ii","tag-dialogo-inter-religioso","tag-familia","tag-liturgia","tag-natal"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/21865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=21865"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/21865\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=21865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=21865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=21865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}