{"id":208405,"date":"2021-05-22T17:51:16","date_gmt":"2021-05-22T16:51:16","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=208405"},"modified":"2021-05-24T13:32:12","modified_gmt":"2021-05-24T12:32:12","slug":"semana-laudato-si-experiencia-portuguesa-apresentada-ao-movimento-catolico-global-pelo-clima","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/semana-laudato-si-experiencia-portuguesa-apresentada-ao-movimento-catolico-global-pelo-clima\/","title":{"rendered":"Semana \u00abLaudato Si\u00bb: Experi\u00eancia portuguesa apresentada ao Movimento Cat\u00f3lico Global pelo Clima"},"content":{"rendered":"<p><em>Focos de Convers\u00e3o Ecol\u00f3gica de par\u00f3quias lisboetas entre as \u00abpr\u00e1ticas que fazem a diferen\u00e7a\u00bb na aplica\u00e7\u00e3o da enc\u00edclica<\/em><!--more--><\/p>\n<figure id=\"attachment_190192\" aria-describedby=\"caption-attachment-190192\" style=\"width: 1500px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-190192 size-full\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10.jpeg\" alt=\"\" width=\"1500\" height=\"1000\" srcset=\"https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10.jpeg 1500w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10-390x260.jpeg 390w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10-1024x683.jpeg 1024w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10-768x512.jpeg 768w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10-1080x720.jpeg 1080w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10-1280x853.jpeg 1280w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10-980x653.jpeg 980w, https:\/\/agencia.ecclesia.pt\/portal\/wp-content\/uploads\/2020\/11\/foco-ecologico-chelas-10-480x320.jpeg 480w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/a><figcaption id=\"caption-attachment-190192\" class=\"wp-caption-text\">Foto: Ag\u00eancia ECCLESIA\/HM<\/figcaption><\/figure>\n<p>Lisboa, 21 mai 2021 (Ecclesia) \u2013 Os Focos de Convers\u00e3o Ecol\u00f3gica das Par\u00f3quias de S\u00e3o Maximiliano Kolbe e Santa Beatriz da Silva, em Lisboa, estiveram hoje em destaque num webinar do Movimento Cat\u00f3lico Global pelo Clima (MCGC), sobre a aplica\u00e7\u00e3o da \u2018Laudato Si\u2019 (2015).<\/p>\n<p>Frei Fabrizio Bordin, p\u00e1roco na zona oriental da capital portuguesa, destacou o impulso dado pelo ensinamento do Papa Francisco no aumento da preocupa\u00e7\u00e3o por \u201cum estilo de vida saud\u00e1vel, respeitoso desta terra\u201d, uma necessidade que veio a ser sublinhada pela pandemia de Covid-19.<\/p>\n<p>O orador destacou o papel do grupo de leigos que acolheu este desafio e tornou \u201cmuito sens\u00edvel a estes temas da Laudato Si\u201d.<\/p>\n<p>\u201cEncontramos uma alma ecol\u00f3gica na vida das pessoas\u201d, assinalou o religioso, destacando a import\u00e2ncia de \u201ccuidar da beleza do espa\u00e7o verde\u201d no meio de tantos pr\u00e9dios.<\/p>\n<p>Os focos, referiu frei Fabrizio Bordin, criaram uma rede que assumiu a enc\u00edclica ecol\u00f3gica e social de 2015 como a sua \u201cmagna carta\u201d.<\/p>\n<p>O religioso assinalou a import\u00e2ncia de envolver as novas gera\u00e7\u00f5es, dado o exemplo da recolha de lixo, um trabalho \u201cnem sempre gratificante\u201d.<\/p>\n<p>A confer\u00eancia online decorreu no \u00e2mbito da celebra\u00e7\u00e3o da Semana \u2018Laudato Si\u2019 2021, com organiza\u00e7\u00e3o do MCGC, o Servi\u00e7o \u2018Justi\u00e7a, Paz e Integridade da Cria\u00e7\u00e3o\u2019 da Ordem dos Frades Menores (Franciscanos) e a Rede \u2018Cuidar da Casa Comum\u2019 (Portugal), sobre o tema \u00ab\u2018Laudato Si\u2019 em a\u00e7\u00e3o: Pr\u00e1ticas que fazem a diferen\u00e7a\u00bb.<\/p>\n<p>https:\/\/www.facebook.com\/vivalaudatosi\/videos\/1571506026573711<\/p>\n<p>Frei Jaime Campos, diretor do Servi\u00e7o \u2018Justi\u00e7a, Paz e Integridade da Cria\u00e7\u00e3o\u2019 dos Franciscanos, referiu na sua interven\u00e7\u00e3o que as mudan\u00e7as pedidas pelo Papa Francisco implicam \u201cprocessos lentos, mas que pouco a pouco v\u00e3o dando frutos\u201d.<\/p>\n<p>O religioso apresentou imagens da instala\u00e7\u00e3o de pain\u00e9is fotovoltaicos em casas de retiro nos EUA, Guin\u00e9-Bissau, Brasil ou Indon\u00e9sia, entre outros, sublinhando que v\u00e1rias casas da ordem franciscana procuram ser alimentadas completamente com energias renov\u00e1veis.<\/p>\n<p>Maria Leonor de Freitas, secret\u00e1ria executiva da Comiss\u00e3o Episcopal de Justi\u00e7a e Paz da Confer\u00eancia Episcopal de Angola e S\u00e3o Tom\u00e9 (CEAST) falou da \u201cfloresta Laudato Si\u201d que foi plantada em territ\u00f3rio angolana para travar a desertifica\u00e7\u00e3o \u2013 com o desafio que seja replicada em todas as dioceses cat\u00f3licas.<\/p>\n<p>D. Vicente Ferreira, secret\u00e1rio da Comiss\u00e3o Especial de Ecologia Integral e Minera\u00e7\u00e3o da Confer\u00eancia Nacional dos Bispos do Brasil (CNBB), real\u00e7ou a aposta da Igreja Cat\u00f3lica neste setor ambiental.<\/p>\n<p>O respons\u00e1vel \u00e9 bispo de Brumadinho, Minas Gerais, onde em 2019 mais de 270 pessoas morreram soterradas, ap\u00f3s a rutura de uma barragem da mineradora Vale.<\/p>\n<p>O respons\u00e1vel cat\u00f3lico saudou os jovens que acompanham diretamente as comunidades atingidas, porque \u201cn\u00e3o \u00e9 poss\u00edvel uma Igreja apenas de escrit\u00f3rio\u201d.<\/p>\n<p>\u201cSe o povo est\u00e1 correndo riscos, o bispo tem de estar l\u00e1, junto\u201d, assinalou D. Vicente Ferreira.<\/p>\n<p>\u201cO sistema capitalista, colonialista, continua matando\u201d, acrescentou.<\/p>\n<p>A sess\u00e3o foi moderada pela jornalista Margarida Vaqueiro Lopes.<\/p>\n<p>A \u2018Semana Laudato Si\u2019 \u00e9 o momento culminante do ano especial de anivers\u00e1rio da enc\u00edclica ecol\u00f3gica e social do Papa Francisco, que decorre at\u00e9 25 de maio, promovendo a celebra\u00e7\u00e3o \u201cdos progressos que a Igreja tem vindo a realizar no caminho da convers\u00e3o ecol\u00f3gica, ao mesmo tempo que propor\u00e1 um trajeto para a pr\u00f3xima d\u00e9cada\u201d.<\/p>\n<p><em>OC<\/em><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"XsplQZeB4W\"><p><a href=\"https:\/\/agencia.ecclesia.pt\/portal\/igreja-ecologia-laudato-si-inspira-leigos-catolicos-a-lancar-sementes-de-novas-hortas-urbanas-c-fotos\/\">Igreja\/Ecologia: \u00abLaudato si\u00bb inspira leigos cat\u00f3licos a lan\u00e7ar sementes de novas hortas urbanas (c\/fotos e v\u00eddeo)<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Igreja\/Ecologia: \u00abLaudato si\u00bb inspira leigos cat\u00f3licos a lan\u00e7ar sementes de novas hortas urbanas (c\/fotos e v\u00eddeo)&#8221; &#8212; Ag\u00eancia ECCLESIA\" src=\"https:\/\/agencia.ecclesia.pt\/portal\/igreja-ecologia-laudato-si-inspira-leigos-catolicos-a-lancar-sementes-de-novas-hortas-urbanas-c-fotos\/embed\/#?secret=mEzzhWuTJ6#?secret=XsplQZeB4W\" data-secret=\"XsplQZeB4W\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Focos de Convers\u00e3o Ecol\u00f3gica de par\u00f3quias lisboetas entre as \u00abpr\u00e1ticas que fazem a diferen\u00e7a\u00bb na aplica\u00e7\u00e3o da enc\u00edclica<\/p>\n","protected":false},"author":2,"featured_media":190182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[89,3],"tags":[195],"class_list":["post-208405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque2","category-nacional","tag-enciclica-laudato-si"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/208405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=208405"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/208405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/190182"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=208405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=208405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=208405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}