{"id":20485,"date":"2006-10-03T17:22:56","date_gmt":"2006-10-03T17:22:56","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/10\/03\/bento-xvi-lamenta-maior-acidente-aereo-da-historia-do-brasil\/"},"modified":"2006-10-03T17:22:56","modified_gmt":"2006-10-03T17:22:56","slug":"bento-xvi-lamenta-maior-acidente-aereo-da-historia-do-brasil","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/bento-xvi-lamenta-maior-acidente-aereo-da-historia-do-brasil\/","title":{"rendered":"Bento XVI lamenta maior acidente a\u00e9reo da hist\u00f3ria do Brasil"},"content":{"rendered":"<p>Bento XVI manifestou o seu profundo pesar pela morte de 155 pessoas, entre os quais um portugu\u00eas, no maior acidente a\u00e9reo da hist\u00f3ria do Brasil. O Papa mostra-se \u201cprofundamente consternado pelo acidente a\u00e9reo ocorrido no Planalto Mato-grossense, invocando a miseric\u00f3rdia divina sobre os passageiros e tripulantes envolvidos na trag\u00e9dia\u201d. A mensagem de pesar \u00e9 enviada, em nome de Bento XVI, pelo Cardeal Tarcisio Bertone, Secret\u00e1rio de Estado do Vaticano. A For\u00e7a A\u00e9rea Brasileira j\u00e1 confirmou morte dos 155 ocupantes do Boeing 737-800 da companhia Gol, que se despenhou, na passada sexta-feira, na selva amaz\u00f3nica, no Brasil. A Confer\u00eancia Nacional dos Bispos do Brasil tamb\u00e9m endere\u00e7ou uma mensagem aos familiares das v\u00edtimas do acidente e  aos funcion\u00e1rios da Gol linhas a\u00e9reas, na qual \u201cfaz pr\u00f3pria a dor das pessoas atingidas e reza por elas, para que os seus cora\u00e7\u00f5es sejam confortados\u201d. \u201cEnquanto espera que as circunst\u00e2ncias do acidente sejam esclarecidas, a CNBB solidariza-se com os familiares e parentes das v\u00edtimas, bem como com a direc\u00e7\u00e3o da Empresa e colegas de trabalho dos funcion\u00e1rios que morreram\u201d, refere a nota, enviada \u00e0 Ag\u00eancia ECCLESIA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bento XVI manifestou o seu profundo pesar pela morte de 155 pessoas, entre os quais um portugu\u00eas, no maior acidente a\u00e9reo da hist\u00f3ria do Brasil. O Papa mostra-se \u201cprofundamente consternado pelo acidente a\u00e9reo ocorrido no Planalto Mato-grossense, invocando a miseric\u00f3rdia divina sobre os passageiros e tripulantes envolvidos na trag\u00e9dia\u201d. A mensagem de pesar \u00e9 enviada, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[120,122],"class_list":["post-20485","post","type-post","status-publish","format-standard","hentry","category-vaticano","tag-bento-xvi","tag-brasil"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/20485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=20485"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/20485\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=20485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=20485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=20485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}