{"id":200963,"date":"2021-03-04T17:00:50","date_gmt":"2021-03-04T17:00:50","guid":{"rendered":"https:\/\/agencia.ecclesia.pt\/portal\/?p=200963"},"modified":"2021-03-04T18:13:55","modified_gmt":"2021-03-04T18:13:55","slug":"memorias-que-contam-a-biografia-de-quem-entrou-no-convento-de-clausura-para-ser-livre","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/memorias-que-contam-a-biografia-de-quem-entrou-no-convento-de-clausura-para-ser-livre\/","title":{"rendered":"\u00abMem\u00f3rias que contam\u00bb: A biografia de quem entrou no convento de clausura para ser livre"},"content":{"rendered":"<p><em>Cineasta In\u00eas Gil recorda o sorriso e a liberdade da irm\u00e3 Maria Domingos e o acolhimento que se experimentava no Mosteiro das Monjas Dominicanas do Lumiar\u00a0<\/em><\/p>\n<p><!--more--><\/p>\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_19982\"  width=\"480\" height=\"270\"  data-origwidth=\"480\" data-origheight=\"270\" src=\"https:\/\/www.youtube.com\/embed\/nLArGiJZBMA?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=pt&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=1&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<p>Lisboa, 04 mar 2021 (Ecclesia) \u2013 In\u00eas Gil disse \u00e0 Ag\u00eancia ECCLESIA que est\u00e1 \u201cimensamente grata\u201d por ter filmado o quotidiano do Mosteiro das Monjas Dominicanas do Lumiar e recorda o \u201cacolhimento e do\u00e7ura\u201d da irm\u00e3 Maria Domingos, que escolheu a clausura para ser livre.<\/p>\n<p>\u201cQuando decidiu entrar num convento de clausura era para ser livre. E encontrou essa liberdade, porque foi ao encontro do que procurava: uma liberdade interior\u201d, disse a realizadora e professora de cinema na Universidade Lus\u00f3fona.<\/p>\n<p>Para In\u00eas Gil, a irm\u00e3 Maria Domingos \u201cera extremamente espont\u00e2nea\u201d, n\u00e3o \u201cprecisava de provar\u201d que era habitada pela dimens\u00e3o espiritual porque a \u201csua vida e a sua espiritualidade estavam presentes\u201d como \u201calgo que se exprime no seu pr\u00f3prio ser\u201d.<\/p>\n<p>Convidada a recordar a irm\u00e3 Maria Domingos, que faleceu com Covid-19 no dia 15 de fevereiro, na rubrica da Ag\u00eancia ECCLESIA \u201cMem\u00f3rias que contam\u201d, In\u00eas Gil lembrou os dias em que esteve no mosteiro para fazer um filme sobre a vida das irm\u00e3s e afirma que est\u00e1 \u201cimensamente grata\u201d por essa possibilidade.<\/p>\n<p>\u201cFilmei uma intimidade do mosteiro, das irm\u00e3s, que foi um privil\u00e9gio absoluto: estar no mosteiro, filmar o quotidiano dessas irm\u00e3s inesquec\u00edveis. Estou imensamente grata por essa possibilidade que elas me deram\u201d, referiu.<\/p>\n<p>In\u00eas Gil recorda o acolhimento, diz que o \u201csorriso da Irm\u00e3 Domingos era maravilhoso\u201d, assim como \u201co humor, a do\u00e7ura, o olhar e as conversas&#8221;.<\/p>\n<p>\u201cAs conversas com a Irm\u00e3 Domingos ajudaram-me mesmo a crescer\u201d, sublinhou.<\/p>\n<p>In\u00eas Gil disse que as Irm\u00e3s do Mosteiro do Lumiar eram \u201ccompletamente inclusivas\u201d, \u201cacolhiam o crente e o n\u00e3o crente\u201d, sem qualquer julgamento, e davam as \u201cferramentas para crescer\u201d, atrav\u00e9s \u201cda reflex\u00e3o e da ora\u00e7\u00e3o\u201d, a quem quisesse.<\/p>\n<p>A cineasta recorda que entrou no mosteiro pela primeira vez h\u00e1 cerca de 20 anos quando decidiu descobrir um \u201cespa\u00e7o t\u00e3o misterioso\u201d de que uma amiga lhe falava e foi \u201cmuito bem acolhida\u201d, como se estivesse na sua pr\u00f3pria casa.<\/p>\n<p>\u201cEra um ambiente familiar\u201d, diz a professora de cinema na Universidade Lus\u00f3fona sobre o acolhimento no Mosteiro das Dominicanas do Lumiar, e lembra a qualidade das confer\u00eancias que a\u00ed aconteciam, \u201ctodo o cuidado\u201d, o ch\u00e1, as bolachas, a distribui\u00e7\u00e3o das publica\u00e7\u00f5es das confer\u00eancias, os \u00edcones.<\/p>\n<p>O filme realizado por In\u00eas Gil sobre o quotidiano das dominicanas do Lumiar intitula-se \u00abOnde moras?\u00bb e ser\u00e1 divulgado &#8220;oportunamente&#8221;, apurou a Ag\u00eancia ECCLESIA.<\/p>\n<p>A rubrica \u201cMem\u00f3rias que contam\u201d apresenta, durante o tempo da Quaresma, o percurso biogr\u00e1fico de homens e mulheres que faleceram com Covid-19.<\/p>\n<p><em>PR<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cineasta In\u00eas Gil recorda o sorriso e a liberdade da irm\u00e3 Maria Domingos e o acolhimento que se experimentava no Mosteiro das Monjas Dominicanas do Lumiar<\/p>\n","protected":false},"author":5,"featured_media":200960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[58,3],"tags":[],"class_list":["post-200963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caixa1","category-nacional"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/200963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=200963"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/200963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media\/200960"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=200963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=200963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=200963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}