{"id":18534,"date":"2006-06-12T11:07:02","date_gmt":"2006-06-12T11:07:02","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/06\/12\/pobreza-tem-muitas-causas\/"},"modified":"2006-06-12T11:07:02","modified_gmt":"2006-06-12T11:07:02","slug":"pobreza-tem-muitas-causas","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/pobreza-tem-muitas-causas\/","title":{"rendered":"Pobreza tem muitas causas"},"content":{"rendered":"<p>Entrevista ao Jornal da Madeira de Alfredo Bruto da Costa, Presidente do CES e Vice-presidente da Comiss\u00e3o Nacional Justi\u00e7a e Paz   <!--more--> \u00c9 preciso promover o conceito de \u201ccidadania mundial\u201d a favor do bem-comum, tal como defende a Doutrina Social da Igreja h\u00e1 mais de 40 nos, a partir de Jo\u00e3o XXIII. A pobreza tem uma dimens\u00e3o moral que n\u00e3o pode ser ultrapassada sem a necess\u00e1ria mudan\u00e7a de mentalidades a v\u00e1rios n\u00edveis. O emprego inst\u00e1vel e a sustentabilidade da seguran\u00e7a social n\u00e3o se resolvem apenas por interm\u00e9dio de factores econ\u00f3micos ou financeiros, mas sobretudo atrav\u00e9s de uma \u201cfilosofia pol\u00edtica\u201d, em que se garanta \u201co grau de solidariedade que cada sociedade est\u00e1 disposta a dar\u201d, segundo Alfredo Bruto da Costa ao Jornal da Madeira.  <i>JORNAL da MADEIRA \u2014 A exist\u00eancia de pobreza \u00e9 fruto de qu\u00ea? Culpa de quem? Como se resolve?  Alfredo Bruto da Costa \u2014<\/i> Se a pobreza fosse uma coisa dependente de coisas cegas n\u00e3o teria uma dimens\u00e3o moral, Mas tem esta dimens\u00e3o precisamente porque resulta de comportamentos e de quadros culturais relacionados com homens e mulheres concretos; pode ser alterada com a mudan\u00e7a de conduta, pois, a pobreza n\u00e3o \u00e9 fruto de um determinismo, n\u00e3o existe por acaso; \u00e9 fruto de mecanismos que existem na sociedade e que fazem com que uns possam ter riqueza e rendimentos quase ilimitados, e outros n\u00e3o t\u00eam acesso aquilo que se considera o m\u00ednimo necess\u00e1rio para o ser humano viver decentemente. N\u00e3o \u00e9 um facto mecanicista, sublinho, n\u00e3o depende s\u00f3 de for\u00e7as incontrol\u00e1veis, \u00e9 algo evit\u00e1vel e que existe em fun\u00e7\u00e3o de institui\u00e7\u00f5es de comportamentos, de quadros culturais, de valores que vigoram nas sociedades. Desta forma, \u00e9 sempre poss\u00edvel mudar para melhor; e cada vez mais urgente.   <i>JM \u2014 Fala-se muito de factores inevit\u00e1vies no aparecimento da pobreza, como o desemprego, a falta de competitividade, a fal\u00eancia da seguran\u00e7a social&#8230; Neste cen\u00e1rio, qual a solu\u00e7\u00e3o?  ABC \u2014<\/i> Se tivesse a solu\u00e7\u00e3o no bolso seria a pessoa mais rica deste mundo. Todos andam \u00e0 procura de solu\u00e7\u00f5es, n\u00e3o h\u00e1 uma solu\u00e7\u00e3o apenas, porque a situa\u00e7\u00e3o \u00e9 composta por v\u00e1rios tipos de problemas.  Na minha opini\u00e3o, temos que ver o problema com base nas seguintes perspectivas: na linha de uma preocupa\u00e7\u00e3o crist\u00e3 perante os problemas do mundo, temos que olhar para as coisas primeiro na linha \u00e9tica, dos valores, e ver o que est\u00e1 certo ou n\u00e3o; e face ao que n\u00e3o est\u00e1 certo tentar mudar.  Em tudo isto, por\u00e9m, h\u00e1 um problema tamb\u00e9m pr\u00e1tico que \u00e9 preciso considerar. \u00c9 que qualquer mudan\u00e7a tem oposi\u00e7\u00e3o. E n\u00e3o \u00e9 oposi\u00e7\u00e3o s\u00f3 por m\u00e1 vontade ou ego\u00edsmo; tamb\u00e9m h\u00e1 oposi\u00e7\u00e3o das pessoas que tiram privil\u00e9gios da situa\u00e7\u00e3o vigente. H\u00e1 muita gente que est\u00e1 convencida que assim como est\u00e1 \u00e9 que deve ser, e ent\u00e3o considera que a pobreza \u00e9 uma fatalidade, um fen\u00f3meno inevit\u00e1vel resultante da actividade da economia, mas que n\u00e3o \u00e9 poss\u00edvel evit\u00e1-lo.  Por outro lado, h\u00e1 os que pensam que a pobreza existe s\u00f3 porque os pobres n\u00e3o querem sair dela. Veja-se a frase: &#8220;s\u00f3 \u00e9 desempregado quem quer, \u00e9 pobre quem quer&#8221;, etc., como se dependesse exclusivamente dos pobres.  Portanto, existem muitas formas de compreender erradamente a pobreza, o que leva muita gente a pensar que n\u00e3o s\u00e3o precisas mudan\u00e7as na sociedade, e que quem tem de mudar s\u00e3o as pessoas que s\u00e3o v\u00edtimas dessa situa\u00e7\u00e3o, seja pobre, desempregado ou exclu\u00eddos de um modo geral.  Quer dizer, quando pensamos em mudan\u00e7as h\u00e1 que ter tamb\u00e9m em considera\u00e7\u00e3o essas oposi\u00e7\u00f5es para que a nossa estrat\u00e9gia seja vi\u00e1vel, sen\u00e3o batemos com a cabe\u00e7a na parede e n\u00e3o avan\u00e7amos nada.   <b>Globaliza\u00e7\u00e3o e \u201cbem comum mundial\u201d<\/b> <i>JM \u2014 O mundo globalizado em que hoje vivemos tamb\u00e9m n\u00e3o condiciona essas mudan\u00e7as?  ABC \u2014<\/i> \u00c9 um facto, n\u00f3s vivemos situados no mundo que coloca condicionantes para as solu\u00e7\u00f5es. N\u00e3o s\u00e3o determinantes, mas condicionam. Por causa da globaliza\u00e7\u00e3o, hoje, os pa\u00edses n\u00e3o podem defender-se como antigamente. A concorr\u00eancia entre as empresas, por exemplo, fazia-se dentro de um pa\u00eds, depois \u00e0 escala europeia e agora numa dimens\u00e3o mundial. Temos que funcionar, pois, dentro deste contexto.  Mas, isto n\u00e3o quer dizer que a globaliza\u00e7\u00e3o tenha que ser a que existe neste momento. Ela \u00e9 um fen\u00f3meno mundial e aquilo que antes era preciso numa l\u00f3gica do mercado nacional, hoje, \u00e9 preciso numa l\u00f3gica de mercado internacional que \u00e9 o seguinte: o mercado d\u00e1 bons resultados quando os concorrentes t\u00eam um n\u00edvel de poder econ\u00f3mico compar\u00e1vel; quando o n\u00edvel \u00e9 desequilibrado, os mais poderosos tiram mais vantagens e os menos poderosos at\u00e9 podem ficar prejudicados.  Da\u00ed que o Papa Jo\u00e3o XXIII, em 1961 (h\u00e1 mais de 40 anos), na sua enc\u00edclica \u201cPacem in Terris\u201d falava j\u00e1 em duas coisas importantes: na necessidade de haver o conceito de &#8220;bem-comum mundial&#8221;, em vez do bem-comum de um pa\u00eds, a que est\u00e1vamos ent\u00e3o habituados.  Nesta ordem de ideias, \u00e9 preciso que haja tamb\u00e9m uma autoridade mundial para promover o bem-comum; ora, passados todos estes anos ap\u00f3s o apelo do Papa, ainda n\u00e3o temos esse conceito e muito menos uma autoridade mundial.  Existem tentativas atrav\u00e9s da Organiza\u00e7\u00e3o Mundial do Com\u00e9rcio (OMC) com algumas regras no jogo, mas s\u00e3o regras que est\u00e3o dominadas pelos mais poderosos, quer sejam pa\u00edses ou empresas multinacionais. Ainda h\u00e1 pouco soube de uma situa\u00e7\u00e3o perfeitamente bizarra nas regras do movimento de trabalhadores entre os pa\u00edses, e que \u00e9 esta situa\u00e7\u00e3o: a OMC j\u00e1 aceitou que as empresas multinacionais devem poder transferir o seu pessoal dum pa\u00eds para outro, dentro da mesma empresa, sem problemas; se isto j\u00e1 existe, se as multinacionais conseguem, veja-se se um qualquer consegue&#8230; Isto para dizer que h\u00e1 dificuldades.   <b>Quest\u00e3o financeira versus filosofia pol\u00edtica<\/b> <i>JM \u2014 E quanto \u00e0 \u201cprotec\u00e7\u00e3o social\u201d dos trabalhadores, o \u201cEstado-provid\u00eancia\u201d acabou?  ABC \u2014<\/i> Fala-se muito na sua sustentabilidade e restringe-se o problema apenas \u00e0 quest\u00e3o financeira. Penso que \u00e9 um erro muito grande, porque o \u201cEstado-provid\u00eancia\u201d, antes de mais, \u00e9 um acordo de sociedade que come\u00e7a por pertencer n\u00e3o ao campo das finan\u00e7as, mas ao da filosofia pol\u00edtica.  Compete antes do mais perguntar aos cidad\u00e3os que tipo de sociedade quer, que tipo de solidariedade quer que fique a cargo da sociedade, que tipo de solidariedade a cargo das fam\u00edlias ou do indiv\u00edduo.  O \u201cEstado-provid\u00eancia\u201d \u00e9 fundamentalmente um modelo institucional de solidariedade. E s\u00f3 depois de conhecermos qual o modelo que queremos neste campo \u00e9 que se pode saber quem deve contribuir, com quanto deve contribuir e a que pre\u00e7o deve contribuir.  Se sou defensor de uma sociedade em que cada um olha por si e o Estado n\u00e3o olha por ningu\u00e9m, eu n\u00e3o estarei disposto a pagar nada pela seguran\u00e7a social. Se sou uma pessoa que acredita que h\u00e1 uma coisa que se chama &#8220;risco social&#8221;, risco a que todo o cidad\u00e3o est\u00e1 sujeito; e se estiver convencido que, normalmente, o cidad\u00e3o n\u00e3o tem meios para enfrentar sozinho certos riscos, como uma doen\u00e7a grave, um desemprego&#8230;, nessa altura estarei dispon\u00edvel para contribuir para um sistema que tenha uma institui\u00e7\u00e3o de solidariedade nacional para acorrer a essas situa\u00e7\u00f5es.  Portanto, antes de ser um problema financeiro, \u00e9 de natureza da filosofia pol\u00edtica, de cidadania. H\u00e1 que primeiro que perceber que as finan\u00e7as n\u00e3o s\u00e3o tudo. Se come\u00e7amos por discutir o fim estamos condenados ao insucesso.   <b>Qualifica\u00e7\u00e3o de recursos e inova\u00e7\u00e3o tecnol\u00f3gica<\/b> <i>JM \u2014 Em termos de sustentabilidade da protec\u00e7\u00e3o social e dos empregos em geral, que radiografia faz do nosso pa\u00eds? Que orienta\u00e7\u00f5es sugere?  ABC \u2014<\/i> Somos uma sociedade (trabalhadores e empres\u00e1rios) sem uma qualifica\u00e7\u00e3o exigida pela competitividade actual. O problema dos trabalhadores reflecte-se na compet\u00eancia, na qualidade do trabalho; e o dos empres\u00e1rios na parte da de gest\u00e3o, de inova\u00e7\u00e3o, da tecnologia e da organiza\u00e7\u00e3o de empresas. Isto \u00e9 muito importante porque o que est\u00e1 em causa n\u00e3o \u00e9 s\u00f3 um problema dos trabalhadores, \u00e9 tamb\u00e9m das empresas. Mesmo que tiv\u00e9ssemos trabalhadores competitivos, ser\u00e1 que as nossas empresas est\u00e3o a ser geridas de forma competitiva? Est\u00e3o organizadas? Os empres\u00e1rios t\u00eam forma\u00e7\u00e3o que \u00e9 exigida ao mundo de hoje?  Esta \u00e9 a quest\u00e3o principal. A solu\u00e7\u00e3o, quanto a mim, tem de respeitar os tr\u00eas tipos de pessoa que est\u00e3o em causa: no caso dos trabalhadores qualificados e altamente qualificados, a solu\u00e7\u00e3o \u00e9 entrar declaradamente no mercado competitivo; e aqui o problema que se p\u00f5e \u00e9 haver empresas suficientemente agressivas para competir a n\u00edvel europeu e mundial.  Depois, um sector que tem uma certa qualifica\u00e7\u00e3o mas que ainda tem de aumentar mais; para esses tem que haver sistemas de forma\u00e7\u00e3o r\u00e1pida; e aqui \u00e9 tudo quanto podemos e devemos incluir sob a designa\u00e7\u00e3o ampla de pol\u00edtica de emprego; pol\u00edtica esta que n\u00e3o depender apenas do Estado, as empresas devem tamb\u00e9m participar na qualifica\u00e7\u00e3o dos seus trabalhadores; e estes t\u00eam de ser motivados para isso.  \u00c9 t\u00edpico da cultura portuguesa olhar s\u00f3 para o dia de hoje e de amanh\u00e3; n\u00e3o vemos a m\u00e9dio e longo prazo; e a qualifica\u00e7\u00e3o n\u00e3o \u00e9 s\u00f3 um problema de promo\u00e7\u00e3o no trabalho, \u00e9 a manuten\u00e7\u00e3o do pr\u00f3prio emprego que t\u00eam hoje; no fundo \u00e9 um problema que deve mobilizar toda a sociedade.  O terceiro aspecto a considerar nesta mat\u00e9ria da sustentabilidade abrange os trabalhadores avan\u00e7ados em idade, com baixas qualifica\u00e7\u00f5es; para esses haveria uma solu\u00e7\u00e3o mista no campo da pol\u00edtica de emprego, mas que passa tamb\u00e9m por medidas de protec\u00e7\u00e3o social.  A protec\u00e7\u00e3o social, hoje, tem um risco novo. Enquanto nos finais do s\u00e9culo XIX pensava no desemprego; no nosso tempo, agora, temos o emprego mais inst\u00e1vel, aos saltos, e portanto a protec\u00e7\u00e3o social tem de integrar este novo risco de emprego prec\u00e1rio em condi\u00e7\u00f5es, em termos de sal\u00e1rios insuficientes e de n\u00e3o ser emprego para toda a vida.  Penso que \u00e9 chegada a hora de institui\u00e7\u00f5es respons\u00e1veis, eventualmente a Assembleia da Rep\u00fablica ter um centro de reflex\u00e3o permanente sobre estes assuntos, como j\u00e1 existe noutros pa\u00edses. Os verdadeiros problemas, na suas mais diversas dimens\u00f5es, n\u00e3o t\u00eam apenas causas econ\u00f3micas, s\u00e3o tamb\u00e9m reflexo de problemas culturais e outros.   <i>JM \u2014 Est\u00e1 pessimista quanto ao futuro, num contexto global?  ABC \u2014<\/i> Tudo depende da forma como soubermos captar os  condicionalismos. At\u00e9 que ponto tenho capacidade para ver cada vez mais longe&#8230; As mudan\u00e7as hoje s\u00e3o todas os dias.  Se sou um \u201ccidad\u00e3o mundial\u201d olho para as coisas de uma outra forma. E aqui lembro de novo a doutrina de Jo\u00e3o Paulo II que lan\u00e7ou um princ\u00edpio inovador, que ele pr\u00f3prio n\u00e3o explicou mas que compete a n\u00f3s, seguidores da DSI desenvolver, e que \u00e9 o conceito da \u201ccidadania mundial\u201d.  Eu sou um cidad\u00e3o mundial, como aquele senhor africano que n\u00e3o tem nada para comer; logo, os deveres para com ele n\u00e3o se limitam aos concidad\u00e3os do seu pa\u00eds, mas competem a todo o mundo, a cada um de n\u00f3s, viva ou n\u00e3o em \u00c1frica. Tudo depende da forma como eu quero pensar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista ao Jornal da Madeira de Alfredo Bruto da Costa, Presidente do CES e Vice-presidente da Comiss\u00e3o Nacional Justi\u00e7a e Paz<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6],"tags":[101,191,206,237,238,272,314],"class_list":["post-18534","post","type-post","status-publish","format-standard","hentry","category-entrevistas","tag-africa","tag-economia","tag-familia","tag-joao-paulo-ii","tag-joao-xxiii","tag-pacem-in-terris","tag-solidariedade"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/18534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=18534"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/18534\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=18534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=18534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=18534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}