{"id":14633,"date":"2006-04-03T14:44:19","date_gmt":"2006-04-03T14:44:19","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/04\/03\/loc-mtc-atenta-as-oportunidades-do-mercado\/"},"modified":"2006-04-03T14:44:19","modified_gmt":"2006-04-03T14:44:19","slug":"loc-mtc-atenta-as-oportunidades-do-mercado","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/loc-mtc-atenta-as-oportunidades-do-mercado\/","title":{"rendered":"LOC\/MTC atenta \u00e0s oportunidades do mercado"},"content":{"rendered":"<p>Assembleia diocesana de Braga debateu forma\u00e7\u00e3o dos militantes <!--more--> Na Assembleia Diocesana de Braga da Liga Oper\u00e1ria Cat\u00f3lica\/Movimento de Trabalhadores Crist\u00e3os (LOC\/MTC), que ontem reuniu cerca de 110 militantes, foi debatida a forma mais eficaz de se informar os militantes e trabalhadores acerca das oportunidades de neg\u00f3cios, apoios ao pequeno investimento e iniciativas de micro-cr\u00e9dito.  O trabalho em rede, que envolve o movimento, sindicatos e outros parceiros, tem ajudado a descobrir novas perspectivas de mercado. Por\u00e9m, real\u00e7ou-se a import\u00e2ncia de se ter de defender e viver com mais afinco os valores da solidariedade, partilha, simplicidade de vida, sobriedade no consumo e no estilo de vida, para que os militantes tamb\u00e9m consigam dar um testemunho crist\u00e3o mais convincente.  A par disso, os presentes conclu\u00edram que \u00e9 necess\u00e1rio incentivar um ambiente familiar de di\u00e1logo, esp\u00edrito cr\u00edtico e aberto, para que esses valores possam ser assumidos. Por isso, para os participantes \u00e9 fundamental a ades\u00e3o da LOC\/MTC \u00e0 tem\u00e1tica da Fam\u00edlia, proposta pela Arquidiocese de Braga para o pr\u00f3ximo tri\u00e9nio, assunto abordado pelo Arcebispo Primaz, D. Jorge Ortiga, que presidiu \u00e0 sess\u00e3o de abertura dos trabalhos.  O respons\u00e1vel eclesi\u00e1stico dirigiu aos participantes palavras de est\u00edmulo e coragem pela ac\u00e7\u00e3o que v\u00e3o desenvolvendo no conturbado mundo do trabalho, referindo-se \u00e0s express\u00f5es dos papas Jo\u00e3o Paulo II e Bento XVI \u2013 \u00abN\u00e3o tenhais medo!\u00bb e \u00abos humildes trabalhadores da vinha do Senhor\u00bb. Por fim, o prelado bracarense convidou os militantes a uma participa\u00e7\u00e3o activa durante a Semana Social, que se realiza de 9 a 12 de Mar\u00e7o de 2006, em Braga, subordinada ao emprego.   <b>Investir na forma\u00e7\u00e3o<\/b> Os trabalhadores tamb\u00e9m foram desafiados pela Assembleia a investir na melhoria dos seus conhecimentos t\u00e9cnicos e profissionais, familiarizando-se com as novas tecnologias, e participando na forma\u00e7\u00e3o profissional para melhor responder \u00e0s quest\u00f5es do desemprego, precariedade e aos desafios que o actual mercado do trabalho lhes coloca. No fundo, pretende- se sensibilizar os trabalhadores para uma maior \u00abapropria\u00e7\u00e3o do saber\u00bb.  Como \u00e9 apan\u00e1gio da LOC\/MTC, a den\u00fancia das injusti\u00e7as que atormentam o mundo do trabalho e a consequente promo\u00e7\u00e3o de ac\u00e7\u00f5es que visam a participa\u00e7\u00e3o dos trabalhadores nas iniciativas relacionadas com a precariedade, desemprego, seguran\u00e7a social e leis laborais \u00e9 um dado adquirido. Por\u00e9m, os respons\u00e1veis tamb\u00e9m pretendem, atrav\u00e9s de encontros de reflex\u00e3o abertos, despertar os trabalhadores para a educa\u00e7\u00e3o para a sa\u00fade, higiene e seguran\u00e7a nos locais de trabalho.   <b>Situa\u00e7\u00e3o escolar dos filhos<\/b> A situa\u00e7\u00e3o educativa dos filhos dos trabalhadores foi um dos aspectos mais debatidos durante a reuni\u00e3o ordin\u00e1ria, chegando- se \u00e0 conclus\u00e3o que os pais t\u00eam dificuldade em acompanhar o percurso escolar dos seus filhos, tendo- se chegado a referir que, \u00abcomo h\u00e1 pouca criatividade no sentido de se motivar os alunos para o gosto pela escola e aprendizagem, o insucesso e o abandono escolares comportam n\u00fameros assustadores \u00bb. Entretanto, os militantes tiveram um tempo de forma\u00e7\u00e3o coordenado por Am\u00e9rico Monteiro, antigo coordenador diocesano, sobre o m\u00e9todo do movimento nas vertentes do Julgar e do Agir.  Aprovou-se, igualmente, diversas altera\u00e7\u00f5es ao Plano de Ac\u00e7\u00e3o e or\u00e7amento para 2006, bem como as contas do exerc\u00edcio de 2005. No Plano de Actividades aprovado, \u00e9 salientado todo o empenho do Movimento na prepara\u00e7\u00e3o de um Encontro Nacional de Trabalhadores, que se realiza no dia 21 de Maio de 2006, em Guimar\u00e3es, sobre o Futuro do Trabalho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assembleia diocesana de Braga debateu forma\u00e7\u00e3o dos militantes<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3],"tags":[120,172,193,206,237,247,309,314],"class_list":["post-14633","post","type-post","status-publish","format-standard","hentry","category-nacional","tag-bento-xvi","tag-diocese-de-braga","tag-educacao","tag-familia","tag-joao-paulo-ii","tag-loc-mtc","tag-semana-social","tag-solidariedade"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/14633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=14633"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/14633\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=14633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=14633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=14633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}