{"id":12956,"date":"2006-04-03T14:44:19","date_gmt":"2006-04-03T14:44:19","guid":{"rendered":"http:\/\/localhost:81\/dados_wp\/2006\/04\/03\/cristaos-iraquianos-temem-imposicao-da-lei-islamica\/"},"modified":"2006-04-03T14:44:19","modified_gmt":"2006-04-03T14:44:19","slug":"cristaos-iraquianos-temem-imposicao-da-lei-islamica","status":"publish","type":"post","link":"https:\/\/agencia.ecclesia.pt\/portal\/cristaos-iraquianos-temem-imposicao-da-lei-islamica\/","title":{"rendered":"Crist\u00e3os iraquianos temem imposi\u00e7\u00e3o da lei isl\u00e2mica"},"content":{"rendered":"<p>Em entrevista exclusiva \u00e0 Ajuda \u00e0 Igreja que Sofre, D. Andreas Abouna disse ter expressado ao Cardeal Cormac O\u2019Connor a sua preocupa\u00e7\u00e3o pela actual situa\u00e7\u00e3o pol\u00edtico-religiosa no Iraque, uma vez que o pa\u00eds corre o risco de se tornar num Estado isl\u00e2mico que poder\u00e1 vir a discriminar todos os grupos religiosos n\u00e3o-mu\u00e7ulmanos. O Bispo Auxiliar de Bagdade sublinhou que os crist\u00e3os iraquianos receberam informa\u00e7\u00f5es que os mu\u00e7ulmanos xiitas (o maior grupo religioso iraquiano) est\u00e3o a fazer press\u00e3o pol\u00edtica para que a nova Constitui\u00e7\u00e3o, que ir\u00e1 ser debatida na Assembleia Nacional a partir de Agosto, seja baseada na lei isl\u00e2mica (sharia). O Bispo Auxiliar de Bagdade est\u00e1 no Reino Unido para se encontrar com o Arcebispo de Westminster. D. Andreas Abouna ir\u00e1 entregar ao Cardeal O\u2019Connor uma carta assinada pelos l\u00edderes de nove denomina\u00e7\u00f5es crist\u00e3s, que lan\u00e7am um apelo desesperado para que a futura Constitui\u00e7\u00e3o n\u00e3o discrimine os n\u00e3o-mu\u00e7ulmanos. Os prelados iraquianos v\u00e3o pedir tamb\u00e9m a interven\u00e7\u00e3o de Kofi Annan. Os l\u00edderes das denomina\u00e7\u00f5es crist\u00e3s iraquianas (caldeia, greco-cat\u00f3lica, arm\u00e9nia, s\u00edria, melquita, ass\u00edria, protestante e arm\u00e9nia) temem que os seus fi\u00e9is venham a ser perseguidos e discriminados, tal como acontece noutros pa\u00edses onde a sharia foi imposta, como o Sud\u00e3o ou a Nig\u00e9ria. D. Andreas Abouna considera que a aprova\u00e7\u00e3o de uma Constitui\u00e7\u00e3o \u201cpr\u00f3-isl\u00e2mica\u201d vir\u00e1 contribuir para intensificar o \u00eaxodo dos crist\u00e3os, levando ao desaparecimento total da presen\u00e7a crist\u00e3 no Iraque, que remonta aos primeiros s\u00e9culos do cristianismo. O prelado sublinha esta uni\u00e3o sem precedentes entre as v\u00e1rias denomina\u00e7\u00f5es crist\u00e3s: \u201cSe n\u00e3o agirmos juntos, iremos perder\u201d. Na declara\u00e7\u00e3o conjunta que ser\u00e1 envida \u00e0 Assembleia Nacional e ao secret\u00e1rio-geral das Na\u00e7\u00f5es Unidas, Kofi Annan, sublinha-se o princ\u00edpio que \u201cnenhuma religi\u00e3o deve dominar sobre outra\u201d.  \u201cCaso se avance para uma confirma\u00e7\u00e3o do papel da religi\u00e3o isl\u00e2mica na sociedade iraquiana, ent\u00e3o \u00e9 natural que se confirme tamb\u00e9m o papel de outras religi\u00f5es que est\u00e3o historicamente estabelecidas no Iraque. Pedimos apenas&#8230; igualdade, liberdade e oportunidades equitativas e que se acautele a discrimina\u00e7\u00e3o racial e religiosa\u201d,  Os l\u00edderes crist\u00e3os iraquianos receiam estar a correr contra o tempo, uma vez que no dia 15 de Agosto termina o prazo para a apresenta\u00e7\u00e3o da proposta de altera\u00e7\u00e3o constitucional. Esta proposta ser\u00e1 depois debatida na Assembleia Nacional Iraquiana, onde os xiitas est\u00e3o em maioria, e ir\u00e1 ser preparada por uma sub-comiss\u00e3o parlamentar, prevendo-se que venha ainda a ser referendada antes de ser ratificada. A actual Constitui\u00e7\u00e3o provis\u00f3ria, aprovada em Junho de 2004, deixou de lado a sharia, salvaguardando que o seu papel na legisla\u00e7\u00e3o iraquiana seria decidido posteriormente.   <i>Departamento de Informa\u00e7\u00e3o da Funda\u00e7\u00e3o Ajuda \u00e0 Igreja que Sofre<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em entrevista exclusiva \u00e0 Ajuda \u00e0 Igreja que Sofre, D. Andreas Abouna disse ter expressado ao Cardeal Cormac O\u2019Connor a sua preocupa\u00e7\u00e3o pela actual situa\u00e7\u00e3o pol\u00edtico-religiosa no Iraque, uma vez que o pa\u00eds corre o risco de se tornar num Estado isl\u00e2mico que poder\u00e1 vir a discriminar todos os grupos religiosos n\u00e3o-mu\u00e7ulmanos. O Bispo Auxiliar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[5],"tags":[168,266],"class_list":["post-12956","post","type-post","status-publish","format-standard","hentry","category-vaticano","tag-diocese-da-guarda","tag-nacoes-unidas"],"_links":{"self":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/12956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/comments?post=12956"}],"version-history":[{"count":0,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/posts\/12956\/revisions"}],"wp:attachment":[{"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/media?parent=12956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/categories?post=12956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agencia.ecclesia.pt\/portal\/wp-json\/wp\/v2\/tags?post=12956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}